{"id":1016,"date":"2023-03-17T10:01:29","date_gmt":"2023-03-17T09:01:29","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?p=1016"},"modified":"2023-03-17T10:01:29","modified_gmt":"2023-03-17T09:01:29","slug":"elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/","title":{"rendered":"Elezioni Comunali del 2 e 3 aprile 2023 &#8211; manifesto candidature"},"content":{"rendered":"<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1017\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2023\/03\/manifesto-candidature-elezioni-comunali.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2023\/03\/manifesto-candidature-elezioni-comunali.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>manifesto candidature elezioni comunali<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce Allegatimanifesto candidature elezioni comunali<\/p>\n","protected":false},"author":319,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1016","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezioni Comunali del 2 e 3 aprile 2023 - manifesto candidature - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni Comunali del 2 e 3 aprile 2023 - manifesto candidature - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce Allegatimanifesto candidature elezioni comunali\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-17T09:01:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"segreteriasdf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasdf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/17\\\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/17\\\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\\\/\"},\"author\":{\"name\":\"segreteriasdf\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/2a1f599a12bb9773100aaedf2a20c615\"},\"headline\":\"Elezioni Comunali del 2 e 3 aprile 2023 &#8211; manifesto candidature\",\"datePublished\":\"2023-03-17T09:01:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/17\\\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\\\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/17\\\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/17\\\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\\\/\",\"name\":\"Elezioni Comunali del 2 e 3 aprile 2023 - manifesto candidature - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"datePublished\":\"2023-03-17T09:01:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/17\\\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/17\\\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/17\\\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni Comunali del 2 e 3 aprile 2023 &#8211; manifesto candidature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/2a1f599a12bb9773100aaedf2a20c615\",\"name\":\"segreteriasdf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"caption\":\"segreteriasdf\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/author\\\/segreteriasdf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezioni Comunali del 2 e 3 aprile 2023 - manifesto candidature - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni Comunali del 2 e 3 aprile 2023 - manifesto candidature - San Daniele del Friuli","og_description":"\ud83d\udcce Allegatimanifesto candidature elezioni comunali","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-03-17T09:01:29+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"segreteriasdf","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasdf"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/"},"author":{"name":"segreteriasdf","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/2a1f599a12bb9773100aaedf2a20c615"},"headline":"Elezioni Comunali del 2 e 3 aprile 2023 &#8211; manifesto candidature","datePublished":"2023-03-17T09:01:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/"},"wordCount":8,"publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/","name":"Elezioni Comunali del 2 e 3 aprile 2023 - manifesto candidature - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"datePublished":"2023-03-17T09:01:29+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/17\/elezioni-comunali-del-2-e-3-aprile-2023-manifesto-candidature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"Elezioni Comunali del 2 e 3 aprile 2023 &#8211; manifesto candidature"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/2a1f599a12bb9773100aaedf2a20c615","name":"segreteriasdf","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","caption":"segreteriasdf"},"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/author\/segreteriasdf\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/users\/319"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/comments?post=1016"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1016\/revisions"}],"predecessor-version":[{"id":1018,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1016\/revisions\/1018"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=1016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/categories?post=1016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/tags?post=1016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}