{"id":1036,"date":"2023-03-31T15:53:10","date_gmt":"2023-03-31T13:53:10","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?p=1036"},"modified":"2023-03-31T15:53:10","modified_gmt":"2023-03-31T13:53:10","slug":"contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/","title":{"rendered":"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22)"},"content":{"rendered":"<p><main class=\"section-column maincontent-wrap\" role=\"main\"><\/p>\n<div id=\"c145033\" class=\"frame frame-default frame-type-list frame-layout-0 frame-background-none frame-no-backgroundimage frame-space-before-none frame-space-after-none\">\n<div class=\"frame-container\">\n<div class=\"frame-inner\">\n<div class=\"news news-single\">\n<div class=\"article\">\n<div class=\"header\"><\/div>\n<div class=\"news-text-wrap\">\n<p><strong>Dal 1\u00b0 maggio al 31 luglio 2023 \u00e8 possibile fare domanda per ottenere un contributo a sostegno delle spese veterinarie degli animali d\u2019affezione per i titolari di pensione minima, di et\u00e0 superiore a 65 anni con ISEE di importo pari o inferiore a \u20ac 15.000,00<\/strong><\/p>\n<\/div>\n<div class=\"news-related-wrap\">\n<div class=\"news-related news-related-files\">\n<ul>\n<li><span class=\"news-related-files-link\"><a href=\"http:\/\/www.comune.sandanieledelfriuli.ud.it\/fileadmin\/user_sandanieledelfriuli\/allegati\/bando_animali_d_affezione.pdf\" target=\"_blank\" rel=\"noopener\"> bando_animali_d_affezione.pdf <\/a><\/span><span class=\"news-related-files-size\"> 261 KB <\/span><\/li>\n<li><span class=\"news-related-files-link\"><a href=\"http:\/\/www.comune.sandanieledelfriuli.ud.it\/fileadmin\/user_sandanieledelfriuli\/allegati\/modello_domanda_bando_animali_d_affezione.pdf\" target=\"_blank\" rel=\"noopener\"> modello_domanda_bando_animali_d_affezione.pdf <\/a><\/span><span class=\"news-related-files-size\"> 273 KB <\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/main><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 1\u00b0 maggio al 31 luglio 2023 \u00e8 possibile fare domanda per ottenere un contributo a sostegno delle spese veterinarie degli animali d\u2019affezione per i titolari di pensione minima, di [&hellip;]<\/p>\n","protected":false},"author":373,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1036","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22) - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22) - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"Dal 1\u00b0 maggio al 31 luglio 2023 \u00e8 possibile fare domanda per ottenere un contributo a sostegno delle spese veterinarie degli animali d\u2019affezione per i titolari di pensione minima, di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-31T13:53:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"pdepaulis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pdepaulis\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/31\\\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/31\\\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\\\/\"},\"author\":{\"name\":\"pdepaulis\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/990f502e73e0bbae99187c777f02874b\"},\"headline\":\"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22)\",\"datePublished\":\"2023-03-31T13:53:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/31\\\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\\\/\"},\"wordCount\":72,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/31\\\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/31\\\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\\\/\",\"name\":\"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22) - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"datePublished\":\"2023-03-31T13:53:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/31\\\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/31\\\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/03\\\/31\\\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/990f502e73e0bbae99187c777f02874b\",\"name\":\"pdepaulis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"caption\":\"pdepaulis\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/author\\\/pdepaulis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22) - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/","og_locale":"it_IT","og_type":"article","og_title":"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22) - San Daniele del Friuli","og_description":"Dal 1\u00b0 maggio al 31 luglio 2023 \u00e8 possibile fare domanda per ottenere un contributo a sostegno delle spese veterinarie degli animali d\u2019affezione per i titolari di pensione minima, di [&hellip;]","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-03-31T13:53:10+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"pdepaulis","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pdepaulis"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/"},"author":{"name":"pdepaulis","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/990f502e73e0bbae99187c777f02874b"},"headline":"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22)","datePublished":"2023-03-31T13:53:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/"},"wordCount":72,"publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/","name":"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22) - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"datePublished":"2023-03-31T13:53:10+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/03\/31\/contributo-regionale-a-sostegno-delle-spese-mediche-per-gli-animali-daffezione-art-4-bis-comma2-della-l-r-14-11-2014-n-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"Contributo regionale a sostegno delle spese mediche per gli animali d\u2019affezione (art. 4 bis, comma2 della L.R. 14.11.2014, n.22)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/990f502e73e0bbae99187c777f02874b","name":"pdepaulis","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","caption":"pdepaulis"},"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/author\/pdepaulis\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/users\/373"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/comments?post=1036"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1036\/revisions"}],"predecessor-version":[{"id":1037,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1036\/revisions\/1037"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=1036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/categories?post=1036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/tags?post=1036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}