{"id":1127,"date":"2023-05-24T15:40:38","date_gmt":"2023-05-24T13:40:38","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?p=1127"},"modified":"2023-09-05T10:21:01","modified_gmt":"2023-09-05T08:21:01","slug":"ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/","title":{"rendered":"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO"},"content":{"rendered":"<p><strong>orario invernale (ottobre &#8211; marzo)<\/strong><\/p>\n<p>marted\u00ec 14.00 &#8211; 16.00<\/p>\n<p>gioved\u00ec \u00a014.00 &#8211; 16.00<\/p>\n<p>sabato 10.00 &#8211; 12.00 e 14.00 &#8211; 16.00<\/p>\n<p>&nbsp;<\/p>\n<p><strong>orario estivo (aprile &#8211; settembre)<\/strong><\/p>\n<p>marted\u00ec\u00a0 15.00 &#8211; 18.00<\/p>\n<p>gioved\u00ec\u00a0\u00a0 15.00 &#8211; 18.00<\/p>\n<p>sabato\u00a0\u00a0 10.00 &#8211; 12.00 e 15.00 &#8211; 18.00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>orario invernale (ottobre &#8211; marzo) marted\u00ec 14.00 &#8211; 16.00 gioved\u00ec \u00a014.00 &#8211; 16.00 sabato 10.00 &#8211; 12.00 e 14.00 &#8211; 16.00 &nbsp; orario estivo (aprile &#8211; settembre) marted\u00ec\u00a0 15.00 &#8211; [&hellip;]<\/p>\n","protected":false},"author":373,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1127","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"orario invernale (ottobre &#8211; marzo) marted\u00ec 14.00 &#8211; 16.00 gioved\u00ec \u00a014.00 &#8211; 16.00 sabato 10.00 &#8211; 12.00 e 14.00 &#8211; 16.00 &nbsp; orario estivo (aprile &#8211; settembre) marted\u00ec\u00a0 15.00 &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-24T13:40:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T08:21:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"pdepaulis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pdepaulis\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/05\\\/24\\\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/05\\\/24\\\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\\\/\"},\"author\":{\"name\":\"pdepaulis\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/990f502e73e0bbae99187c777f02874b\"},\"headline\":\"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO\",\"datePublished\":\"2023-05-24T13:40:38+00:00\",\"dateModified\":\"2023-09-05T08:21:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/05\\\/24\\\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\\\/\"},\"wordCount\":34,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/05\\\/24\\\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/05\\\/24\\\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\\\/\",\"name\":\"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"datePublished\":\"2023-05-24T13:40:38+00:00\",\"dateModified\":\"2023-09-05T08:21:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/05\\\/24\\\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/05\\\/24\\\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2023\\\/05\\\/24\\\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/990f502e73e0bbae99187c777f02874b\",\"name\":\"pdepaulis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"caption\":\"pdepaulis\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/author\\\/pdepaulis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/","og_locale":"it_IT","og_type":"article","og_title":"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO - San Daniele del Friuli","og_description":"orario invernale (ottobre &#8211; marzo) marted\u00ec 14.00 &#8211; 16.00 gioved\u00ec \u00a014.00 &#8211; 16.00 sabato 10.00 &#8211; 12.00 e 14.00 &#8211; 16.00 &nbsp; orario estivo (aprile &#8211; settembre) marted\u00ec\u00a0 15.00 &#8211; [&hellip;]","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-05-24T13:40:38+00:00","article_modified_time":"2023-09-05T08:21:01+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"pdepaulis","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pdepaulis"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/"},"author":{"name":"pdepaulis","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/990f502e73e0bbae99187c777f02874b"},"headline":"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO","datePublished":"2023-05-24T13:40:38+00:00","dateModified":"2023-09-05T08:21:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/"},"wordCount":34,"publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/","name":"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"datePublished":"2023-05-24T13:40:38+00:00","dateModified":"2023-09-05T08:21:01+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2023\/05\/24\/ecopiazzola-comunale-variazione-temporanea-orari-di-apertura-al-pubblico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"ECOPIAZZOLA COMUNALE \u2013 ORARI DI APERTURA AL PUBBLICO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/990f502e73e0bbae99187c777f02874b","name":"pdepaulis","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","caption":"pdepaulis"},"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/author\/pdepaulis\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/users\/373"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/comments?post=1127"}],"version-history":[{"count":5,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1127\/revisions"}],"predecessor-version":[{"id":1187,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/1127\/revisions\/1187"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=1127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/categories?post=1127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/tags?post=1127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}