{"id":204,"date":"2020-08-20T08:35:46","date_gmt":"2020-08-20T06:35:46","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?p=204"},"modified":"2020-08-20T08:35:46","modified_gmt":"2020-08-20T06:35:46","slug":"avviso-servizio-trasporto-scolastico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/","title":{"rendered":"Avviso &#8211; Servizio Trasporto Scolastico"},"content":{"rendered":"<p>Il\u00a0<a class=\"external-link-new-window\" title=\"Opens external link in new window\" href=\"http:\/\/www.governo.it\/sites\/new.governo.it\/files\/DPCM_20200807.pdf\">DPCM del \u00a007\/08\/202<\/a>0 ha definito le nuove linee guide per il trasporto scolastico.<\/p>\n<p>Per dar luogo alla corretta applicazione della normativa per il rispetto delle norme sanitarie si chiede ai Sig.ri genitori, che non lo hanno ancora fatto ma che sono intenzionati a fruire del servizio scuolabus, di procedere\u00a0<b>IMMEDIATAMENTE\u00a0<\/b>alla trasmissione all\u2019Ufficio scolastico della scheda di iscrizione scaricabile dalla Home page del sito del Comune (<a class=\"internal-link\" title=\"Opens internal link in current window\" href=\"http:\/\/www.comune.sandanieledelfriuli.ud.it\/index.php?id=59743\">www.comune.sandanieledelfriuli.ud.it<\/a>). Il Modulo di iscrizione dovr\u00e0 pervenire entro il\u00a0<b>24\/08\/2020.<\/b><\/p>\n<p><b>Visto quanto previsto dalla normativa per la gestione dell\u2019emergenza COVID-19 le iscrizioni che perverranno in data successiva rischiano, nostro malgrado, di non poter essere accolte<\/b><\/p>\n<p><b>Ulteriori informazioni sul servizio verranno inoltrare, come consueto, tramite l\u2019applicativo School.net (servizio mensa)<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il\u00a0DPCM del \u00a007\/08\/2020 ha definito le nuove linee guide per il trasporto scolastico. Per dar luogo alla corretta applicazione della normativa per il rispetto delle norme sanitarie si chiede ai [&hellip;]<\/p>\n","protected":false},"author":319,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-204","post","type-post","status-publish","format-standard","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso - Servizio Trasporto Scolastico - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso - Servizio Trasporto Scolastico - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"Il\u00a0DPCM del \u00a007\/08\/2020 ha definito le nuove linee guide per il trasporto scolastico. Per dar luogo alla corretta applicazione della normativa per il rispetto delle norme sanitarie si chiede ai [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-20T06:35:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"segreteriasdf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasdf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2020\\\/08\\\/20\\\/avviso-servizio-trasporto-scolastico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2020\\\/08\\\/20\\\/avviso-servizio-trasporto-scolastico\\\/\"},\"author\":{\"name\":\"segreteriasdf\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/2a1f599a12bb9773100aaedf2a20c615\"},\"headline\":\"Avviso &#8211; Servizio Trasporto Scolastico\",\"datePublished\":\"2020-08-20T06:35:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2020\\\/08\\\/20\\\/avviso-servizio-trasporto-scolastico\\\/\"},\"wordCount\":127,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2020\\\/08\\\/20\\\/avviso-servizio-trasporto-scolastico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2020\\\/08\\\/20\\\/avviso-servizio-trasporto-scolastico\\\/\",\"name\":\"Avviso - Servizio Trasporto Scolastico - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"datePublished\":\"2020-08-20T06:35:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2020\\\/08\\\/20\\\/avviso-servizio-trasporto-scolastico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2020\\\/08\\\/20\\\/avviso-servizio-trasporto-scolastico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2020\\\/08\\\/20\\\/avviso-servizio-trasporto-scolastico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso &#8211; Servizio Trasporto Scolastico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/2a1f599a12bb9773100aaedf2a20c615\",\"name\":\"segreteriasdf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"caption\":\"segreteriasdf\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/author\\\/segreteriasdf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso - Servizio Trasporto Scolastico - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso - Servizio Trasporto Scolastico - San Daniele del Friuli","og_description":"Il\u00a0DPCM del \u00a007\/08\/2020 ha definito le nuove linee guide per il trasporto scolastico. Per dar luogo alla corretta applicazione della normativa per il rispetto delle norme sanitarie si chiede ai [&hellip;]","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-08-20T06:35:46+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png","height":600,"width":1200,"type":""}],"author":"segreteriasdf","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasdf","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/"},"author":{"name":"segreteriasdf","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/2a1f599a12bb9773100aaedf2a20c615"},"headline":"Avviso &#8211; Servizio Trasporto Scolastico","datePublished":"2020-08-20T06:35:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/"},"wordCount":127,"publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/","name":"Avviso - Servizio Trasporto Scolastico - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"datePublished":"2020-08-20T06:35:46+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2020\/08\/20\/avviso-servizio-trasporto-scolastico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"Avviso &#8211; Servizio Trasporto Scolastico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/2a1f599a12bb9773100aaedf2a20c615","name":"segreteriasdf","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","caption":"segreteriasdf"},"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/author\/segreteriasdf\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/users\/319"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/comments?post=204"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/204\/revisions"}],"predecessor-version":[{"id":205,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/204\/revisions\/205"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/categories?post=204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/tags?post=204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}