{"id":339,"date":"2021-03-16T13:39:17","date_gmt":"2021-03-16T12:39:17","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?p=339"},"modified":"2021-03-16T13:39:17","modified_gmt":"2021-03-16T12:39:17","slug":"centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/","title":{"rendered":"Centro estivo 2021-  manifestazione di interesse alla partecipazione  (entro il 31.03.2021)"},"content":{"rendered":"<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_340\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2021\/03\/questionario-per-interesse-a-iscrizione.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2021\/03\/questionario-per-interesse-a-iscrizione.docx', '_system'); return false;\"><i class='icon attachment'><\/i>questionario per interesse a iscrizione<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce Allegatiquestionario per interesse a iscrizione<\/p>\n","protected":false},"author":319,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-339","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021) - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021) - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce Allegatiquestionario per interesse a iscrizione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-16T12:39:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"segreteriasdf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasdf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2021\\\/03\\\/16\\\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2021\\\/03\\\/16\\\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\\\/\"},\"author\":{\"name\":\"segreteriasdf\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/2a1f599a12bb9773100aaedf2a20c615\"},\"headline\":\"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021)\",\"datePublished\":\"2021-03-16T12:39:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2021\\\/03\\\/16\\\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2021\\\/03\\\/16\\\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2021\\\/03\\\/16\\\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\\\/\",\"name\":\"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021) - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"datePublished\":\"2021-03-16T12:39:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2021\\\/03\\\/16\\\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2021\\\/03\\\/16\\\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2021\\\/03\\\/16\\\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/2a1f599a12bb9773100aaedf2a20c615\",\"name\":\"segreteriasdf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"caption\":\"segreteriasdf\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/author\\\/segreteriasdf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021) - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021) - San Daniele del Friuli","og_description":"\ud83d\udcce Allegatiquestionario per interesse a iscrizione","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-03-16T12:39:17+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"segreteriasdf","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasdf"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/"},"author":{"name":"segreteriasdf","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/2a1f599a12bb9773100aaedf2a20c615"},"headline":"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021)","datePublished":"2021-03-16T12:39:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/"},"wordCount":10,"publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/","name":"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021) - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"datePublished":"2021-03-16T12:39:17+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2021\/03\/16\/centro-estivo-2021-manifestazione-di-interesse-alla-partecipazione-entro-il-31-03-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"Centro estivo 2021- manifestazione di interesse alla partecipazione (entro il 31.03.2021)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/2a1f599a12bb9773100aaedf2a20c615","name":"segreteriasdf","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","caption":"segreteriasdf"},"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/author\/segreteriasdf\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/users\/319"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/comments?post=339"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/339\/revisions"}],"predecessor-version":[{"id":341,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/339\/revisions\/341"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/categories?post=339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/tags?post=339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}