{"id":731,"date":"2022-07-27T13:12:08","date_gmt":"2022-07-27T11:12:08","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?p=731"},"modified":"2022-07-27T13:12:08","modified_gmt":"2022-07-27T11:12:08","slug":"avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/","title":{"rendered":"Avviso taglio piante e\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP &#8211; periodo 01\/08\/2022 \u2013 31\/07\/2023"},"content":{"rendered":"<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_732\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2022\/07\/AVVISO_Taglio-Alberi_GRUPPO-TERNA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2022\/07\/AVVISO_Taglio-Alberi_GRUPPO-TERNA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO_Taglio Alberi_GRUPPO TERNA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce AllegatiAVVISO_Taglio Alberi_GRUPPO TERNA<\/p>\n","protected":false},"author":319,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-731","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso taglio piante e\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP - periodo 01\/08\/2022 \u2013 31\/07\/2023 - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso taglio piante e\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP - periodo 01\/08\/2022 \u2013 31\/07\/2023 - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce AllegatiAVVISO_Taglio Alberi_GRUPPO TERNA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-27T11:12:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"segreteriasdf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasdf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/07\\\/27\\\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/07\\\/27\\\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\\\/\"},\"author\":{\"name\":\"segreteriasdf\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/2a1f599a12bb9773100aaedf2a20c615\"},\"headline\":\"Avviso taglio piante e\\\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP &#8211; periodo 01\\\/08\\\/2022 \u2013 31\\\/07\\\/2023\",\"datePublished\":\"2022-07-27T11:12:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/07\\\/27\\\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\\\/\"},\"wordCount\":38,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/07\\\/27\\\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/07\\\/27\\\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\\\/\",\"name\":\"Avviso taglio piante e\\\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP - periodo 01\\\/08\\\/2022 \u2013 31\\\/07\\\/2023 - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"datePublished\":\"2022-07-27T11:12:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/07\\\/27\\\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/07\\\/27\\\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/07\\\/27\\\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso taglio piante e\\\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP &#8211; periodo 01\\\/08\\\/2022 \u2013 31\\\/07\\\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/2a1f599a12bb9773100aaedf2a20c615\",\"name\":\"segreteriasdf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g\",\"caption\":\"segreteriasdf\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/author\\\/segreteriasdf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso taglio piante e\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP - periodo 01\/08\/2022 \u2013 31\/07\/2023 - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso taglio piante e\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP - periodo 01\/08\/2022 \u2013 31\/07\/2023 - San Daniele del Friuli","og_description":"\ud83d\udcce AllegatiAVVISO_Taglio Alberi_GRUPPO TERNA","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-07-27T11:12:08+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"segreteriasdf","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasdf"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/"},"author":{"name":"segreteriasdf","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/2a1f599a12bb9773100aaedf2a20c615"},"headline":"Avviso taglio piante e\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP &#8211; periodo 01\/08\/2022 \u2013 31\/07\/2023","datePublished":"2022-07-27T11:12:08+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/"},"wordCount":38,"publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/","name":"Avviso taglio piante e\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP - periodo 01\/08\/2022 \u2013 31\/07\/2023 - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"datePublished":"2022-07-27T11:12:08+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/07\/27\/avviso-taglio-piante-e-o-rami-presenti-nella-fascia-di-rispetto-degli-elettrodotti-di-alta-tensione-valori-45kv-66kv-132kv-220kv-380kv-e-lungo-i-sentieri-di-accesso-ai-sostegni-delle-linee-elettrich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"Avviso taglio piante e\/o rami presenti nella fascia di rispetto degli elettrodotti di Alta Tensione (valori 45kV-66kV-132kV-220kV-380kV) e lungo i sentieri di accesso ai sostegni delle linee elettriche di TERNA GROUP &#8211; periodo 01\/08\/2022 \u2013 31\/07\/2023"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/2a1f599a12bb9773100aaedf2a20c615","name":"segreteriasdf","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4aa34feb2ad1e675f3f6e0bf11cb426014557c7a27227868156cb49e58e84b8?s=96&d=mm&r=g","caption":"segreteriasdf"},"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/author\/segreteriasdf\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/users\/319"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/comments?post=731"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/731\/revisions"}],"predecessor-version":[{"id":733,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/731\/revisions\/733"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/categories?post=731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/tags?post=731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}