{"id":782,"date":"2022-08-18T18:07:24","date_gmt":"2022-08-18T16:07:24","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?p=782"},"modified":"2022-08-18T18:07:24","modified_gmt":"2022-08-18T16:07:24","slug":"avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/","title":{"rendered":"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) &#8211; scadenza 16\/09\/2022"},"content":{"rendered":"<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_783\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2022\/08\/BANDO-SAN-DANIELE-IMPRESE.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2022\/08\/BANDO-SAN-DANIELE-IMPRESE.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>BANDO SAN DANIELE IMPRESE<\/a><\/li>\n<li><a id=\"wpba_attachment_list_784\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2022\/08\/DOMANDA-CONTRIBUTO.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2022\/08\/DOMANDA-CONTRIBUTO.docx', '_system'); return false;\"><i class='icon attachment'><\/i>DOMANDA CONTRIBUTO<\/a><\/li>\n<li><a id=\"wpba_attachment_list_785\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2022\/08\/Tabella_1_Spese_Nuove_Attivita-sAN-dANIELE.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2022\/08\/Tabella_1_Spese_Nuove_Attivita-sAN-dANIELE.docx', '_system'); return false;\"><i class='icon attachment'><\/i>Tabella_1_Spese_Nuove_Attivita sAN dANIELE<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce AllegatiBANDO SAN DANIELE IMPRESE DOMANDA CONTRIBUTO Tabella_1_Spese_Nuove_Attivita sAN dANIELE<\/p>\n","protected":false},"author":373,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-782","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) - scadenza 16\/09\/2022 - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) - scadenza 16\/09\/2022 - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce AllegatiBANDO SAN DANIELE IMPRESE DOMANDA CONTRIBUTO Tabella_1_Spese_Nuove_Attivita sAN dANIELE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-18T16:07:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"pdepaulis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pdepaulis\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/08\\\/18\\\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/08\\\/18\\\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\\\/\"},\"author\":{\"name\":\"pdepaulis\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/990f502e73e0bbae99187c777f02874b\"},\"headline\":\"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) &#8211; scadenza 16\\\/09\\\/2022\",\"datePublished\":\"2022-08-18T16:07:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/08\\\/18\\\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\\\/\"},\"wordCount\":24,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/08\\\/18\\\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/08\\\/18\\\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\\\/\",\"name\":\"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) - scadenza 16\\\/09\\\/2022 - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"datePublished\":\"2022-08-18T16:07:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/08\\\/18\\\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/08\\\/18\\\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/2022\\\/08\\\/18\\\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) &#8211; scadenza 16\\\/09\\\/2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/person\\\/990f502e73e0bbae99187c777f02874b\",\"name\":\"pdepaulis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g\",\"caption\":\"pdepaulis\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/author\\\/pdepaulis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) - scadenza 16\/09\/2022 - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) - scadenza 16\/09\/2022 - San Daniele del Friuli","og_description":"\ud83d\udcce AllegatiBANDO SAN DANIELE IMPRESE DOMANDA CONTRIBUTO Tabella_1_Spese_Nuove_Attivita sAN dANIELE","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-08-18T16:07:24+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"pdepaulis","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pdepaulis"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/"},"author":{"name":"pdepaulis","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/990f502e73e0bbae99187c777f02874b"},"headline":"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) &#8211; scadenza 16\/09\/2022","datePublished":"2022-08-18T16:07:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/"},"wordCount":24,"publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/","name":"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) - scadenza 16\/09\/2022 - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"datePublished":"2022-08-18T16:07:24+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/2022\/08\/18\/avviso-pubblico-per-lerogazione-di-contributi-a-fondo-perduto-una-tantum-a-sostegno-delle-microimprese-colpite-dallemergenza-covid19-secondo-bando-scadenza-16-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"AVVISO PUBBLICO PER L\u2019EROGAZIONE DI \u201cCONTRIBUTI A FONDO PERDUTO UNA TANTUM\u201d A SOSTEGNO DELLE MICROIMPRESE COLPITE DALL\u2019EMERGENZA COVID19 (secondo bando) &#8211; scadenza 16\/09\/2022"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/person\/990f502e73e0bbae99187c777f02874b","name":"pdepaulis","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f0122dc506a45ffba0e449cc8f621821b352024df48e196b79476da4cdb756e?s=96&d=mm&r=g","caption":"pdepaulis"},"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/author\/pdepaulis\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/users\/373"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":786,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/posts\/782\/revisions\/786"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}