{"id":26,"date":"2019-12-09T15:00:41","date_gmt":"2019-12-09T14:00:41","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?post_type=turismo&#038;p=26"},"modified":"2019-12-09T15:14:59","modified_gmt":"2019-12-09T14:14:59","slug":"portone-di-tramontana-detto-portnat","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/","title":{"rendered":"Portone di Tramontana detto &#8220;Portnat&#8221;"},"content":{"rendered":"<p>Fu costruito in sostituzione dell&#8217;antico torrione rovinato dal terremoto del 1511, su indicazione del Patriarca e con la mediazione di<strong> Giulio Savorgnan<\/strong>, signore di Osoppo.<\/p>\n<p>Del progetto venne incaricato il <strong>Palladio<\/strong> e la costruzione fu iniziata nel 1579 da <strong>Andrea da Venzone<\/strong> e proseguita, dopo l&#8217;improvvisa morte di costui, da <strong>Andrea Podaro<\/strong> venuto ad abitare in citt\u00e0 con la sua famiglia.<\/p>\n<p>Legato al torrione \u00e8 il celebre <strong>Palio di San Daniele<\/strong> che si disputava appunto nelle sue immediate vicinanze, il 28 agosto di ogni anno.<\/p>\n<p>La festa iniziava con la lettura dei regolamenti di gara dalla soggetta del manufatto da dove il cancelliere della citt\u00e0 proclamava successivamente anche i vincitori cui andavano dieci <em>brazza di damasco cremisino, delle calze di setta o del tavolazzo.<\/em><\/p>\n<p>A tirar con le <em>balestre e coi grandi archibuzzi e moschetti<\/em>, i concorrenti provenivano da tutto il Friuli e dalla Carnia, acclamati dalla folla dei borghi cittadini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fu costruito in sostituzione dell&#8217;antico torrione rovinato dal terremoto del 1511, su indicazione del Patriarca e con la mediazione di Giulio Savorgnan, signore di Osoppo. Del progetto venne incaricato il [&hellip;]<\/p>\n","protected":false},"featured_media":27,"parent":34,"menu_order":2,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-26","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portone di Tramontana detto &quot;Portnat&quot; - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portone di Tramontana detto &quot;Portnat&quot; - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"Fu costruito in sostituzione dell&#8217;antico torrione rovinato dal terremoto del 1511, su indicazione del Patriarca e con la mediazione di Giulio Savorgnan, signore di Osoppo. Del progetto venne incaricato il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-09T14:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/San-Daniele-del-Friuli-Portonat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/portone-di-tramontana-detto-portnat\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/portone-di-tramontana-detto-portnat\\\/\",\"name\":\"Portone di Tramontana detto \\\"Portnat\\\" - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/portone-di-tramontana-detto-portnat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/portone-di-tramontana-detto-portnat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/San-Daniele-del-Friuli-Portonat.jpg\",\"datePublished\":\"2019-12-09T14:00:41+00:00\",\"dateModified\":\"2019-12-09T14:14:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/portone-di-tramontana-detto-portnat\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/portone-di-tramontana-detto-portnat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/portone-di-tramontana-detto-portnat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/San-Daniele-del-Friuli-Portonat.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/San-Daniele-del-Friuli-Portonat.jpg\",\"width\":768,\"height\":510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/portone-di-tramontana-detto-portnat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edifici di interesse\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/turismo\\\/edifici-di-interesse\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Portone di Tramontana detto &#8220;Portnat&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portone di Tramontana detto \"Portnat\" - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/","og_locale":"it_IT","og_type":"article","og_title":"Portone di Tramontana detto \"Portnat\" - San Daniele del Friuli","og_description":"Fu costruito in sostituzione dell&#8217;antico torrione rovinato dal terremoto del 1511, su indicazione del Patriarca e con la mediazione di Giulio Savorgnan, signore di Osoppo. Del progetto venne incaricato il [&hellip;]","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2019-12-09T14:14:59+00:00","og_image":[{"width":768,"height":510,"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/San-Daniele-del-Friuli-Portonat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/","name":"Portone di Tramontana detto \"Portnat\" - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/San-Daniele-del-Friuli-Portonat.jpg","datePublished":"2019-12-09T14:00:41+00:00","dateModified":"2019-12-09T14:14:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/#primaryimage","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/San-Daniele-del-Friuli-Portonat.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/San-Daniele-del-Friuli-Portonat.jpg","width":768,"height":510},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/portone-di-tramontana-detto-portnat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"Edifici di interesse","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/turismo\/edifici-di-interesse\/"},{"@type":"ListItem","position":3,"name":"Portone di Tramontana detto &#8220;Portnat&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/turismo\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/turismo\/34"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media\/27"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/plugin_turismo?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}