{"id":16,"date":"2018-11-30T15:49:16","date_gmt":"2018-11-30T14:49:16","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniincarico\/?post_type=info&#038;p=16"},"modified":"2021-05-26T17:21:40","modified_gmt":"2021-05-26T15:21:40","slug":"vanita-di-tallini-martina","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/","title":{"rendered":"Vanit\u00e0 di Tallini Martina"},"content":{"rendered":"<p>Parrucchiere, centro benessere e cura della persona, ubicato nel cuore del paese. Un ampio salone accogliente e confortevole, che offre ai clienti la possibilit\u00e0 di dialogare con lo staff per scegliere modalit\u00e0 di intervento per migliorare e valorizzare il proprio aspetto. Qualit\u00e0 e cortesia sono le priorit\u00e0 che offrono.<\/p>\n<p><i class=\"fa fa-phone\"><\/i><a href=\"tel:3932325988\"> 393 2325988<\/a><\/p>\n<p><i class=\"map marker icon\"><\/i> Via Civita Farnese Centro &#8211; San Giovanni Incarico (FR)<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2988.076657423341!2d13.555481115821644!3d41.50261357925383!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x133ab34be3ef7b2f%3A0x923ca70e470b8551!2sVia+Civita+Farnese+Centro%2C+Provincia+di+Frosinone!5e0!3m2!1sit!2sit!4v1543846142163\" width=\"100%\" height=\"450\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parrucchiere, centro benessere e cura della persona, ubicato nel cuore del paese. Un ampio salone accogliente e confortevole, che offre ai clienti la possibilit\u00e0 di dialogare con lo staff per [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":15,"menu_order":0,"template":"","meta":[],"plugin_info":[],"class_list":["post-16","info","type-info","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vanit\u00e0 di Tallini Martina - San Giovanni Incarico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vanit\u00e0 di Tallini Martina - San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"Parrucchiere, centro benessere e cura della persona, ubicato nel cuore del paese. Un ampio salone accogliente e confortevole, che offre ai clienti la possibilit\u00e0 di dialogare con lo staff per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni Incarico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-26T15:21:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2019\/02\/sangiovanniincarico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/vanita-di-tallini-martina\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/vanita-di-tallini-martina\\\/\",\"name\":\"Vanit\u00e0 di Tallini Martina - San Giovanni Incarico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\"},\"datePublished\":\"2018-11-30T14:49:16+00:00\",\"dateModified\":\"2021-05-26T15:21:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/vanita-di-tallini-martina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/vanita-di-tallini-martina\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/vanita-di-tallini-martina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consorzio Valle della Guardia\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servizi per la Persona\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Vanit\u00e0 di Tallini Martina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\",\"name\":\"San Giovanni Incarico\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vanit\u00e0 di Tallini Martina - San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/","og_locale":"it_IT","og_type":"article","og_title":"Vanit\u00e0 di Tallini Martina - San Giovanni Incarico","og_description":"Parrucchiere, centro benessere e cura della persona, ubicato nel cuore del paese. Un ampio salone accogliente e confortevole, che offre ai clienti la possibilit\u00e0 di dialogare con lo staff per [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/","og_site_name":"San Giovanni Incarico","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2021-05-26T15:21:40+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2019\/02\/sangiovanniincarico.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/","name":"Vanit\u00e0 di Tallini Martina - San Giovanni Incarico","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website"},"datePublished":"2018-11-30T14:49:16+00:00","dateModified":"2021-05-26T15:21:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/vanita-di-tallini-martina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/"},{"@type":"ListItem","position":2,"name":"Consorzio Valle della Guardia","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/"},{"@type":"ListItem","position":3,"name":"Servizi per la Persona","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/"},{"@type":"ListItem","position":4,"name":"Vanit\u00e0 di Tallini Martina"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/","name":"San Giovanni Incarico","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniincarico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/types\/info"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info\/15"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media?parent=16"}],"wp:term":[{"taxonomy":"plugin_info","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/plugin_info?post=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}