{"id":61,"date":"2018-12-03T12:17:56","date_gmt":"2018-12-03T11:17:56","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniincarico\/?post_type=info&#038;p=61"},"modified":"2021-05-26T17:21:00","modified_gmt":"2021-05-26T15:21:00","slug":"centro-estetico-relax-di-fraioli-natalina","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/","title":{"rendered":"Centro Estetico Relax di Fraioli Natalina"},"content":{"rendered":"<p>Poco fuori dal paese, il centro estetico relax offre momenti di benessere e cura della persona,in un ambiente di relax. Un luogo in cui spazio e tempo non contano, dove mente e corpo si ritrovano in sintonia, dove si lasciano alle spalle i ritmi frenetici della quotidianit\u00e0 per riscoprire la scansione naturale del tempo. Tutto \u00e8 pensato per offrire un\u2019esperienza di benessere assoluto.Curando ogni dettaglio nei minimi particolari,cos\u00ec che tutto comunichi relax e armonia.<\/p>\n<p><i class=\"fa fa-phone\"><\/i><a href=\"tel:3492978710\"> 349 2978710<\/a><\/p>\n<p><i class=\"fa fa-envelope\"><\/i><a href=\"mailto:nataliefraioli@yahoo.it\"> nataliefraioli@yahoo.it<\/a><\/p>\n<p><i class=\"fa fa-clock-o\"><\/i>Tutti i giorni <span class=\"ccBold\">8:00 \u2013 12:00<\/span> &#8211; <span class=\"ccBold\">14:00 \u2013 18:00<\/span><br \/>\n<span class=\"ccBold\">Chiuso:<\/span> Luned\u00ec<\/p>\n<p><i class=\"map marker icon\"><\/i> Via Dirupata snc &#8211; San Giovanni Incarico (FR)<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d528.1005275042048!2d13.564568416750515!3d41.517541616103244!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x133ab342b32c8eb3%3A0x2843527b0bc7825e!2sVia+Dirupata%2C+03028+San+Giovanni+incarico+FR!5e0!3m2!1sit!2sit!4v1543847852523\" width=\"100%\" height=\"450\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poco fuori dal paese, il centro estetico relax offre momenti di benessere e cura della persona,in un ambiente di relax. Un luogo in cui spazio e tempo non contano, dove [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":15,"menu_order":0,"template":"","meta":[],"plugin_info":[],"class_list":["post-61","info","type-info","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro Estetico Relax di Fraioli Natalina - San Giovanni Incarico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro Estetico Relax di Fraioli Natalina - San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"Poco fuori dal paese, il centro estetico relax offre momenti di benessere e cura della persona,in un ambiente di relax. Un luogo in cui spazio e tempo non contano, dove [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni Incarico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-26T15:21:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2019\/02\/sangiovanniincarico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/centro-estetico-relax-di-fraioli-natalina\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/centro-estetico-relax-di-fraioli-natalina\\\/\",\"name\":\"Centro Estetico Relax di Fraioli Natalina - San Giovanni Incarico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\"},\"datePublished\":\"2018-12-03T11:17:56+00:00\",\"dateModified\":\"2021-05-26T15:21:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/centro-estetico-relax-di-fraioli-natalina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/centro-estetico-relax-di-fraioli-natalina\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/centro-estetico-relax-di-fraioli-natalina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consorzio Valle della Guardia\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servizi per la Persona\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/servizi-per-la-persona\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Centro Estetico Relax di Fraioli Natalina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\",\"name\":\"San Giovanni Incarico\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro Estetico Relax di Fraioli Natalina - San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/","og_locale":"it_IT","og_type":"article","og_title":"Centro Estetico Relax di Fraioli Natalina - San Giovanni Incarico","og_description":"Poco fuori dal paese, il centro estetico relax offre momenti di benessere e cura della persona,in un ambiente di relax. Un luogo in cui spazio e tempo non contano, dove [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/","og_site_name":"San Giovanni Incarico","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2021-05-26T15:21:00+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2019\/02\/sangiovanniincarico.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/","name":"Centro Estetico Relax di Fraioli Natalina - San Giovanni Incarico","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website"},"datePublished":"2018-12-03T11:17:56+00:00","dateModified":"2021-05-26T15:21:00+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/centro-estetico-relax-di-fraioli-natalina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/"},{"@type":"ListItem","position":2,"name":"Consorzio Valle della Guardia","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/"},{"@type":"ListItem","position":3,"name":"Servizi per la Persona","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/servizi-per-la-persona\/"},{"@type":"ListItem","position":4,"name":"Centro Estetico Relax di Fraioli Natalina"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/","name":"San Giovanni Incarico","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniincarico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/types\/info"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info\/15"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media?parent=61"}],"wp:term":[{"taxonomy":"plugin_info","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/plugin_info?post=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}