{"id":70,"date":"2018-12-03T12:31:44","date_gmt":"2018-12-03T11:31:44","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniincarico\/?post_type=info&#038;p=70"},"modified":"2021-05-26T17:20:34","modified_gmt":"2021-05-26T15:20:34","slug":"pizza-pazza-di-federici-emanuela","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/","title":{"rendered":"Pizza Pazza di Federici Emanuela"},"content":{"rendered":"<p>Pizza Pazza nasce con l\u2019idea di donare ai clienti un cibo tradizionale ma di alta qualit\u00e0 e di creare con loro un clima confidenziale, in modo tale che la cena diventi un\u2019esperienza amichevole in un ambiente familiare, \u00e8 possibile degustare la pizza presso il loro locale oppure da asporto.Oltre alla pizza troviamo anche deliziosi hamburger , hot dogs, patate, crocchette e tanto altro. Situato proprio nel cuore del paese. Unisce fantasia e qualit\u00e0 per regalarti un gusto unico ed inimitabile.<\/p>\n<p><i class=\"fa fa-phone\"><\/i><a href=\"tel:3409818127\"> 340 9818127<\/a><\/p>\n<p><i class=\"fa fa-envelope\"><\/i><a href=\"mailto:denise.zurlo@hotmail.it\"> denise.zurlo@hotmail.it<\/a><\/p>\n<p><i class=\"fa fa-clock-o\"><\/i>Tutti i giorni <span class=\"ccBold\">16:00 \u2013 22:00<\/span><br \/>\n<span class=\"ccBold\">Chiuso:<\/span> Luned\u00ec<\/p>\n<p><i class=\"map marker icon\"><\/i> Via Civita Farnese &#8211; San Giovanni Incarico (FR)<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d186.75476496529828!2d13.55762889653331!3d41.50262263734163!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x133ab34be3ef7b2f%3A0x923ca70e470b8551!2sVia+Civita+Farnese+Centro%2C+Provincia+di+Frosinone!5e0!3m2!1sit!2sit!4v1543847302236\" width=\"100%\" height=\"450\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pizza Pazza nasce con l\u2019idea di donare ai clienti un cibo tradizionale ma di alta qualit\u00e0 e di creare con loro un clima confidenziale, in modo tale che la cena [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":11,"menu_order":0,"template":"","meta":[],"plugin_info":[],"class_list":["post-70","info","type-info","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pizza Pazza di Federici Emanuela - San Giovanni Incarico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pizza Pazza di Federici Emanuela - San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"Pizza Pazza nasce con l\u2019idea di donare ai clienti un cibo tradizionale ma di alta qualit\u00e0 e di creare con loro un clima confidenziale, in modo tale che la cena [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni Incarico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-26T15:20:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2019\/02\/sangiovanniincarico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/ristoranti-e-pizzerie\\\/pizza-pazza-di-federici-emanuela\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/ristoranti-e-pizzerie\\\/pizza-pazza-di-federici-emanuela\\\/\",\"name\":\"Pizza Pazza di Federici Emanuela - San Giovanni Incarico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\"},\"datePublished\":\"2018-12-03T11:31:44+00:00\",\"dateModified\":\"2021-05-26T15:20:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/ristoranti-e-pizzerie\\\/pizza-pazza-di-federici-emanuela\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/ristoranti-e-pizzerie\\\/pizza-pazza-di-federici-emanuela\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/ristoranti-e-pizzerie\\\/pizza-pazza-di-federici-emanuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consorzio Valle della Guardia\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ristoranti e Pizzerie\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/info\\\/rete-dimpresa\\\/ristoranti-e-pizzerie\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pizza Pazza di Federici Emanuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\",\"name\":\"San Giovanni Incarico\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pizza Pazza di Federici Emanuela - San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/","og_locale":"it_IT","og_type":"article","og_title":"Pizza Pazza di Federici Emanuela - San Giovanni Incarico","og_description":"Pizza Pazza nasce con l\u2019idea di donare ai clienti un cibo tradizionale ma di alta qualit\u00e0 e di creare con loro un clima confidenziale, in modo tale che la cena [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/","og_site_name":"San Giovanni Incarico","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2021-05-26T15:20:34+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2019\/02\/sangiovanniincarico.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/","name":"Pizza Pazza di Federici Emanuela - San Giovanni Incarico","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website"},"datePublished":"2018-12-03T11:31:44+00:00","dateModified":"2021-05-26T15:20:34+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/pizza-pazza-di-federici-emanuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/"},{"@type":"ListItem","position":2,"name":"Consorzio Valle della Guardia","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/"},{"@type":"ListItem","position":3,"name":"Ristoranti e Pizzerie","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/info\/rete-dimpresa\/ristoranti-e-pizzerie\/"},{"@type":"ListItem","position":4,"name":"Pizza Pazza di Federici Emanuela"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/","name":"San Giovanni Incarico","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniincarico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/types\/info"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/info\/11"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media?parent=70"}],"wp:term":[{"taxonomy":"plugin_info","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/plugin_info?post=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}