{"id":173,"date":"2018-11-25T17:06:42","date_gmt":"2018-11-25T16:06:42","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniincarico\/?p=173"},"modified":"2018-12-06T17:08:17","modified_gmt":"2018-12-06T16:08:17","slug":"violenza-contro-le-donne","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/","title":{"rendered":"Violenza contro le Donne"},"content":{"rendered":"<p>La violenza contro le donne \u00e8 una delle pi\u00f9 vergognose violazioni dei diritti umani (Kofi Annan)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La violenza contro le donne \u00e8 una delle pi\u00f9 vergognose violazioni dei diritti umani (Kofi Annan)<\/p>\n","protected":false},"author":282,"featured_media":174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Violenza contro le Donne - San Giovanni Incarico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Violenza contro le Donne - San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"La violenza contro le donne \u00e8 una delle pi\u00f9 vergognose violazioni dei diritti umani (Kofi Annan)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni Incarico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-25T16:06:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-06T16:08:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/violenza-sulle-donne-San-Giovanni-Incarico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gestoreyic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestoreyic\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/\"},\"author\":{\"name\":\"gestoreyic\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"headline\":\"Violenza contro le Donne\",\"datePublished\":\"2018-11-25T16:06:42+00:00\",\"dateModified\":\"2018-12-06T16:08:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/\"},\"wordCount\":19,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/violenza-sulle-donne-San-Giovanni-Incarico.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/\",\"name\":\"Violenza contro le Donne - San Giovanni Incarico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/violenza-sulle-donne-San-Giovanni-Incarico.jpg\",\"datePublished\":\"2018-11-25T16:06:42+00:00\",\"dateModified\":\"2018-12-06T16:08:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/violenza-sulle-donne-San-Giovanni-Incarico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/violenza-sulle-donne-San-Giovanni-Incarico.jpg\",\"width\":835,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2018\\\/11\\\/25\\\/violenza-contro-le-donne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Violenza contro le Donne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\",\"name\":\"San Giovanni Incarico\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\",\"name\":\"gestoreyic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"caption\":\"gestoreyic\"},\"description\":\"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/author\\\/gestoreyic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Violenza contro le Donne - San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/","og_locale":"it_IT","og_type":"article","og_title":"Violenza contro le Donne - San Giovanni Incarico","og_description":"La violenza contro le donne \u00e8 una delle pi\u00f9 vergognose violazioni dei diritti umani (Kofi Annan)","og_url":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/","og_site_name":"San Giovanni Incarico","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-11-25T16:06:42+00:00","article_modified_time":"2018-12-06T16:08:17+00:00","og_image":[{"width":835,"height":675,"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/violenza-sulle-donne-San-Giovanni-Incarico.jpg","type":"image\/jpeg"}],"author":"gestoreyic","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"gestoreyic"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/"},"author":{"name":"gestoreyic","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"headline":"Violenza contro le Donne","datePublished":"2018-11-25T16:06:42+00:00","dateModified":"2018-12-06T16:08:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/"},"wordCount":19,"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/violenza-sulle-donne-San-Giovanni-Incarico.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/","name":"Violenza contro le Donne - San Giovanni Incarico","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/violenza-sulle-donne-San-Giovanni-Incarico.jpg","datePublished":"2018-11-25T16:06:42+00:00","dateModified":"2018-12-06T16:08:17+00:00","author":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/#primaryimage","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/violenza-sulle-donne-San-Giovanni-Incarico.jpg","contentUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/violenza-sulle-donne-San-Giovanni-Incarico.jpg","width":835,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2018\/11\/25\/violenza-contro-le-donne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/"},{"@type":"ListItem","position":2,"name":"Violenza contro le Donne"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/","name":"San Giovanni Incarico","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniincarico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196","name":"gestoreyic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","caption":"gestoreyic"},"description":"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/author\/gestoreyic\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/users\/282"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/comments?post=173"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/173\/revisions"}],"predecessor-version":[{"id":175,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/173\/revisions\/175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media\/174"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media?parent=173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/categories?post=173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/tags?post=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}