{"id":22518,"date":"2026-01-16T09:37:32","date_gmt":"2026-01-16T08:37:32","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniincarico\/?p=22518"},"modified":"2026-01-16T09:37:36","modified_gmt":"2026-01-16T08:37:36","slug":"giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/","title":{"rendered":"Giornata di prevenzione delle patologie cerebro e cardiovascolari"},"content":{"rendered":"<p><em>Il 25 gennaio 2026, dalle 8:00 alle 13:30, presso il Palazzo Municipale di San Giovanni Incarico, si terr\u00e0 una giornata di prevenzione cerebro e cardiovascolare con controlli gratuiti e senza impegnativa.<br \/>\nL\u2019iniziativa \u00e8 aperta a tutta la cittadinanza.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il Comune di San Giovanni Incarico, in collaborazione con A.L.I.Ce. \u2013 Associazione per la Lotta all\u2019Ictus Cerebrale e con il supporto dei partner sanitari, promuove una giornata di informazione e sensibilizzazione dedicata alla prevenzione delle patologie cerebrovascolari e cardiovascolari, con particolare attenzione a ictus e fibrillazione atriale.<\/p>\n<p>Nel corso dell\u2019iniziativa sar\u00e0 possibile effettuare controlli sanitari gratuiti, finalizzati alla valutazione dei principali fattori di rischio, tra cui:<\/p>\n<ul>\n<li>misurazione della pressione arteriosa;<\/li>\n<li>controllo della frequenza e del ritmo cardiaco;<\/li>\n<li>ECG;<\/li>\n<li>Ecodoppler TSA;<\/li>\n<li>controllo di colesterolo e glicemia.<\/li>\n<\/ul>\n<p>I partecipanti riceveranno inoltre indicazioni utili per migliorare lo stile di vita e ridurre il rischio di ictus e patologie cardiovascolari.<\/p>\n<p><strong>Data: 25 gennaio 2026<\/strong><\/p>\n<p><strong>Orario: dalle ore 8:00 alle ore 13:30<\/strong><\/p>\n<p><strong>Luogo: Piazza Umberto I \u2013 Palazzo Municipale<\/strong><\/p>\n<p><strong> Visite gratuite e senza impegnativa<\/strong><\/p>\n<p>L\u2019Amministrazione Comunale invita tutta la cittadinanza a partecipare a questa importante iniziativa di prevenzione e tutela della salute.<\/p>\n<p>L\u2019Amministrazione Comunale<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 25 gennaio 2026, dalle 8:00 alle 13:30, presso il Palazzo Municipale di San Giovanni Incarico, si terr\u00e0 una giornata di prevenzione cerebro e cardiovascolare con controlli gratuiti e senza [&hellip;]<\/p>\n","protected":false},"author":286,"featured_media":22536,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-22518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giornata di prevenzione delle patologie cerebro e cardiovascolari - San Giovanni Incarico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata di prevenzione delle patologie cerebro e cardiovascolari - San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"Il 25 gennaio 2026, dalle 8:00 alle 13:30, presso il Palazzo Municipale di San Giovanni Incarico, si terr\u00e0 una giornata di prevenzione cerebro e cardiovascolare con controlli gratuiti e senza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni Incarico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-16T08:37:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T08:37:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2026\/01\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gaetano Battaglini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gaetano Battaglini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/\"},\"author\":{\"name\":\"Gaetano Battaglini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\"},\"headline\":\"Giornata di prevenzione delle patologie cerebro e cardiovascolari\",\"datePublished\":\"2026-01-16T08:37:32+00:00\",\"dateModified\":\"2026-01-16T08:37:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/\"},\"wordCount\":195,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2026\\\/01\\\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/\",\"name\":\"Giornata di prevenzione delle patologie cerebro e cardiovascolari - San Giovanni Incarico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2026\\\/01\\\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg\",\"datePublished\":\"2026-01-16T08:37:32+00:00\",\"dateModified\":\"2026-01-16T08:37:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2026\\\/01\\\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2026\\\/01\\\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg\",\"width\":1414,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2026\\\/01\\\/16\\\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornata di prevenzione delle patologie cerebro e cardiovascolari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\",\"name\":\"San Giovanni Incarico\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\",\"name\":\"Gaetano Battaglini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"caption\":\"Gaetano Battaglini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/author\\\/gbattaglini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornata di prevenzione delle patologie cerebro e cardiovascolari - San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/","og_locale":"it_IT","og_type":"article","og_title":"Giornata di prevenzione delle patologie cerebro e cardiovascolari - San Giovanni Incarico","og_description":"Il 25 gennaio 2026, dalle 8:00 alle 13:30, presso il Palazzo Municipale di San Giovanni Incarico, si terr\u00e0 una giornata di prevenzione cerebro e cardiovascolare con controlli gratuiti e senza [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/","og_site_name":"San Giovanni Incarico","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-16T08:37:32+00:00","article_modified_time":"2026-01-16T08:37:36+00:00","og_image":[{"width":1414,"height":2000,"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2026\/01\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg","type":"image\/jpeg"}],"author":"Gaetano Battaglini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gaetano Battaglini","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/"},"author":{"name":"Gaetano Battaglini","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009"},"headline":"Giornata di prevenzione delle patologie cerebro e cardiovascolari","datePublished":"2026-01-16T08:37:32+00:00","dateModified":"2026-01-16T08:37:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/"},"wordCount":195,"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2026\/01\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/","name":"Giornata di prevenzione delle patologie cerebro e cardiovascolari - San Giovanni Incarico","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2026\/01\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg","datePublished":"2026-01-16T08:37:32+00:00","dateModified":"2026-01-16T08:37:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/#primaryimage","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2026\/01\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg","contentUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2026\/01\/2e38bf6d-8db6-4c36-be3f-097e0ce9f43d.jpeg","width":1414,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2026\/01\/16\/giornata-di-prevenzione-delle-patologie-cerebro-e-cardiovascolari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/"},{"@type":"ListItem","position":2,"name":"Giornata di prevenzione delle patologie cerebro e cardiovascolari"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/","name":"San Giovanni Incarico","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniincarico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009","name":"Gaetano Battaglini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","caption":"Gaetano Battaglini"},"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/author\/gbattaglini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00005864"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/22518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/users\/286"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/comments?post=22518"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/22518\/revisions"}],"predecessor-version":[{"id":22534,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/22518\/revisions\/22534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media\/22536"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media?parent=22518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/categories?post=22518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/tags?post=22518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}