{"id":399,"date":"2020-02-02T17:40:11","date_gmt":"2020-02-02T16:40:11","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniincarico\/?p=399"},"modified":"2020-02-02T17:40:11","modified_gmt":"2020-02-02T16:40:11","slug":"alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/","title":{"rendered":"Alla riscoperta degli antichi percorsi per valorizzare il territorio"},"content":{"rendered":"<p><strong>E\u2019 questo un progetto che coinvolge gli assessorati all\u2019Ambiente, Cultura e Sport per valorizzare un\u00a0 territorio ricco di risorse paesaggistiche, storico-archeologiche attraverso un cammino salutare e, nello stesso tempo, fare memoria dei luoghi attraversati dalla Via Francigena.<\/strong>\u00a0 Un percorso a contatto con la natura\u00a0 mettendo in risalto il valore di un territorio partendo dal Lago di San Giovanni Incarico, dove la flora e la fauna fanno da coreografia all\u2019Anfiteatro dell\u2019antica Citt\u00e0 romana di Fabrateria Nova, ubicato nella vasta e preziosa area archeologica in localit\u00e0 \u201cLa Civita\u201d.<\/p>\n<p>Proprio qui, questa mattina alle 10.30, si sono dati appuntamento i rappresentanti delle diverse realt\u00e0 istituzionali locali e associative <strong>accolti dall&#8217;assessore alla Cultura Gaetano Battaglini. Il gruppo \u00e8 stato guidato da Pier Matteo Carbone e Ivana Orsini<\/strong> per fare un primo sopralluogo atto a verificare la fruibilit\u00e0 dei percorsi da valorizzare in quella che \u00e8 un\u2019area che rappresenta, di fatto, una vera e propria risorsa.<\/p>\n<p><strong>La dichiarazione congiunta dell\u2019 Assessore all\u2019Ambiente Isabella Corsetti, dell\u2019Assessore alla Cultura Gaetano Battaglini e del Consigliere delegato allo Sport Antonio Petrucci<\/strong><\/p>\n<p>\u201cQuesto \u00e8 l\u2019inizio di un progetto ambizioso che vuole coinvolgere tutti, istituzioni, associazioni e volontari, nel recupero degli antichi sentieri. La loro conservazione \u00e8 fondamentale nel valorizzare i numerosi percorsi, custodi della memoria di una comunit\u00e0. Una vera e propria rete che diventa un punto d\u2019incontro con altre realt\u00e0 locali attraversate dall\u2019antica Via Francigena.\u00a0 Un modo per aggregare e mettere insieme le diverse realt\u00e0 associative e di volontariato per costruire, insieme, un cammino alla riscoperta della natura e delle preziose risorse storiche. Un&#8217;iniziativa per promuovere il benessere della persona attraverso il trekking immersi nella natura: un momento fondamentale per rilassarsi narrando la storia dei luoghi che, ancora oggi, conservano le tracce di un passato memorabile.\u00a0 <strong>Ringraziamo, a nome del sindaco Paolo Fallone, tutti i presenti a partire dal giovane Pier Matteo Carbone, l\u2019architetto Ivana Orsini vice presidente dell\u2019Associazione \u00a0Culturale Ecomuseo Argil,\u00a0 Augusto Car\u00e8 commissario della XVI Comunit\u00e0 Montana dei Monti Ausoni, le guide CAI Diego Magliocchetti e Massimo Parente, Carlo Troccoli di Legambiente e Duilio Di Santo membro dell\u2019Associazione I Borghi Pi\u00f9 Belli d\u2019Italia<\/strong>\u201d.<\/p>\n<p>Dopo l\u2019escursione nei pressi del lago di San Giovanni Incarico e dell\u2019Area archeologica, il gruppo ha concluso il suo percorso, per una panoramica pi\u00f9 ampia, sul Santuario della Madonna della Guardia, un luogo denso di storia e di risorse naturalistiche da poter inserire in questo progetto.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 questo un progetto che coinvolge gli assessorati all\u2019Ambiente, Cultura e Sport per valorizzare un\u00a0 territorio ricco di risorse paesaggistiche, storico-archeologiche attraverso un cammino salutare e, nello stesso tempo, fare [&hellip;]<\/p>\n","protected":false},"author":286,"featured_media":400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alla riscoperta degli antichi percorsi per valorizzare il territorio - San Giovanni Incarico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alla riscoperta degli antichi percorsi per valorizzare il territorio - San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"E\u2019 questo un progetto che coinvolge gli assessorati all\u2019Ambiente, Cultura e Sport per valorizzare un\u00a0 territorio ricco di risorse paesaggistiche, storico-archeologiche attraverso un cammino salutare e, nello stesso tempo, fare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni Incarico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-02T16:40:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2020\/02\/I-partecipanti-al-percorso.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"777\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gaetano Battaglini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gaetano Battaglini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/\"},\"author\":{\"name\":\"Gaetano Battaglini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\"},\"headline\":\"Alla riscoperta degli antichi percorsi per valorizzare il territorio\",\"datePublished\":\"2020-02-02T16:40:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/\"},\"wordCount\":412,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2020\\\/02\\\/I-partecipanti-al-percorso.jpeg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/\",\"name\":\"Alla riscoperta degli antichi percorsi per valorizzare il territorio - San Giovanni Incarico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2020\\\/02\\\/I-partecipanti-al-percorso.jpeg\",\"datePublished\":\"2020-02-02T16:40:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2020\\\/02\\\/I-partecipanti-al-percorso.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2020\\\/02\\\/I-partecipanti-al-percorso.jpeg\",\"width\":1600,\"height\":777},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/02\\\/02\\\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alla riscoperta degli antichi percorsi per valorizzare il territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\",\"name\":\"San Giovanni Incarico\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\",\"name\":\"Gaetano Battaglini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"caption\":\"Gaetano Battaglini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/author\\\/gbattaglini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alla riscoperta degli antichi percorsi per valorizzare il territorio - San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/","og_locale":"it_IT","og_type":"article","og_title":"Alla riscoperta degli antichi percorsi per valorizzare il territorio - San Giovanni Incarico","og_description":"E\u2019 questo un progetto che coinvolge gli assessorati all\u2019Ambiente, Cultura e Sport per valorizzare un\u00a0 territorio ricco di risorse paesaggistiche, storico-archeologiche attraverso un cammino salutare e, nello stesso tempo, fare [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/","og_site_name":"San Giovanni Incarico","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-02-02T16:40:11+00:00","og_image":[{"width":1600,"height":777,"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2020\/02\/I-partecipanti-al-percorso.jpeg","type":"image\/jpeg"}],"author":"Gaetano Battaglini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gaetano Battaglini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/"},"author":{"name":"Gaetano Battaglini","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009"},"headline":"Alla riscoperta degli antichi percorsi per valorizzare il territorio","datePublished":"2020-02-02T16:40:11+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/"},"wordCount":412,"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2020\/02\/I-partecipanti-al-percorso.jpeg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/","name":"Alla riscoperta degli antichi percorsi per valorizzare il territorio - San Giovanni Incarico","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2020\/02\/I-partecipanti-al-percorso.jpeg","datePublished":"2020-02-02T16:40:11+00:00","author":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/#primaryimage","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2020\/02\/I-partecipanti-al-percorso.jpeg","contentUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2020\/02\/I-partecipanti-al-percorso.jpeg","width":1600,"height":777},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/02\/02\/alla-riscoperta-degli-antichi-percorsi-per-valorizzare-il-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/"},{"@type":"ListItem","position":2,"name":"Alla riscoperta degli antichi percorsi per valorizzare il territorio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/","name":"San Giovanni Incarico","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniincarico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009","name":"Gaetano Battaglini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","caption":"Gaetano Battaglini"},"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/author\/gbattaglini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/users\/286"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/comments?post=399"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/399\/revisions"}],"predecessor-version":[{"id":401,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/399\/revisions\/401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media\/400"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media?parent=399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/categories?post=399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/tags?post=399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}