{"id":710,"date":"2020-07-05T09:30:02","date_gmt":"2020-07-05T07:30:02","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniincarico\/?p=710"},"modified":"2020-07-03T20:31:12","modified_gmt":"2020-07-03T18:31:12","slug":"una-nuova-condotta-idrica-servira-via-selva-piana","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/","title":{"rendered":"Una nuova condotta idrica servir\u00e0 via Selva Piana"},"content":{"rendered":"<p><strong>Sono iniziati i lavori di rifacimento della condotta idrica della lunga via Selva Piana<\/strong><br \/>\n<strong>Il sindaco Paolo Fallone e il consigliere delegato Angelo Petrucci ne danno notizia\u00a0 esprimendo la loro soddisfazione per l\u2019importante risultato, \u201cfrutto di una proficua mediazione\u00a0 progettuale tra Amministrazione comunale e\u00a0 Acea Ato 5\u201d.<\/strong><\/p>\n<h3>Le dichiarazioni de sindaco Paolo Fallone<\/h3>\n<p>\u201c<strong>Questo significativo progetto\u00a0 \u00e8 la sintesi delle azioni messe in campo da questa Amministrazioni rivolte, come sempre, verso il cittadino<\/strong> che ha diritto a servizi di qualit\u00e0. Da sempre abbiamo infatti rivolto la nostra attenzione alla rete idrica che percorre l\u2019intero \u00a0territorio comunale interfacciandoci, quotidianamente, con i referenti di Acea Ato 5 al fine di migliorare questo servizio essenziale. <strong>Un lavoro seguito quotidianamente dal nostro consigliere delegato Angelo Petrucci che, attraverso la sua disponibilit\u00e0 ha reso possibile il raggiungere, in tempi cos\u00ec brevi, questi obiettivi.<\/strong><br \/>\n<strong>Un lavoro, quello del consigliere Petrucci, che ha \u00a0evidenziato notevoli capacit\u00e0 tecniche per la risoluzione dei problemi da affrontare giornalmente e un ottima capacit\u00e0 di mediazione,\u00a0 improntata sulle azioni risolutive\u00a0 con abnegazione e umilt\u00e0<\/strong>. <strong>Un modus operandi fondato sull\u2019indirizzo politico &#8211; amministrativo seguito da tutti gli amministratori, \u00a0abituati a rimboccarsi le maniche mettendoci la faccia.<\/strong> \u00a0Una politica che caratterizza questa Amministrazione comunale che mi onoro di presiedere. Con il consigliere delegato Angelo Petrucci non posso non ringraziare la solerte disponibilit\u00e0 della dirigenza di Acea Ato 5 sempre proiettata alla risoluzione delle criticit\u00e0 attraverso il confronto producendo, come oggi \u00e8 ben evidente, \u00a0tali e eccellenti risultati a beneficio dei \u00a0sangiovannesi.<br \/>\n<strong>Con la realizzazione della poderosa condotta idrica abbiamo inoltre ottenuto il rifacimento dell\u2019intero manto stradale di via Selva Piana, cosi da ripristinare una viabilit\u00e0 pi\u00f9 sicura per gli abitanti di queste\u00a0 zone e di\u00a0 quanti transitano, giornalmente, su questo tratto di strada.<\/strong> Il raggiungimento di tali e significativi obiettivi certifica peraltro una politica attiva che ha quale priorit\u00e0 il cittadino\u00a0 a cui non devono\u00a0 mancare servizi di qualit\u00e0\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.comunesangiovanniincarico.fr.it\/wp-content\/uploads\/2020\/07\/IMG_4695.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17143\" src=\"https:\/\/www.comunesangiovanniincarico.fr.it\/wp-content\/uploads\/2020\/07\/IMG_4695.jpg\" alt=\"\" width=\"1270\" height=\"824\" \/><\/a><br \/>\n<strong>Un tratto di via Selva Piana<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono iniziati i lavori di rifacimento della condotta idrica della lunga via Selva Piana Il sindaco Paolo Fallone e il consigliere delegato Angelo Petrucci ne danno notizia\u00a0 esprimendo la loro [&hellip;]<\/p>\n","protected":false},"author":286,"featured_media":181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una nuova condotta idrica servir\u00e0 via Selva Piana - San Giovanni Incarico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una nuova condotta idrica servir\u00e0 via Selva Piana - San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"Sono iniziati i lavori di rifacimento della condotta idrica della lunga via Selva Piana Il sindaco Paolo Fallone e il consigliere delegato Angelo Petrucci ne danno notizia\u00a0 esprimendo la loro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni Incarico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-05T07:30:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/sindaco-san-giovanni-incarico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"594\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gaetano Battaglini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gaetano Battaglini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/\"},\"author\":{\"name\":\"Gaetano Battaglini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\"},\"headline\":\"Una nuova condotta idrica servir\u00e0 via Selva Piana\",\"datePublished\":\"2020-07-05T07:30:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/\"},\"wordCount\":329,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/sindaco-san-giovanni-incarico.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/\",\"name\":\"Una nuova condotta idrica servir\u00e0 via Selva Piana - San Giovanni Incarico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/sindaco-san-giovanni-incarico.jpg\",\"datePublished\":\"2020-07-05T07:30:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/sindaco-san-giovanni-incarico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/sindaco-san-giovanni-incarico.jpg\",\"width\":594,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/2020\\\/07\\\/05\\\/una-nuova-condotta-idrica-servira-via-selva-piana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una nuova condotta idrica servir\u00e0 via Selva Piana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\",\"name\":\"San Giovanni Incarico\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#\\\/schema\\\/person\\\/e4e1b3a6890057bbfac2ee07c88d9009\",\"name\":\"Gaetano Battaglini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g\",\"caption\":\"Gaetano Battaglini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/author\\\/gbattaglini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una nuova condotta idrica servir\u00e0 via Selva Piana - San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/","og_locale":"it_IT","og_type":"article","og_title":"Una nuova condotta idrica servir\u00e0 via Selva Piana - San Giovanni Incarico","og_description":"Sono iniziati i lavori di rifacimento della condotta idrica della lunga via Selva Piana Il sindaco Paolo Fallone e il consigliere delegato Angelo Petrucci ne danno notizia\u00a0 esprimendo la loro [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/","og_site_name":"San Giovanni Incarico","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-07-05T07:30:02+00:00","og_image":[{"width":594,"height":445,"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/sindaco-san-giovanni-incarico.jpg","type":"image\/jpeg"}],"author":"Gaetano Battaglini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gaetano Battaglini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/"},"author":{"name":"Gaetano Battaglini","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009"},"headline":"Una nuova condotta idrica servir\u00e0 via Selva Piana","datePublished":"2020-07-05T07:30:02+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/"},"wordCount":329,"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/sindaco-san-giovanni-incarico.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/","name":"Una nuova condotta idrica servir\u00e0 via Selva Piana - San Giovanni Incarico","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/sindaco-san-giovanni-incarico.jpg","datePublished":"2020-07-05T07:30:02+00:00","author":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/#primaryimage","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/sindaco-san-giovanni-incarico.jpg","contentUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/sindaco-san-giovanni-incarico.jpg","width":594,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/2020\/07\/05\/una-nuova-condotta-idrica-servira-via-selva-piana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/"},{"@type":"ListItem","position":2,"name":"Una nuova condotta idrica servir\u00e0 via Selva Piana"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/","name":"San Giovanni Incarico","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniincarico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#\/schema\/person\/e4e1b3a6890057bbfac2ee07c88d9009","name":"Gaetano Battaglini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c01ef374d0c037fb2a6539d919638622d655f5bc47e5d5033ebc96fdf5ef19c6?s=96&d=mm&r=g","caption":"Gaetano Battaglini"},"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/author\/gbattaglini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/users\/286"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/710\/revisions"}],"predecessor-version":[{"id":711,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/posts\/710\/revisions\/711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media\/181"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media?parent=710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/categories?post=710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/tags?post=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}