{"id":198,"date":"2018-12-06T17:33:59","date_gmt":"2018-12-06T16:33:59","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniincarico\/?post_type=turismo&#038;p=198"},"modified":"2018-12-10T12:41:30","modified_gmt":"2018-12-10T11:41:30","slug":"pollo-e-peperoni","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/","title":{"rendered":"Pollo e peperoni"},"content":{"rendered":"<p><strong>Ingredienti<\/strong>: un pollo di circa 1 kg, 300 g di pomodoro, due o tre peperoni dolci a polpa grossa, un peperoncino, due spicchi d\u2019aglio, mezzo bicchiere di vino bianco, poco olio, sale. Pulire il pollo, fiammeggiare e tagliare a tocchetti. In un tegame imbiondire nell\u2019olio gli spicchi d\u2019aglio. Aggiungere i tocchetti di pollo e far rosolare spruzzando con vino bianco. Appena il vino sar\u00e0 evaporato aggiungere il peperoncino, i pomodori e i peperoni mondati e tagliati a falde. Scolare, coprire il tegame e cuocere per circa 45 minuti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredienti: un pollo di circa 1 kg, 300 g di pomodoro, due o tre peperoni dolci a polpa grossa, un peperoncino, due spicchi d\u2019aglio, mezzo bicchiere di vino bianco, poco [&hellip;]<\/p>\n","protected":false},"featured_media":199,"parent":183,"menu_order":0,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-198","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pollo e peperoni - San Giovanni Incarico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pollo e peperoni - San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"Ingredienti: un pollo di circa 1 kg, 300 g di pomodoro, due o tre peperoni dolci a polpa grossa, un peperoncino, due spicchi d\u2019aglio, mezzo bicchiere di vino bianco, poco [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni Incarico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-10T11:41:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/baked-chicken-PEC4FXC_min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/pollo-e-peperoni\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/pollo-e-peperoni\\\/\",\"name\":\"Pollo e peperoni - San Giovanni Incarico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/pollo-e-peperoni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/pollo-e-peperoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/baked-chicken-PEC4FXC_min.jpg\",\"datePublished\":\"2018-12-06T16:33:59+00:00\",\"dateModified\":\"2018-12-10T11:41:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/pollo-e-peperoni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/pollo-e-peperoni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/pollo-e-peperoni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/baked-chicken-PEC4FXC_min.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/wp-content\\\/uploads\\\/sites\\\/161\\\/2018\\\/12\\\/baked-chicken-PEC4FXC_min.jpg\",\"width\":600,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/pollo-e-peperoni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastronomia Sangiovannese\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/turismo\\\/gastronomia-sangiovannese\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pollo e peperoni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/\",\"name\":\"San Giovanni Incarico\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniincarico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pollo e peperoni - San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/","og_locale":"it_IT","og_type":"article","og_title":"Pollo e peperoni - San Giovanni Incarico","og_description":"Ingredienti: un pollo di circa 1 kg, 300 g di pomodoro, due o tre peperoni dolci a polpa grossa, un peperoncino, due spicchi d\u2019aglio, mezzo bicchiere di vino bianco, poco [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/","og_site_name":"San Giovanni Incarico","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2018-12-10T11:41:30+00:00","og_image":[{"width":600,"height":401,"url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/baked-chicken-PEC4FXC_min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/","name":"Pollo e peperoni - San Giovanni Incarico","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/baked-chicken-PEC4FXC_min.jpg","datePublished":"2018-12-06T16:33:59+00:00","dateModified":"2018-12-10T11:41:30+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/#primaryimage","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/baked-chicken-PEC4FXC_min.jpg","contentUrl":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-content\/uploads\/sites\/161\/2018\/12\/baked-chicken-PEC4FXC_min.jpg","width":600,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/pollo-e-peperoni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/"},{"@type":"ListItem","position":2,"name":"Gastronomia Sangiovannese","item":"https:\/\/comunicacity.net\/sangiovanniincarico\/turismo\/gastronomia-sangiovannese\/"},{"@type":"ListItem","position":3,"name":"Pollo e peperoni"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniincarico\/#website","url":"https:\/\/comunicacity.net\/sangiovanniincarico\/","name":"San Giovanni Incarico","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniincarico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/turismo\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/turismo\/183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media\/199"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/media?parent=198"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniincarico\/wp-json\/wp\/v2\/plugin_turismo?post=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}