{"id":161,"date":"2024-06-21T17:02:59","date_gmt":"2024-06-21T15:02:59","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/"},"modified":"2024-06-21T17:02:59","modified_gmt":"2024-06-21T15:02:59","slug":"improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/","title":{"rendered":"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\/06\/2024 sino a conclusione dei lavori"},"content":{"rendered":"<p><em>Avviso improvvisa interruzione erogazione acqua potabile in zona Palla Palla e Olivaro<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si avvisa la cittadinanza che a causa di alcuni lavori privati che hanno danneggiato la conduttura idropotabile comunale, \u00e8 stato necessario sospendere l&#8217;erogazione dell&#8217;acqua potabile per consentire la riparazione. Le zone interessate sono i quartieri Palla Palla e Olivaro. Il tutto verr\u00e0 ripristinato al termine dei lavori che sono in corso.&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='http:\/\/comune.sangiovanniinfiore.cs.it\/wp-content\/uploads\/2024\/03\/acqua.jpg' alt='image'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avviso improvvisa interruzione erogazione acqua potabile in zona Palla Palla e Olivaro&nbsp; Descrizione&nbsp; Si avvisa la cittadinanza che a causa di alcuni lavori privati che hanno danneggiato la conduttura idropotabile [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-161","post","type-post","status-publish","format-standard","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\/06\/2024 sino a conclusione dei lavori - San Giovanni in Fiore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\/06\/2024 sino a conclusione dei lavori - San Giovanni in Fiore\" \/>\n<meta property=\"og:description\" content=\"Avviso improvvisa interruzione erogazione acqua potabile in zona Palla Palla e Olivaro&nbsp; Descrizione&nbsp; Si avvisa la cittadinanza che a causa di alcuni lavori privati che hanno danneggiato la conduttura idropotabile [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni in Fiore\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-21T15:02:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/comune.sangiovanniinfiore.cs.it\/wp-content\/uploads\/2024\/03\/acqua.jpg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\\\/06\\\/2024 sino a conclusione dei lavori\",\"datePublished\":\"2024-06-21T15:02:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/\"},\"wordCount\":89,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comune.sangiovanniinfiore.cs.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/acqua.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/\",\"name\":\"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\\\/06\\\/2024 sino a conclusione dei lavori - San Giovanni in Fiore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comune.sangiovanniinfiore.cs.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/acqua.jpg\",\"datePublished\":\"2024-06-21T15:02:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comune.sangiovanniinfiore.cs.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/acqua.jpg\",\"contentUrl\":\"http:\\\/\\\/comune.sangiovanniinfiore.cs.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/acqua.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/06\\\/21\\\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\\\/06\\\/2024 sino a conclusione dei lavori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\/06\/2024 sino a conclusione dei lavori - San Giovanni in Fiore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/","og_locale":"it_IT","og_type":"article","og_title":"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\/06\/2024 sino a conclusione dei lavori - San Giovanni in Fiore","og_description":"Avviso improvvisa interruzione erogazione acqua potabile in zona Palla Palla e Olivaro&nbsp; Descrizione&nbsp; Si avvisa la cittadinanza che a causa di alcuni lavori privati che hanno danneggiato la conduttura idropotabile [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/","og_site_name":"San Giovanni in Fiore","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-06-21T15:02:59+00:00","og_image":[{"url":"http:\/\/comune.sangiovanniinfiore.cs.it\/wp-content\/uploads\/2024\/03\/acqua.jpg","type":"","width":"","height":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\/06\/2024 sino a conclusione dei lavori","datePublished":"2024-06-21T15:02:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/"},"wordCount":89,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/#primaryimage"},"thumbnailUrl":"http:\/\/comune.sangiovanniinfiore.cs.it\/wp-content\/uploads\/2024\/03\/acqua.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/","name":"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\/06\/2024 sino a conclusione dei lavori - San Giovanni in Fiore","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/#primaryimage"},"thumbnailUrl":"http:\/\/comune.sangiovanniinfiore.cs.it\/wp-content\/uploads\/2024\/03\/acqua.jpg","datePublished":"2024-06-21T15:02:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/#primaryimage","url":"http:\/\/comune.sangiovanniinfiore.cs.it\/wp-content\/uploads\/2024\/03\/acqua.jpg","contentUrl":"http:\/\/comune.sangiovanniinfiore.cs.it\/wp-content\/uploads\/2024\/03\/acqua.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/06\/21\/improvvisa-interruzione-erogazione-acqua-potabile-in-quartieri-palla-palla-e-olivaro-dalle-ore-16-30-del-21-06-2024-sino-a-conclusione-dei-lavori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniinfiore\/"},{"@type":"ListItem","position":2,"name":"Improvvisa interruzione erogazione acqua potabile in quartieri Palla Palla e Olivaro dalle ore 16.30 del 21\/06\/2024 sino a conclusione dei lavori"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniinfiore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002630"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/comments?post=161"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/161\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/media?parent=161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/categories?post=161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/tags?post=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}