{"id":179,"date":"2024-07-14T12:37:54","date_gmt":"2024-07-14T10:37:54","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/"},"modified":"2024-07-14T12:37:54","modified_gmt":"2024-07-14T10:37:54","slug":"invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/","title":{"rendered":"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore"},"content":{"rendered":"<p><em>Avviso manifestazione di interesse<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In esecuzione delle determinazioni n. 198 del 12\/07\/2024 il Comune di San Giovanni in Fiore intende acquisire la manifestazione d\u2019interesse, non vincolante per l\u2019Amministrazione Comunale, corredata dall\u2019offerta economica, al fine di individuare l\u2019operatore economico con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore, attraverso un Ordine Diretto di Acquisto mediante la piattaforma www.acquistiinretepa.it.<\/p>\n<p>Vedi avviso allegato<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_181\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/uploads\/sites\/226\/2024\/07\/MANIF-INTERESSE-ENERGIA_signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/uploads\/sites\/226\/2024\/07\/MANIF-INTERESSE-ENERGIA_signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MANIF INTERESSE ENERGIA_signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avviso manifestazione di interesse&nbsp; Descrizione&nbsp; In esecuzione delle determinazioni n. 198 del 12\/07\/2024 il Comune di San Giovanni in Fiore intende acquisire la manifestazione d\u2019interesse, non vincolante per l\u2019Amministrazione Comunale, [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore - San Giovanni in Fiore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore - San Giovanni in Fiore\" \/>\n<meta property=\"og:description\" content=\"Avviso manifestazione di interesse&nbsp; Descrizione&nbsp; In esecuzione delle determinazioni n. 198 del 12\/07\/2024 il Comune di San Giovanni in Fiore intende acquisire la manifestazione d\u2019interesse, non vincolante per l\u2019Amministrazione Comunale, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni in Fiore\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-14T10:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/uploads\/sites\/226\/2024\/07\/cropped-San-Giovanni-in-Fiore.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore\",\"datePublished\":\"2024-07-14T10:37:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/\"},\"wordCount\":129,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/wp-content\\\/uploads\\\/sites\\\/226\\\/2024\\\/07\\\/cropped-San-Giovanni-in-Fiore.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/\",\"name\":\"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore - San Giovanni in Fiore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/wp-content\\\/uploads\\\/sites\\\/226\\\/2024\\\/07\\\/cropped-San-Giovanni-in-Fiore.png\",\"datePublished\":\"2024-07-14T10:37:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/wp-content\\\/uploads\\\/sites\\\/226\\\/2024\\\/07\\\/cropped-San-Giovanni-in-Fiore.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/wp-content\\\/uploads\\\/sites\\\/226\\\/2024\\\/07\\\/cropped-San-Giovanni-in-Fiore.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/07\\\/14\\\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore - San Giovanni in Fiore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/","og_locale":"it_IT","og_type":"article","og_title":"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore - San Giovanni in Fiore","og_description":"Avviso manifestazione di interesse&nbsp; Descrizione&nbsp; In esecuzione delle determinazioni n. 198 del 12\/07\/2024 il Comune di San Giovanni in Fiore intende acquisire la manifestazione d\u2019interesse, non vincolante per l\u2019Amministrazione Comunale, [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/","og_site_name":"San Giovanni in Fiore","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-07-14T10:37:54+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/uploads\/sites\/226\/2024\/07\/cropped-San-Giovanni-in-Fiore.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore","datePublished":"2024-07-14T10:37:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/"},"wordCount":129,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/uploads\/sites\/226\/2024\/07\/cropped-San-Giovanni-in-Fiore.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/","name":"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore - San Giovanni in Fiore","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/uploads\/sites\/226\/2024\/07\/cropped-San-Giovanni-in-Fiore.png","datePublished":"2024-07-14T10:37:54+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/#primaryimage","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/uploads\/sites\/226\/2024\/07\/cropped-San-Giovanni-in-Fiore.png","contentUrl":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/uploads\/sites\/226\/2024\/07\/cropped-San-Giovanni-in-Fiore.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/07\/14\/invito-a-presentare-manifestazione-dinteresse-corredata-dallofferta-economica-al-fine-di-individuare-un-unico-operatore-con-il-quale-sottoscrivere-il-contratto-di-fornitura-dell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniinfiore\/"},{"@type":"ListItem","position":2,"name":"Invito a presentare manifestazione d\u2019interesse corredata dall\u2019offerta economica, al fine di individuare un unico operatore con il quale sottoscrivere il contratto di fornitura dell\u2019energia elettrica e del gas metano per le utenze di propriet\u00e0 del Comune di San Giovanni in Fiore"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniinfiore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002665"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/media\/180"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/media?parent=179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/categories?post=179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/tags?post=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}