{"id":296,"date":"2024-09-17T12:23:43","date_gmt":"2024-09-17T10:23:43","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/"},"modified":"2024-09-17T12:23:43","modified_gmt":"2024-09-17T10:23:43","slug":"san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/","title":{"rendered":"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: &#8220;Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale&#8221;"},"content":{"rendered":"<p><em>Videosorveglianza nelle scuole comunali<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Le scuole comunali di San Giovanni in Fiore saranno pi\u00f9 sicure grazie \u2013 a \u00abmodernissimi circuiti di videosorveglianza \u2013 ha anticipato la sindaca Rosaria Succurro \u2013 in corso di installazione all\u2019interno dei singoli plessi scolastici\u00bb.\u00a0\u00a0\u00abFinanziato dal ministero dell\u2019Interno con apposita misura\u00bb, si tratta \u2013 ha precisato la stessa sindaca \u2013 di un progetto della sua giunta \u00abvolto ad aumentare la sicurezza per gli alunni e per tutto il personale scolastico\u00bb. \u00abL\u2019abbiamo voluto \u2013 ha spiegato Succurro \u2013 con la consapevolezza che nel mondo di oggi \u00e8 pi\u00f9 alta l\u2019esposizione ai rischi, soprattutto dei bambini e dei ragazzi. La scuola ha un ruolo di guida fondamentale, che noi riconosciamo e sosteniamo con spirito di aperta e stretta collaborazione. \u00c8 indispensabile, dunque, favorire la crescita dei minori con la formazione culturale e l\u2019educazione alla convivenza e alla cittadinanza. Insieme alle scuole cittadine, lavoriamo anzitutto in questa direzione. Ora aggiungiamo la tecnologia per migliorare la sicurezza e dare un servizio ulteriore agli istituti scolastici, ai minori e alle loro famiglie\u00bb. \u00abSulle scuole cittadine prosegue il nostro impegno per renderle pi\u00f9 accoglienti, pi\u00f9 belle, pi\u00f9 attrezzate per la didattica e per lo sport; per elevarne l\u2019efficienza energetica; per adeguarle tutte alla normativa antisismica e \u2013 ha concluso la sindaca di San Giovanni in Fiore \u2013 per garantire maggiore tranquillit\u00e0 negli spazi scolastici\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Videosorveglianza nelle scuole comunali&nbsp; Descrizione&nbsp; Le scuole comunali di San Giovanni in Fiore saranno pi\u00f9 sicure grazie \u2013 a \u00abmodernissimi circuiti di videosorveglianza \u2013 ha anticipato la sindaca Rosaria Succurro [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-296","post","type-post","status-publish","format-standard","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: &quot;Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale&quot; - San Giovanni in Fiore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: &quot;Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale&quot; - San Giovanni in Fiore\" \/>\n<meta property=\"og:description\" content=\"Videosorveglianza nelle scuole comunali&nbsp; Descrizione&nbsp; Le scuole comunali di San Giovanni in Fiore saranno pi\u00f9 sicure grazie \u2013 a \u00abmodernissimi circuiti di videosorveglianza \u2013 ha anticipato la sindaca Rosaria Succurro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni in Fiore\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T10:23:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/09\\\/17\\\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/09\\\/17\\\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: &#8220;Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale&#8221;\",\"datePublished\":\"2024-09-17T10:23:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/09\\\/17\\\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\\\/\"},\"wordCount\":253,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/09\\\/17\\\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/09\\\/17\\\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\\\/\",\"name\":\"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: \\\"Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale\\\" - San Giovanni in Fiore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\"},\"datePublished\":\"2024-09-17T10:23:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/09\\\/17\\\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/09\\\/17\\\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/09\\\/17\\\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: &#8220;Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: \"Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale\" - San Giovanni in Fiore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/","og_locale":"it_IT","og_type":"article","og_title":"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: \"Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale\" - San Giovanni in Fiore","og_description":"Videosorveglianza nelle scuole comunali&nbsp; Descrizione&nbsp; Le scuole comunali di San Giovanni in Fiore saranno pi\u00f9 sicure grazie \u2013 a \u00abmodernissimi circuiti di videosorveglianza \u2013 ha anticipato la sindaca Rosaria Succurro [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/","og_site_name":"San Giovanni in Fiore","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-09-17T10:23:43+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: &#8220;Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale&#8221;","datePublished":"2024-09-17T10:23:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/"},"wordCount":253,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/","name":"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: \"Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale\" - San Giovanni in Fiore","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website"},"datePublished":"2024-09-17T10:23:43+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/09\/17\/san-giovanni-in-fiore-partiti-i-lavori-per-la-videosorveglianza-delle-scuole-comunali-la-sindaca-succurro-ulteriore-e-moderno-servizio-a-favore-dei-minori-e-delle-loro-famiglie-cosi-come-del-per\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniinfiore\/"},{"@type":"ListItem","position":2,"name":"San Giovanni in Fiore, partiti i lavori per la videosorveglianza delle scuole comunali, la sindaca Succurro: &#8220;Ulteriore e moderno servizio a favore dei minori e delle loro famiglie, cos\u00ec come del personale&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniinfiore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002774"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/comments?post=296"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/296\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/media?parent=296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/categories?post=296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/tags?post=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}