{"id":372,"date":"2024-12-02T15:41:43","date_gmt":"2024-12-02T14:41:43","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/"},"modified":"2024-12-02T15:41:43","modified_gmt":"2024-12-02T14:41:43","slug":"cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/","title":{"rendered":"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: &#8220;L&#8217;abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore&#8221;"},"content":{"rendered":"<p><em>Premio internazionale Citt\u00e0 di Gioacchino da Fiore<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Sabato 7 dicembre si terr\u00e0 nell\u2019Abbazia florense di San Giovanni in Fiore la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, nato per divulgare l\u2019attualit\u00e0 del pensiero profetico dell\u2019abate e teologo calabrese. Ideato dalla sindaca di San Giovanni in Fiore, Rosaria Succurro, il Premio viene assegnato a eminenti personalit\u00e0 dell\u2019ambito accademico, scientifico, culturale, artistico, sportivo, imprenditoriale e sociale. Realizzato quest\u2019anno dal maestro orafo Giovanni Pertichini, il prestigioso riconoscimento, che stavolta riproduce la figura gioachimita dell\u2019Albero Aquila, andr\u00e0, fra gli altri, a Giuseppe Remuzzi, fra i pi\u00f9 importanti ricercatori al mondo nel campo della medicina; al teologo Vito Mancuso; al poeta e scrittore Franco Arminio; al rettore dell\u2019Unical, Nicola Leone; all\u2019urbanista Giuseppe De Luca; alla diplomatica\u00a0Lendita Haxhitasim; agli imprenditori Gloria Tenuta e Filippo Callipo; al regista Jordan River, autore del primo film, in uscita, sulla vita di Gioacchino da Fiore; ai giornalisti Paola Severini Melograni e Stefano Buttafuoco; allo chef stellato Caterina Ceraudo; a Salvatore Angelo Oliverio, presidente emerito del Centro internazionale di studi gioachimiti; all\u2019attrice Valeria Marini, ospite dell\u2019evento, per l\u2019impegno sociale. Il Premio speciale andr\u00e0 invece alla memoria di Giacomo Mancini,\u00a0\u00abper l\u2019altissimo spessore politico, lo spirito democratico e i valori umani che ne hanno caratterizzato e ancora ne caratterizzano la figura\u00bb. Organizzato dal Comune di San Giovanni in Fiore con A2A come partner esclusivo, patrocinato dalla Regione Calabria, dalla Provincia di Cosenza e dal Parco nazionale della Sila, il Premio sar\u00e0 presentato da Ugo Floro e Francesca Russo.\u00a0\u00abCon questo appuntamento annuale \u2013 spiega la sindaca Succurro \u2013 vogliamo far conoscere il fascino, la storia e l\u2019attualit\u00e0 dell\u2019abate Gioacchino, che ebbe un\u2019influenza straordinaria nel corso dei secoli, spirituale, filosofica e in senso lato politica, anche anticipando, con le complesse immagini del suo \u201cLiber Figurarum\u201d, l\u2019ambientalismo di Papa Francesco e la concettualizzazione del presente per ideogrammi\u00bb.\u00a0\u00abOggi dobbiamo insistere \u2013 prosegue Succurro \u2013 sulla centralit\u00e0 del Sud, patria di un umanesimo contemporaneo che deriva dall\u2019utopia di Gioacchino. Di solito si parla della Calabria come luogo di criminalit\u00e0 e povert\u00e0, ma bisogna raccontarla come terra di grandi utopie ancora vive. La forza del pensiero di Gioacchino sta proprio nella sua capacit\u00e0 di richiamare l\u2019attenzione sul futuro e sulla pace come presupposto per l\u2019incontro di popoli, religioni e culture differenti\u00bb. Data l\u2019importanza del Premio, Poste Italiane ha garantito l\u2019annullo filatelico temporaneo, che verr\u00e0 apposto sulle cartoline dedicate all\u2019evento.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Premio internazionale Citt\u00e0 di Gioacchino da Fiore&nbsp; Descrizione&nbsp; Sabato 7 dicembre si terr\u00e0 nell\u2019Abbazia florense di San Giovanni in Fiore la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-372","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: &quot;L&#039;abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore&quot; - San Giovanni in Fiore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: &quot;L&#039;abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore&quot; - San Giovanni in Fiore\" \/>\n<meta property=\"og:description\" content=\"Premio internazionale Citt\u00e0 di Gioacchino da Fiore&nbsp; Descrizione&nbsp; Sabato 7 dicembre si terr\u00e0 nell\u2019Abbazia florense di San Giovanni in Fiore la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni in Fiore\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T14:41:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/02\\\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/02\\\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: &#8220;L&#8217;abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore&#8221;\",\"datePublished\":\"2024-12-02T14:41:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/02\\\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\\\/\"},\"wordCount\":448,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/02\\\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/02\\\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\\\/\",\"name\":\"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: \\\"L'abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore\\\" - San Giovanni in Fiore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\"},\"datePublished\":\"2024-12-02T14:41:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/02\\\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/02\\\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/02\\\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: &#8220;L&#8217;abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: \"L'abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore\" - San Giovanni in Fiore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/","og_locale":"it_IT","og_type":"article","og_title":"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: \"L'abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore\" - San Giovanni in Fiore","og_description":"Premio internazionale Citt\u00e0 di Gioacchino da Fiore&nbsp; Descrizione&nbsp; Sabato 7 dicembre si terr\u00e0 nell\u2019Abbazia florense di San Giovanni in Fiore la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/","og_site_name":"San Giovanni in Fiore","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-12-02T14:41:43+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: &#8220;L&#8217;abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore&#8221;","datePublished":"2024-12-02T14:41:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/"},"wordCount":448,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/","name":"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: \"L'abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore\" - San Giovanni in Fiore","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website"},"datePublished":"2024-12-02T14:41:43+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/02\/cosenza-presentata-in-provincia-la-iii-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-succurro-labate-florense-riferimento-di-un-nuovo-umanesimo-che-parte-da-san-giovanni-in-fi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniinfiore\/"},{"@type":"ListItem","position":2,"name":"Cosenza, presentata in Provincia la III edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, Succurro: &#8220;L&#8217;abate florense riferimento di un nuovo umanesimo che parte da San Giovanni in Fiore&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniinfiore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002873"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/comments?post=372"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/372\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/media?parent=372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/categories?post=372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/tags?post=372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}