{"id":378,"date":"2024-12-09T10:44:19","date_gmt":"2024-12-09T09:44:19","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/"},"modified":"2024-12-09T10:44:19","modified_gmt":"2024-12-09T09:44:19","slug":"san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/","title":{"rendered":"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: &#8220;L&#8217;abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute&#8221;"},"content":{"rendered":"<p><em>Terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si \u00e8 svolta nell\u2019Abbazia florense di San Giovanni in Fiore la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore, seguita da oltre un migliaio di persone che hanno molto apprezzato il livello e la qualit\u00e0 dell\u2019evento, ideato dalla sindaca Rosaria Succurro, con 23 premiati fra cui: il professore Giuseppe Remuzzi, tra gli scienziati della medicina pi\u00f9 quotati nel mondo; il conosciuto teologo Vito Mancuso; la gi\u00e0 ambasciatrice del Kosovo in Italia, Lendita Haxhitasim; l\u2019urbanista Giuseppe De Luca, componente del Consiglio superiore dei Lavori pubblici; il rettore dell\u2019Unical, Giovanni Leone; Paolo Maggi, infettivologo e filosofo della medicina; il campione di Tuffi Giovanni Tocci; i tenori di rango internazionale Andrea e Stefano Tanzillo; gli imprenditori modello Gloria Tenuta e Filippo Callipo; l\u2019attrice Valeria Marini, accompagnata da Anton Giulio Grande, presidente di Calabria Film Commission; il regista Jordan River, autore e direttore del film \u201cIl Monaco che vinse l\u2019Apocalisse\u201d, dedicato alla vita, all\u2019umanit\u00e0 e alla spiritualit\u00e0 di Gioacchino da Fiore, appena uscito nelle sale cinematografiche italiane. Organizzato dal Comune di San Giovanni in Fiore con A2A come partner esclusivo, il Premio ha avuto il patrocinio della Regione Calabria, della Provincia di Cosenza e del Parco nazionale della Sila. Inoltre, per la sua importanza, l\u2019evento ha ottenuto l\u2019annullo filatelico temporaneo da parte di Poste Italiane sulle relative cartoline, anche con francobolli dedicati alla compianta Jole Santelli, prima donna a presiedere l\u2019amministrazione regionale calabrese. Quest\u2019anno il premio materiale, raffigurante l\u2019Albero Aquila di Gioacchino da Fiore, \u00e8 stato realizzato con laccatura d\u2019oro dal maestro orafo Giovanni Pertichini. La sindaca di San Giovanni in Fiore ha tracciato un bilancio dell\u2019appuntamento. \u00abQuesta edizione del Premio \u2013 ha spiegato Succurro \u2013 \u00e8 servita a lanciare un messaggio al mondo: Gioacchino \u00e8 profeta della pace e della speranza. La sua visione aperta del futuro \u00e8 una luce che illumina il cammino dell\u2019umanit\u00e0 in quest\u2019epoca di guerre, crisi e smarrimento. Abbiamo reso popolare la figura dell\u2019abate calabrese e il film di River, che abbiamo sostenuto, \u00e8 uno strumento straordinario per farne comprendere l\u2019attualit\u00e0. La Calabria \u00e8 allora terra di un nuovo umanesimo contemporaneo che parte proprio dall\u2019eredit\u00e0 filosofica e spirituale di Gioacchino\u00bb. Il teologo Mancuso ha detto: \u00ab\u00c8 vero che i nostri giorni sono dotati di inquietudine e di paura, tuttavia lo spirito profetico di cui parlava Gioacchino risuona ancora, perch\u00e9 la superiorit\u00e0 dello spirito si va diffondendo sempre di pi\u00f9\u00bb. Remuzzi ha lanciato un appello importante e potente, che ha legato alla lezione concreta dell\u2019abate calabrese. \u00abFacciamo della Calabria \u2013 ha dichiarato \u2013 la capitale europea della salute. Impegniamoci tutti per questo, perch\u00e9 niente \u00e8 impossibile, se lo vogliamo fortemente\u00bb. Fra gli altri, sono stati premiati anche Salvatore Angelo Oliverio, presidente emerito del Centro internazionale di studi gioachimiti; Alfredo Prisco, che ha condotto una ricerca originale su Gioacchino e le culture islamica ed ebraica; Domenico Caruso, artista di fama internazionale che ha rappresentato le figure gioachimite in arazzi, borse, scarpe e altre opere di tessuto. La medaglia speciale del Premio, gi\u00e0 consegnata a Papa Francesco, \u00e8 stata conferita a monsignor Carlo Arnone, \u00abteologo e costruttore di spiritualit\u00e0 e comunit\u00e0\u00bb. L\u2019evento \u00e8 iniziato con una significativa esibizione musicale dell\u2019orchestra degli studenti della locale scuola media Marconi ed \u00e8 stato accompagnato dall\u2019interpretazione magistrale di noti brani lirici da parte dei tenori Tanzillo.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore&nbsp; Descrizione&nbsp; Si \u00e8 svolta nell\u2019Abbazia florense di San Giovanni in Fiore la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-378","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: &quot;L&#039;abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute&quot; - San Giovanni in Fiore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: &quot;L&#039;abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute&quot; - San Giovanni in Fiore\" \/>\n<meta property=\"og:description\" content=\"Terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore&nbsp; Descrizione&nbsp; Si \u00e8 svolta nell\u2019Abbazia florense di San Giovanni in Fiore la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni in Fiore\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T09:44:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/09\\\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/09\\\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: &#8220;L&#8217;abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute&#8221;\",\"datePublished\":\"2024-12-09T09:44:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/09\\\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\\\/\"},\"wordCount\":595,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/09\\\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/09\\\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\\\/\",\"name\":\"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: \\\"L'abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute\\\" - San Giovanni in Fiore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\"},\"datePublished\":\"2024-12-09T09:44:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/09\\\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/09\\\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2024\\\/12\\\/09\\\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: &#8220;L&#8217;abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: \"L'abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute\" - San Giovanni in Fiore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/","og_locale":"it_IT","og_type":"article","og_title":"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: \"L'abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute\" - San Giovanni in Fiore","og_description":"Terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore&nbsp; Descrizione&nbsp; Si \u00e8 svolta nell\u2019Abbazia florense di San Giovanni in Fiore la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/","og_site_name":"San Giovanni in Fiore","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-12-09T09:44:19+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: &#8220;L&#8217;abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute&#8221;","datePublished":"2024-12-09T09:44:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/"},"wordCount":595,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/","name":"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: \"L'abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute\" - San Giovanni in Fiore","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website"},"datePublished":"2024-12-09T09:44:19+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2024\/12\/09\/san-giovanni-in-fiore-conclusa-la-terza-edizione-del-premio-internazionale-citta-di-gioacchino-da-fiore-giuseppe-remuzzi-labate-un-gigante-che-ci-ispira-a-fare-della-calabria-la-capitale-europ\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniinfiore\/"},{"@type":"ListItem","position":2,"name":"San Giovanni in Fiore, conclusa la terza edizione del Premio internazionale Citt\u00e0 di Gioacchino da Fiore. Giuseppe Remuzzi: &#8220;L&#8217;abate un gigante, che ci ispira a fare della Calabria la capitale europea della salute&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniinfiore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002884"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/comments?post=378"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/378\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/media?parent=378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/categories?post=378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/tags?post=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}