{"id":580,"date":"2025-06-27T17:55:50","date_gmt":"2025-06-27T15:55:50","guid":{"rendered":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/"},"modified":"2025-06-27T17:55:50","modified_gmt":"2025-06-27T15:55:50","slug":"avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/","title":{"rendered":"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\/06\/2025"},"content":{"rendered":"<p><em>Avviso sospensione temporanea erogazione idrica <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si avvisa la cittadinanza che al fine di agevolare un intervento di ispezione sulla linea di distribuzione dell&#8217;acqua dal serbatoio di Garga, \u00e8 necessario sospendere l&#8217;erogazione dell&#8217;acqua potabile dalle ore 22.00 alle ore 23.00 del 27\/06\/2025. Le zone interessate dalla sospensione sono il quartiere Bacile, zona Pirainella e Bivio Nord.<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Avviso sospensione temporanea erogazione idrica &nbsp; Descrizione&nbsp; Si avvisa la cittadinanza che al fine di agevolare un intervento di ispezione sulla linea di distribuzione dell&#8217;acqua dal serbatoio di Garga, \u00e8 [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-580","post","type-post","status-publish","format-standard","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\/06\/2025 - San Giovanni in Fiore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\/06\/2025 - San Giovanni in Fiore\" \/>\n<meta property=\"og:description\" content=\"Avviso sospensione temporanea erogazione idrica &nbsp; Descrizione&nbsp; Si avvisa la cittadinanza che al fine di agevolare un intervento di ispezione sulla linea di distribuzione dell&#8217;acqua dal serbatoio di Garga, \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giovanni in Fiore\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T15:55:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/urgenze-e-allerta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2025\\\/06\\\/27\\\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2025\\\/06\\\/27\\\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\\\/06\\\/2025\",\"datePublished\":\"2025-06-27T15:55:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2025\\\/06\\\/27\\\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\\\/\"},\"wordCount\":71,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2025\\\/06\\\/27\\\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2025\\\/06\\\/27\\\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\\\/\",\"name\":\"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\\\/06\\\/2025 - San Giovanni in Fiore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\"},\"datePublished\":\"2025-06-27T15:55:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2025\\\/06\\\/27\\\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2025\\\/06\\\/27\\\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/2025\\\/06\\\/27\\\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\\\/06\\\/2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sangiovanniinfiore\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\/06\/2025 - San Giovanni in Fiore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\/06\/2025 - San Giovanni in Fiore","og_description":"Avviso sospensione temporanea erogazione idrica &nbsp; Descrizione&nbsp; Si avvisa la cittadinanza che al fine di agevolare un intervento di ispezione sulla linea di distribuzione dell&#8217;acqua dal serbatoio di Garga, \u00e8 [&hellip;]","og_url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/","og_site_name":"San Giovanni in Fiore","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-06-27T15:55:50+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/urgenze-e-allerta.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\/06\/2025","datePublished":"2025-06-27T15:55:50+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/"},"wordCount":71,"publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/","name":"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\/06\/2025 - San Giovanni in Fiore","isPartOf":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website"},"datePublished":"2025-06-27T15:55:50+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/2025\/06\/27\/avviso-sospensione-temporanea-acqua-potabile-zona-bacile-pirainella-e-bivio-nord-dalle-ore-22-00-alle-ore-23-00-del-27-06-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sangiovanniinfiore\/"},{"@type":"ListItem","position":2,"name":"Avviso sospensione temporanea acqua potabile zona Bacile, Pirainella e Bivio Nord dalle ore 22.00 alle ore 23.00 del 27\/06\/2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#website","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sangiovanniinfiore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sangiovanniinfiore\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sangiovanniinfiore\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003146"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/comments?post=580"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/posts\/580\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/media?parent=580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/categories?post=580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sangiovanniinfiore\/wp-json\/wp\/v2\/tags?post=580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}