{"id":461,"date":"2024-10-25T14:12:02","date_gmt":"2024-10-25T12:12:02","guid":{"rendered":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/?p=461"},"modified":"2024-10-25T14:12:04","modified_gmt":"2024-10-25T12:12:04","slug":"apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/","title":{"rendered":"Apertura del punto di facilitazione digitale del Comune di San Marzano"},"content":{"rendered":"<p><em>Sar\u00e0 aperto a partire da luned\u00ec 28 ottobre. Gli orari del punto e gli obiettivi dell&#8217;iniziativa<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p class=\"western\">Sar\u00e0 aperto a partire da luned\u00ec 28 ottobre il punto di facilitazione digitale del Comune di San Marzano di San Giuseppe. Il punto si trova all\u2019interno della <strong>sala consiliare del Comune di San Marzano<\/strong>, in piazza Angelo Casalini. Osserver\u00e0 i seguenti orari:<\/p>\n<p class=\"western\">&#8211; dal luned\u00ec al venerd\u00ec dalle ore 9 alle ore 13<br \/>\n&#8211; luned\u00ec e mercoled\u00ec anche dalle ore 16 alle ore 18.30<\/p>\n<p class=\"western\">Attraverso il punto, i cittadini potranno essere supportati dai facilitatori nell\u2019utilizzo di Internet e dei dispositivi digitali.<\/p>\n<p class=\"western\">L&#8217;obiettivo dell\u2019iniziativa \u00e8\u00a0<strong>migliorare le competenze digitali di base dei cittadini pugliesi tra i 18 e i 74 anni<\/strong>, con un&#8217;attenzione particolare a chi \u00e8 a rischio di esclusione digitale, per consentire loro di\u00a0<strong>esercitare i diritti di cittadinanza digitale<\/strong>\u00a0previsti dal Codice dell\u2019Amministrazione Digitale (CAD).<\/p>\n<p class=\"western\">Nello specifico, il punto di facilitazione:<\/p>\n<p class=\"western\">&#8211; concorre all\u2019accrescimento delle competenze digitali diffuse;<br \/>\n&#8211; favorisce l\u2019uso autonomo, consapevole e responsabile delle nuove tecnologie;<br \/>\n&#8211; promuove il diritto di cittadinanza digitale attiva da parte di tutti;<br \/>\n&#8211; incentiva l\u2019uso dei servizi online dei privati e delle Amministrazioni Pubbliche, semplificando il rapporto tra cittadini e PA.<\/p>\n<p class=\"western\">Oltre a questo, con l\u2019apertura del punto di facilitazione si intende anche\u00a0<strong>garantire una distribuzione capillare e una prossimit\u00e0 territoriale dei servizi digitali<\/strong>\u00a0in tutta la regione e potenziare l&#8217;accesso e l&#8217;uso dei servizi digitali offerti dalla Pubblica Amministrazione e dalle imprese, integrando e non sostituendo i punti di accesso fisici esistenti.<\/p>\n<p class=\"western\">L\u2019attivazione del punto di facilitazione digitale \u00e8 frutto della convenzione stipulata il 18 ottobre 2024 tra il Comune di Grottaglie, ente capofila dell&#8217;Ambito Territoriale Sociale TA\/6, e la Societ\u00e0 Cooperativa Sociale Ma.Vi., all\u2019interno del progetto \u201cRete dei servizi di facilitazione digitale\u201d, inquadrato nell\u2019ambito della misura nazionale 1.7.2 del PNRR del Dipartimento per la Trasformazione Digitale (DTD).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 aperto a partire da luned\u00ec 28 ottobre. Gli orari del punto e gli obiettivi dell&#8217;iniziativa&nbsp; Descrizione&nbsp; Sar\u00e0 aperto a partire da luned\u00ec 28 ottobre il punto di facilitazione digitale [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":465,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apertura del punto di facilitazione digitale del Comune di San Marzano - San Marzano di San Giuseppe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apertura del punto di facilitazione digitale del Comune di San Marzano - San Marzano di San Giuseppe\" \/>\n<meta property=\"og:description\" content=\"Sar\u00e0 aperto a partire da luned\u00ec 28 ottobre. Gli orari del punto e gli obiettivi dell&#8217;iniziativa&nbsp; Descrizione&nbsp; Sar\u00e0 aperto a partire da luned\u00ec 28 ottobre il punto di facilitazione digitale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/\" \/>\n<meta property=\"og:site_name\" content=\"San Marzano di San Giuseppe\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-25T12:12:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-25T12:12:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/10\/PUnto-di-facilitazione-digitale-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Apertura del punto di facilitazione digitale del Comune di San Marzano\",\"datePublished\":\"2024-10-25T12:12:02+00:00\",\"dateModified\":\"2024-10-25T12:12:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/\"},\"wordCount\":317,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/10\\\/PUnto-di-facilitazione-digitale-1.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/\",\"name\":\"Apertura del punto di facilitazione digitale del Comune di San Marzano - San Marzano di San Giuseppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/10\\\/PUnto-di-facilitazione-digitale-1.png\",\"datePublished\":\"2024-10-25T12:12:02+00:00\",\"dateModified\":\"2024-10-25T12:12:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/10\\\/PUnto-di-facilitazione-digitale-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/10\\\/PUnto-di-facilitazione-digitale-1.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/10\\\/25\\\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apertura del punto di facilitazione digitale del Comune di San Marzano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apertura del punto di facilitazione digitale del Comune di San Marzano - San Marzano di San Giuseppe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/","og_locale":"it_IT","og_type":"article","og_title":"Apertura del punto di facilitazione digitale del Comune di San Marzano - San Marzano di San Giuseppe","og_description":"Sar\u00e0 aperto a partire da luned\u00ec 28 ottobre. Gli orari del punto e gli obiettivi dell&#8217;iniziativa&nbsp; Descrizione&nbsp; Sar\u00e0 aperto a partire da luned\u00ec 28 ottobre il punto di facilitazione digitale [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/","og_site_name":"San Marzano di San Giuseppe","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-10-25T12:12:02+00:00","article_modified_time":"2024-10-25T12:12:04+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/10\/PUnto-di-facilitazione-digitale-1.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Apertura del punto di facilitazione digitale del Comune di San Marzano","datePublished":"2024-10-25T12:12:02+00:00","dateModified":"2024-10-25T12:12:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/"},"wordCount":317,"publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/10\/PUnto-di-facilitazione-digitale-1.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/","name":"Apertura del punto di facilitazione digitale del Comune di San Marzano - San Marzano di San Giuseppe","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/10\/PUnto-di-facilitazione-digitale-1.png","datePublished":"2024-10-25T12:12:02+00:00","dateModified":"2024-10-25T12:12:04+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/#primaryimage","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/10\/PUnto-di-facilitazione-digitale-1.png","contentUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/10\/PUnto-di-facilitazione-digitale-1.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/10\/25\/apertura-del-punto-di-facilitazione-digitale-del-comune-di-san-marzano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/"},{"@type":"ListItem","position":2,"name":"Apertura del punto di facilitazione digitale del Comune di San Marzano"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001417"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/comments?post=461"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/461\/revisions"}],"predecessor-version":[{"id":463,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/461\/revisions\/463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media\/465"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media?parent=461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/categories?post=461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/tags?post=461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}