{"id":564,"date":"2024-12-13T10:04:32","date_gmt":"2024-12-13T09:04:32","guid":{"rendered":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/"},"modified":"2024-12-13T14:49:14","modified_gmt":"2024-12-13T13:49:14","slug":"convocazione-del-consiglio-comunale-per-lunedi-16-dicembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/","title":{"rendered":"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre"},"content":{"rendered":"<p><em>L&#8217;ordine del giorno del Consiglio Comunale convocato per luned\u00ec 16 dicembre<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il Presidente del Consiglio Cosimo Macrip\u00f2 ha convocato il Consiglio Comunale in sessione straordinaria, in seduta pubblica, per il giorno 16 dicembre 2024 alle ore 19.30, in prima convocazione, presso la Sede Municipale.<\/p>\n<p>Ordine del giorno<\/p>\n<p>1. Ratifica variazione d&#8217;urgenza al bilancio di previsione finanziario 2024\/2026 &#8211; Delibera di Giunta Comunale N 104 del 28.11.2024.<\/p>\n<article class=\"it-page-section anchor-offset\" data-audio=\"\">\n<div class=\"richtext-wrapper titillium\">\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Oltre che in sede, sar\u00e0 possibile seguire i lavori del Consiglio Comunale in diretta streaming sulla pagina Facebook del Comune.<\/div>\n<\/div>\n<\/div>\n<\/article>\n<article class=\"it-page-section anchor-offset mt-5\"><\/article>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ordine del giorno del Consiglio Comunale convocato per luned\u00ec 16 dicembre&nbsp; Descrizione&nbsp; Il Presidente del Consiglio Cosimo Macrip\u00f2 ha convocato il Consiglio Comunale in sessione straordinaria, in seduta pubblica, per [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":568,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre - San Marzano di San Giuseppe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre - San Marzano di San Giuseppe\" \/>\n<meta property=\"og:description\" content=\"L&#8217;ordine del giorno del Consiglio Comunale convocato per luned\u00ec 16 dicembre&nbsp; Descrizione&nbsp; Il Presidente del Consiglio Cosimo Macrip\u00f2 ha convocato il Consiglio Comunale in sessione straordinaria, in seduta pubblica, per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/\" \/>\n<meta property=\"og:site_name\" content=\"San Marzano di San Giuseppe\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-13T09:04:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T13:49:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/12\/convocazione-consiglio-comunale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre\",\"datePublished\":\"2024-12-13T09:04:32+00:00\",\"dateModified\":\"2024-12-13T13:49:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/\"},\"wordCount\":88,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/12\\\/convocazione-consiglio-comunale.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/\",\"name\":\"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre - San Marzano di San Giuseppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/12\\\/convocazione-consiglio-comunale.png\",\"datePublished\":\"2024-12-13T09:04:32+00:00\",\"dateModified\":\"2024-12-13T13:49:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/12\\\/convocazione-consiglio-comunale.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/12\\\/convocazione-consiglio-comunale.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/12\\\/13\\\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre - San Marzano di San Giuseppe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre - San Marzano di San Giuseppe","og_description":"L&#8217;ordine del giorno del Consiglio Comunale convocato per luned\u00ec 16 dicembre&nbsp; Descrizione&nbsp; Il Presidente del Consiglio Cosimo Macrip\u00f2 ha convocato il Consiglio Comunale in sessione straordinaria, in seduta pubblica, per [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/","og_site_name":"San Marzano di San Giuseppe","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-12-13T09:04:32+00:00","article_modified_time":"2024-12-13T13:49:14+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/12\/convocazione-consiglio-comunale.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre","datePublished":"2024-12-13T09:04:32+00:00","dateModified":"2024-12-13T13:49:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/"},"wordCount":88,"publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/12\/convocazione-consiglio-comunale.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/","name":"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre - San Marzano di San Giuseppe","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/12\/convocazione-consiglio-comunale.png","datePublished":"2024-12-13T09:04:32+00:00","dateModified":"2024-12-13T13:49:14+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/#primaryimage","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/12\/convocazione-consiglio-comunale.png","contentUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/12\/convocazione-consiglio-comunale.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/12\/13\/convocazione-del-consiglio-comunale-per-lunedi-16-dicembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/"},{"@type":"ListItem","position":2,"name":"Convocazione del Consiglio Comunale per luned\u00ec 16 dicembre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001480"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/comments?post=564"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/564\/revisions"}],"predecessor-version":[{"id":566,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/564\/revisions\/566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media\/568"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media?parent=564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/categories?post=564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/tags?post=564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}