{"id":59,"date":"2024-04-19T12:12:21","date_gmt":"2024-04-19T10:12:21","guid":{"rendered":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/"},"modified":"2024-04-19T12:12:21","modified_gmt":"2024-04-19T10:12:21","slug":"ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/","title":{"rendered":"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie &#8211; anno 2024"},"content":{"rendered":"<p><em>Ordinanza Sindacale n.32 del 19\/04\/2024: Misure contro le zanzare a San Marzano di San Giuseppe. Obiettivo: Prevenire la proliferazione delle zanzare e la diffusione di malattie. Periodo: 19 aprile &#8211; 30 novembre 2024.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il sindaco ha emanato un\u2019ordinanza sulle misure preventive da adottare contro la proliferazione delle zanzare e la potenziale trasmissione di malattie ad essa connesse.<\/p>\n<p>L\u2019ordinanza, in vigore fino al 30 novembre 2024, segue la nota della ASL Taranto con la quale si invita l\u2019Amministrazione Comunale ad adottare le misure necessarie al fine di assicurare idonei interventi di prevenzione della proliferazione delle zanzare (Culex, Aedes aegypti, Aedes albopictus) che fungono da vettore per la trasmissione di vari virus e patogeni responsabili di infezioni.<\/p>\n<p>L\u2019ordinanza prevede una serie di misure da adottare da parte della cittadinanza e delle attivit\u00e0 commerciali. Di seguito, in allegato, il testo integrale da scaricare.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_61\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/Ordinanza-sindacale-32-del-19-04-2024.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/Ordinanza-sindacale-32-del-19-04-2024.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ordinanza sindacale 32 del 19 04 2024<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ordinanza Sindacale n.32 del 19\/04\/2024: Misure contro le zanzare a San Marzano di San Giuseppe. Obiettivo: Prevenire la proliferazione delle zanzare e la diffusione di malattie. Periodo: 19 aprile &#8211; [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":60,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-59","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie - anno 2024 - San Marzano di San Giuseppe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie - anno 2024 - San Marzano di San Giuseppe\" \/>\n<meta property=\"og:description\" content=\"Ordinanza Sindacale n.32 del 19\/04\/2024: Misure contro le zanzare a San Marzano di San Giuseppe. Obiettivo: Prevenire la proliferazione delle zanzare e la diffusione di malattie. Periodo: 19 aprile &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"San Marzano di San Giuseppe\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-19T10:12:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie &#8211; anno 2024\",\"datePublished\":\"2024-04-19T10:12:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/\"},\"wordCount\":160,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/05\\\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/\",\"name\":\"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie - anno 2024 - San Marzano di San Giuseppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/05\\\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg\",\"datePublished\":\"2024-04-19T10:12:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/05\\\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/05\\\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/04\\\/19\\\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie &#8211; anno 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie - anno 2024 - San Marzano di San Giuseppe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie - anno 2024 - San Marzano di San Giuseppe","og_description":"Ordinanza Sindacale n.32 del 19\/04\/2024: Misure contro le zanzare a San Marzano di San Giuseppe. Obiettivo: Prevenire la proliferazione delle zanzare e la diffusione di malattie. Periodo: 19 aprile &#8211; [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/","og_site_name":"San Marzano di San Giuseppe","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-04-19T10:12:21+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie &#8211; anno 2024","datePublished":"2024-04-19T10:12:21+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/"},"wordCount":160,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/","name":"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie - anno 2024 - San Marzano di San Giuseppe","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg","datePublished":"2024-04-19T10:12:21+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg","contentUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-6.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/04\/19\/ordinanza-n-32-del-19-aprile-2024-misure-preventive-contro-la-proliferazione-delle-zanzare-e-la-potenziale-trasmissione-di-malattie-anno-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/"},{"@type":"ListItem","position":2,"name":"Ordinanza n.32 del 19 aprile 2024: Misure preventive contro la proliferazione delle zanzare e la potenziale trasmissione di malattie &#8211; anno 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001192"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/comments?post=59"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/59\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media\/60"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media?parent=59"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/categories?post=59"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/tags?post=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}