{"id":639,"date":"2025-02-03T09:59:50","date_gmt":"2025-02-03T08:59:50","guid":{"rendered":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/"},"modified":"2025-02-21T09:58:40","modified_gmt":"2025-02-21T08:58:40","slug":"avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/","title":{"rendered":"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI"},"content":{"rendered":"<p><em>AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL<br \/>\nSERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>L\u2019Amministrazione Comunale ha indetto un Avviso pubblico per la concessione, per l\u2019anno 2025, di un\u00a0<strong>contributo economico alle famiglie<\/strong>\u00a0tramite un voucher\/contributo una tantum per la fruizione del servizio di asilo nido o micronido al fine di abbattere il costo della retta di frequenza dei nidi autorizzati e\/o accreditati per l&#8217;anno 2025, residenti nel Comune di San Marzano di San Giuseppe, frequentanti anche in un comune diverso da quello di residenza.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Domande <\/strong>tramite protocollo, raccomandata o pec.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Destinatari e Requisiti per la partecipazione all\u2019Avviso pubblico <\/strong>&#8211;\u00a0Alla famiglia che per ogni figlio minore dai 3 ai 36 mesi fruisce e\/o ha fruito del servizio di asilo nido verr\u00e0 assegnato un voucher\/contributo.<br \/>\nLa dotazione finanziaria sar\u00e0 ripartita tra gli idonei ammessi sulla base della spesa effettivamente sostenuta nell\u2019anno 2024 per il servizio e documentata da ricevute quietanzate.<\/p>\n<p>Il voucher\/contributo sar\u00e0 erogato direttamente al richiedente per ogni minore a rimborso delle spese sostenute per un massimo 11 mensilit\u00e0 per tutto l\u2019anno 2025 in relazione alle regolari ricevute delle spese sostenute.<\/p>\n<p>Coloro che hanno pi\u00f9 figli minori possono presentare domanda per ciascun figlio.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Modalit\u00e0 e di presentazione della domanda &#8211;\u00a0<\/strong>Le domande di partecipazione dovranno essere presentate, in forma di dichiarazione sostitutiva a norma del D.P.R. 28\/12\/2000 n. 445, unicamente utilizzando il modulo allegato, con l\u2019indicazione di tutti i dati ivi richiesti.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Documentazione richiesta &#8211;\u00a0<\/strong>Le domande di partecipazione alla presente procedura devono essere corredate dalla seguente documentazione:<\/p>\n<ol>\n<li>Copia non autenticata del documento d\u2019identit\u00e0 del richiedente che sottoscrive la domanda;<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>Criteri di liquidazione dei contributi<\/strong><\/p>\n<p>Il contributo sar\u00e0 erogato dal Comune alla famiglia a seguito di esibizione di documentazione fiscale di avvenuto pagamento del servizio, riportante il nominativo del diversamente abile che ne ha beneficiato.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Controlli<\/strong><\/p>\n<p>Su tutti i dati dichiarati ai fini del presente bando verranno effettuati controlli ai sensi degli art. 71 e 72 del DPR 445\/200.<\/p>\n<p>&nbsp;<\/p>\n<p>Riferimento per informazioni \u00e8 possibile rivolgersi all\u2019Ufficio Servizi Sociali del Comune di San Marzano di San Giuseppe.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_658\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/DOMANDA-CONTRIBUTO-ASILI-NIDO-2025.doc\" onclick=\"window.open('https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/DOMANDA-CONTRIBUTO-ASILI-NIDO-2025.doc', '_system'); return false;\"><i class='icon attachment'><\/i>_DOMANDA CONTRIBUTO ASILI NIDO 2025<\/a><\/li>\n<li><a id=\"wpba_attachment_list_659\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/DETERMINA-CONTRIBUTO-ASILO-NIDO-OBIETTIVI-PER-IL-SOCIALE-2024-2025.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/DETERMINA-CONTRIBUTO-ASILO-NIDO-OBIETTIVI-PER-IL-SOCIALE-2024-2025.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>_DETERMINA CONTRIBUTO ASILO NIDO-OBIETTIVI PER IL SOCIALE 2024-2025<\/a><\/li>\n<li><a id=\"wpba_attachment_list_660\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/AVVISO-PUBBLICO-ASILO-NIDO-2025.doc\" onclick=\"window.open('https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/AVVISO-PUBBLICO-ASILO-NIDO-2025.doc', '_system'); return false;\"><i class='icon attachment'><\/i>_AVVISO PUBBLICO ASILO NIDO 2025<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI&nbsp; Descrizione&nbsp; L\u2019Amministrazione Comunale ha indetto un Avviso [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI - San Marzano di San Giuseppe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI - San Marzano di San Giuseppe\" \/>\n<meta property=\"og:description\" content=\"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI&nbsp; Descrizione&nbsp; L\u2019Amministrazione Comunale ha indetto un Avviso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/\" \/>\n<meta property=\"og:site_name\" content=\"San Marzano di San Giuseppe\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-03T08:59:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-21T08:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/il-comune-informa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI\",\"datePublished\":\"2025-02-03T08:59:50+00:00\",\"dateModified\":\"2025-02-21T08:58:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/\"},\"wordCount\":376,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2025\\\/02\\\/il-comune-informa-3.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/\",\"name\":\"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI - San Marzano di San Giuseppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2025\\\/02\\\/il-comune-informa-3.png\",\"datePublished\":\"2025-02-03T08:59:50+00:00\",\"dateModified\":\"2025-02-21T08:58:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2025\\\/02\\\/il-comune-informa-3.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2025\\\/02\\\/il-comune-informa-3.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/02\\\/03\\\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI - San Marzano di San Giuseppe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI - San Marzano di San Giuseppe","og_description":"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI&nbsp; Descrizione&nbsp; L\u2019Amministrazione Comunale ha indetto un Avviso [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/","og_site_name":"San Marzano di San Giuseppe","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-02-03T08:59:50+00:00","article_modified_time":"2025-02-21T08:58:40+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/il-comune-informa.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI","datePublished":"2025-02-03T08:59:50+00:00","dateModified":"2025-02-21T08:58:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/"},"wordCount":376,"publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/il-comune-informa-3.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/","name":"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI - San Marzano di San Giuseppe","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/il-comune-informa-3.png","datePublished":"2025-02-03T08:59:50+00:00","dateModified":"2025-02-21T08:58:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/#primaryimage","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/il-comune-informa-3.png","contentUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/02\/il-comune-informa-3.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/02\/03\/avviso-pubblico-per-la-concessione-di-contributi-alle-famiglie-per-il-servizio-di-asilo-nido-per-figli-minori-dai-0-ai-36-mesi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/"},{"@type":"ListItem","position":2,"name":"AVVISO PUBBLICO PER LA CONCESSIONE DI CONTRIBUTI ALLE FAMIGLIE PER IL SERVIZIO DI ASILO NIDO PER FIGLI MINORI DAI 0 AI 36 MESI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001530"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/comments?post=639"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/639\/revisions"}],"predecessor-version":[{"id":656,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/639\/revisions\/656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media\/657"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media?parent=639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/categories?post=639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/tags?post=639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}