{"id":70,"date":"2024-05-02T12:26:26","date_gmt":"2024-05-02T10:26:26","guid":{"rendered":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/"},"modified":"2024-05-14T12:29:59","modified_gmt":"2024-05-14T10:29:59","slug":"elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/","title":{"rendered":"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare"},"content":{"rendered":"<p><em>In vista delle Elezioni Europee dell&#8217;8 e 9 giugno 2024 \u00e8 ammessa la possibilit\u00e0 di voto domiciliare per gli elettori affetti da grave infermit\u00e0 o in dipendenza continuativa e vitale da apparecchiature elettromedicali.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In vista delle Elezioni Europee dell&#8217;8 e 9 giugno 2024 \u00e8 ammessa la possibilit\u00e0 di voto domiciliare per gli elettori affetti da grave infermit\u00e0 o in dipendenza continuativa e vitale da apparecchiature elettromedicali.<\/p>\n<p>Come richiedere il voto domiciliare.<\/p>\n<p>La domanda deve essere inoltrata all&#8217;Ufficio Elettorale in un periodo compreso tra il 40\u00b0 e il 20\u00b0 giorno antecedente la data delle elezioni e precisamente tra marted\u00ec 30 aprile 2024 e luned\u00ec 20 maggio 2024 unitamente ai seguenti documenti:<\/p>\n<ul>\n<li>dichiarazione, in carta libera, attestante la volont\u00e0 di esprimere il voto presso l&#8217;abitazione con l&#8217;indicazione dell&#8217;indirizzo;<\/li>\n<li>copia della tessera elettorale;<\/li>\n<li>certificato rilasciato dal funzionario medico designato dall&#8217;ASL, attestante le condizioni di infermit\u00e0 o di dipendenza continuativa da apparecchiature elettromedicali.<\/li>\n<\/ul>\n<p>Nel caso in cui sulla tessera elettorale non sia gi\u00e0 inserita l&#8217;annotazione del diritto di voto assistito, il certificato deve indicare anche l&#8217;eventuale necessit\u00e0 di un accompagnatore per l&#8217;esercizio del voto.<\/p>\n<p>Ufficio Elettorale Comune San Marzano di San Giuseppe<\/p>\n<p><a href=\"mailto:protocollo@pec.comunesanmarzano.ta.it\">protocollo@pec.comunesanmarzano.ta.it<\/a><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_76\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/ISTANZA-VOTO-DOMICILARE-1.doc\" onclick=\"window.open('https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/ISTANZA-VOTO-DOMICILARE-1.doc', '_system'); return false;\"><i class='icon attachment'><\/i>ISTANZA VOTO DOMICILARE<\/a><\/li>\n<li><a id=\"wpba_attachment_list_77\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/MANIFESTO-VOTO-DOMICILIARE-1.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/MANIFESTO-VOTO-DOMICILIARE-1.docx', '_system'); return false;\"><i class='icon attachment'><\/i>MANIFESTO VOTO DOMICILIARE<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In vista delle Elezioni Europee dell&#8217;8 e 9 giugno 2024 \u00e8 ammessa la possibilit\u00e0 di voto domiciliare per gli elettori affetti da grave infermit\u00e0 o in dipendenza continuativa e vitale [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":75,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-70","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare - San Marzano di San Giuseppe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare - San Marzano di San Giuseppe\" \/>\n<meta property=\"og:description\" content=\"In vista delle Elezioni Europee dell&#8217;8 e 9 giugno 2024 \u00e8 ammessa la possibilit\u00e0 di voto domiciliare per gli elettori affetti da grave infermit\u00e0 o in dipendenza continuativa e vitale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/\" \/>\n<meta property=\"og:site_name\" content=\"San Marzano di San Giuseppe\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T10:26:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-14T10:29:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare\",\"datePublished\":\"2024-05-02T10:26:26+00:00\",\"dateModified\":\"2024-05-14T10:29:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/\"},\"wordCount\":192,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/05\\\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/\",\"name\":\"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare - San Marzano di San Giuseppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/05\\\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg\",\"datePublished\":\"2024-05-02T10:26:26+00:00\",\"dateModified\":\"2024-05-14T10:29:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/05\\\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2024\\\/05\\\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2024\\\/05\\\/02\\\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare - San Marzano di San Giuseppe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare - San Marzano di San Giuseppe","og_description":"In vista delle Elezioni Europee dell&#8217;8 e 9 giugno 2024 \u00e8 ammessa la possibilit\u00e0 di voto domiciliare per gli elettori affetti da grave infermit\u00e0 o in dipendenza continuativa e vitale [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/","og_site_name":"San Marzano di San Giuseppe","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-05-02T10:26:26+00:00","article_modified_time":"2024-05-14T10:29:59+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare","datePublished":"2024-05-02T10:26:26+00:00","dateModified":"2024-05-14T10:29:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/"},"wordCount":192,"publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/","name":"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare - San Marzano di San Giuseppe","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg","datePublished":"2024-05-02T10:26:26+00:00","dateModified":"2024-05-14T10:29:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/#primaryimage","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg","contentUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2024\/05\/immagine_evidenza_comune_san_marzano_di_san_giuseppe-10.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2024\/05\/02\/elezioni-europee-8-9-giugno-2024-guida-per-il-voto-domiciliare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/"},{"@type":"ListItem","position":2,"name":"Elezioni Europee 8 \u2013 9 Giugno 2024: guida per il voto domiciliare"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001200"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/comments?post=70"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/70\/revisions"}],"predecessor-version":[{"id":74,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/70\/revisions\/74"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media\/75"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media?parent=70"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/categories?post=70"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/tags?post=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}