{"id":740,"date":"2025-05-13T19:08:39","date_gmt":"2025-05-13T17:08:39","guid":{"rendered":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/"},"modified":"2025-05-13T19:08:39","modified_gmt":"2025-05-13T17:08:39","slug":"elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/","title":{"rendered":"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei."},"content":{"rendered":"<p><em>In occasione delle Elezioni Amministrative 2025 del 25 e 26 maggio 2025, chi si recher\u00e0 a votare nel proprio comune di iscrizione elettorale potr\u00e0 usufruire delle agevolazioni di viaggio previste dalla normativa statale per le consultazioni elettorali<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si comunica alla cittadinanza che con Circ. n.42 DAIT, sono state rese note le agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei in occasione delle prossime Consultazioni Referendarie e Amministrative. Nello specifico, gli elettori che si recheranno a votare nel proprio comune di iscrizione elettorale potranno usufruire delle agevolazioni di viaggio applicate da enti o societ\u00e0 che gestiscono i relativi servizi di trasporto, secondo i tempi e le modalit\u00e0 riportate nella circolare in ALLEGATO.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_742\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/05\/Circolare42-signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/05\/Circolare42-signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Circolare42-signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione delle Elezioni Amministrative 2025 del 25 e 26 maggio 2025, chi si recher\u00e0 a votare nel proprio comune di iscrizione elettorale potr\u00e0 usufruire delle agevolazioni di viaggio previste [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei. - San Marzano di San Giuseppe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei. - San Marzano di San Giuseppe\" \/>\n<meta property=\"og:description\" content=\"In occasione delle Elezioni Amministrative 2025 del 25 e 26 maggio 2025, chi si recher\u00e0 a votare nel proprio comune di iscrizione elettorale potr\u00e0 usufruire delle agevolazioni di viaggio previste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/\" \/>\n<meta property=\"og:site_name\" content=\"San Marzano di San Giuseppe\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-13T17:08:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/05\/immagine-referendum-2025-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei.\",\"datePublished\":\"2025-05-13T17:08:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/\"},\"wordCount\":126,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2025\\\/05\\\/immagine-referendum-2025-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/\",\"name\":\"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei. - San Marzano di San Giuseppe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2025\\\/05\\\/immagine-referendum-2025-1.jpg\",\"datePublished\":\"2025-05-13T17:08:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2025\\\/05\\\/immagine-referendum-2025-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/wp-content\\\/uploads\\\/sites\\\/231\\\/2025\\\/05\\\/immagine-referendum-2025-1.jpg\",\"width\":750,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/2025\\\/05\\\/13\\\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanmarzanodisangiuseppe\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei. - San Marzano di San Giuseppe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei. - San Marzano di San Giuseppe","og_description":"In occasione delle Elezioni Amministrative 2025 del 25 e 26 maggio 2025, chi si recher\u00e0 a votare nel proprio comune di iscrizione elettorale potr\u00e0 usufruire delle agevolazioni di viaggio previste [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/","og_site_name":"San Marzano di San Giuseppe","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-05-13T17:08:39+00:00","og_image":[{"width":750,"height":744,"url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/05\/immagine-referendum-2025-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei.","datePublished":"2025-05-13T17:08:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/"},"wordCount":126,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/05\/immagine-referendum-2025-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/","name":"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei. - San Marzano di San Giuseppe","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/05\/immagine-referendum-2025-1.jpg","datePublished":"2025-05-13T17:08:39+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/#primaryimage","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/05\/immagine-referendum-2025-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-content\/uploads\/sites\/231\/2025\/05\/immagine-referendum-2025-1.jpg","width":750,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/2025\/05\/13\/elezioni-amministrative-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-via-mare-autostradali-e-aerei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/"},{"@type":"ListItem","position":2,"name":"Elezioni Amministrative 2025. Agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#website","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001612"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/comments?post=740"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/posts\/740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media\/741"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/media?parent=740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/categories?post=740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanmarzanodisangiuseppe\/wp-json\/wp\/v2\/tags?post=740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}