{"id":20600,"date":"2020-12-30T11:30:43","date_gmt":"2020-12-30T10:30:43","guid":{"rendered":"https:\/\/comune.san-miniato.pi.it\/?p=20600"},"modified":"2020-12-30T11:30:43","modified_gmt":"2020-12-30T10:30:43","slug":"san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/","title":{"rendered":"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza"},"content":{"rendered":"<p>Con 603 positivi nell&#8217;ultima settimana del mese di novembre, il Comune di San Miniato ha toccato il picco dell&#8217;emergenza sanitaria, una situazione che, alla fine dell&#8217;anno, ci presenta una serie di dati importanti attraverso i quali poter raccontare che cosa \u00e8 stata la pandemia del 2020 per la Citt\u00e0 della Rocca. &#8220;Attualmente siamo a 29 decessi per Covid, un numero che d\u00e0 la dimensione di che cosa sia accaduto finora, con 1.164 guariti e 88 positivi ad oggi &#8211; spiega il sindaco di San Miniato Simone Giglioli -. Non nascondo che l&#8217;anno in via di conclusione sia stato molto tragico per noi, soprattutto perch\u00e9 ci ha portato via un amico, un capace assessore, Gianluca Bertini, e come lui altri cittadini che hanno dovuto affrontare questa terribile malattia. Anche dal punto di vista amministrativo non \u00e8 stato un anno semplice; abbiamo dovuto ribaltare il bilancio e far fronte alle emergenze che hanno affiancato quella sanitaria, come quella alimentare e quella economica&#8221;.<\/p>\n<p>Tre sono stati gli strumenti di cui si \u00e8 avvalso il Comune per tentare di contenere l&#8217;emergenza. Il bonus alimentare con il quale, per due volte, il Governo ha stanziato 148mila euro per San Miniato, consentendo l&#8217;acquisto di 6mila buoni da 25 euro per la prima tranche di contributi e di accogliere 165 domande di aiuto per la seconda. &#8220;Oltre a questo abbiamo attivato il bonus affitti per andare a sostenere quei lavoratori dipendenti e autonomi che, a causa dell&#8217;emergenza, hanno subito una riduzione del reddito, stanziando 30mila euro che ci hanno permesso di aiutare ben 104 famiglie &#8211; spiega ancora il sindaco -. Grazie ad una raccolta fondi organizzata dal nostro Comune, sono stati raccolti 5mila euro che abbiamo destinato all&#8217;acquisto di cibo e medicinali, oltre ai 10mila euro erogati dalla Fondazione CRSM, sempre da destinare a queste primarie necessit\u00e0&#8221;.<\/p>\n<p>Sempre per quanto riguarda gli aiuti ai cittadini, il Comune di San Miniato ha organizzato la consegna delle mascherine che la Regione Toscana ha messo a disposizione della popolazione, grazie al prezioso contributo delle associazioni di Protezione Civile, andando a consegnarne 64mila ad aprile e 145mila a novembre.<\/p>\n<p><strong>COMMERCIO E ATTIVITA&#8217; PRODUTTIVE<\/strong><br \/>\n&#8220;Le attivit\u00e0 commerciali e produttive sono state due categorie che molto hanno sofferto le chiusure ad intermittenza imposte dai decreti governativi &#8211; dichiara la vicesindaco e assessore alle attivit\u00e0 produttive Elisa Montanelli -. Per questo abbiamo fatto uno sforzo importante per andare ad intercettare tutte le risorse di bilancio necessarie ad intervenire per alleggerire le spese e i costi&#8221;. Anche in questo caso sono state tre le misure pi\u00f9 importanti: per quanto riguarda l&#8217;IMU \u00e8 stato revocato dello 0,10% l&#8217;aumento sui fabbricati &#8220;D&#8221; (capannoni e opifici industriali) e aree edificabili, misura che ha richiesto un investimento di 90mila euro; per la TOSAP, oltre all&#8217;esenzione per tutto il 2020, si \u00e8 stanziato un fondo da 10mila euro con il quale rimborsare i mesi gi\u00e0 pagati ma non dovuti, versati dagli ambulanti dei mercati; infine sulla Tari \u00e8 stato stanziato un fondo da 70mila euro con il quale si vanno a ristorare tutte le attivit\u00e0 chiuse o costrette a ridurre il loro lavoro, al quale vanno aggiunti i 230mila euro stanziati per il primo lockdown. &#8220;Si tratta di interventi mirati ad aiutare nell&#8217;immediato le nostre attivit\u00e0, ben consapevoli che questo non baster\u00e0 &#8211; spiega ancora l&#8217;assessore Montanelli -. Oltre a questi aiuti, abbiamo creato una serie di azioni in aiuto alle attivit\u00e0 di vicinato, come il progetto &#8220;Amazzoni San Miniato&#8221; che non solo ha avuto un ottimo successo, ma che proseguir\u00e0 anche per il periodo dei saldi. Da bilancio abbiamo inoltre stanziato 25mila euro per i nostri tre CCN (San Miniato, San Miniato Basso e Ponte a Egola), il Consorzio Conciatori di Ponte a Egola e il Consorzio Artigiani di San Miniato Basso.<\/p>\n<p><strong>SCUOLA<\/strong><br \/>\nAnno travagliato anche per il mondo della scuola. &#8220;Dopo la chiusura dei servizi educativi e la sospensione dell&#8217;attivit\u00e0 didattica in presenza prevista lo scorso 5 marzo, ci siamo dovuti riorganizzare &#8211; spiega l&#8217;assessore alla scuola Giulia Profeti -. Sono state sospese le rette per tutti i servizi a domanda individuale (mensa, trasporto e nidi) nei mesi da marzo a luglio, oltre a ridurre del 50% la quota delle rette in caso di assenza pari a 14 giorni o superiore. Abbiamo dato 14mila euro al nido accreditato e alle scuole paritarie in modo da sostenere il sistema scolastico integrato e abbiamo supportato i nostri due istituti comprensivi nella realizzazione della didattica a distanza. Per dare un ulteriore supporto alle famiglie, ci siamo impegnati ad attivare i centri estivi (giugno-settembre) con 1.597 bambini e oltre 5mila ore di attivit\u00e0, grazie ad un contributo di circa 63mila euro proveniente da fondi ministeriali e regionali&#8221;. E per il 2021 sono molteplici gli investimenti previsti in ambito scolastico. &#8220;Abbiamo partecipato a una serie di bandi per il potenziamento della connessione nelle diverse aree del comune &#8211; prosegue l&#8217;assessore Profeti &#8211; e vogliamo riqualificare gli spazi esterni degli edifici scolastici, nell&#8217;ottica dell&#8217;educazione all&#8217;aria aperta&#8221;.<\/p>\n<p><strong>CULTURA E SPORT<\/strong><br \/>\nAnche per la cultura \u00e8 stato un anno molto complicato. &#8220;Il 9 marzo hanno chiuso i battenti i Musei, la biblioteche e gli archivi, un colpo durissimo che improvvisamente ci ha costretto a modificare tutti i nostri piani &#8211; commenta l&#8217;assessore alla cultura Loredano Arzilli -. Siamo riusciti a garantire &#8216;La luna \u00e8 azzurra&#8217; e il cinema sotto le stelle ma abbiamo rinunciato alla stagione al Quaranthana che per l&#8217;occasione ha costruito un&#8217;Arena estiva a San Miniato Basso, a Prima del teatro, all&#8217;Estate di San Martino che compiva 25 anni e che faremo l&#8217;anno prossimo, insieme a eventi dedicati a Dante e Napoleone&#8221;.<\/p>\n<p>Lo sport si \u00e8 reinventato online e ha convertito tutti i progetti didattici in operazioni &#8220;a distanza&#8221;. &#8220;Ho voluto premiare le associazioni del territorio che hanno creato progetti sportivi online, incrementando l&#8217;annuale bando fino a 20mila euro di contributi, ben 7mila euro in pi\u00f9 di quanto stanziato nel 2019 &#8211; spiega l&#8217;assessore Arzilli -. Una scelta non semplice che \u00e8 andata nella direzione di dare un aiuto concreto a chi si \u00e8 rimesso in gioco nonostante gli allenamenti fossero sospesi e gli impianti chiusi. Per il 2021 vogliamo comunque impegnarci in una serie di interventi per rendere idonei e all&#8217;avanguardia i nostri impianti sportivi e stipulare delle convenzioni con le associazioni per la loro gestione&#8221;.<\/p>\n<p><strong>LAVORI PUBBLICI<\/strong><br \/>\nIl lockdown dei mesi primaverili ha fatto slittare molti dei cantieri in programma sul territorio di San Miniato, soprattutto per quanto riguarda le manutenzioni programmate. &#8220;Siamo indietro con i lavori, anche se a fine anno, grazie ad una variazione da 1 milione di euro, abbiamo affidato molti dei lavori rimasti in sospeso &#8211; dichiara l&#8217;assessore ai lavori pubblici Marzia Fattori -. Penso ad esempio al cimitero di San Miniato per cui sono gi\u00e0 stati stanziati 300mila euro, oltre 104mila euro saranno invece destinati alle asfaltature dei tratti a maggiore criticit\u00e0. Due gli interventi importanti gi\u00e0 pronti a partire: il rifacimento dell&#8217;area gioco di piazza Spalletti a Ponte a Egola e il secondo lotto di interventi su via Maremmana a La Serra&#8221;. Prosegue il progetto di efficientamento energetico che interessa diversi tratti stradali di pubblica illuminazione, mentre nel piano di interventi ci sono anche quelli relativi alla difesa del suolo, con l&#8217;ottenimento di due importanti finanziamenti per la frana di via Bagnoli e per quella in localit\u00e0 Baccanella, lungo la via Francigena. &#8220;Per il 2021 abbiamo gi\u00e0 stanziato 80mila euro per la realizzazione di ben due aree di sgambatura per i cani (una per quelli di taglia grande e l&#8217;altra per quelli di taglia piccola), che sorgeranno a Ponte a Egola, vicino al complesso sportivo di Casa Bonello &#8211; prosegue ancora l&#8217;assessore Fattori -. Mentre due sono i progetti importanti che stiamo seguendo da vicino: il primo riguarda il ponte di Isola per il quale il Ministero ci ha da poco assegnato 100mila euro per la progettazione; il secondo \u00e8 quello della scuola &#8216;Collodi&#8217; di Ponte a Elsa, in attesa di finanziamento, ma con buone speranze visto che in graduatoria regionale siamo al quarto posto e quindi con molte probabilit\u00e0 di ottenerlo&#8221;.<\/p>\n<p>&#8220;Tutti questi numeri ci raccontano la storia del nostro anno alle prese con l&#8217;emergenza, un anno difficile, faticoso, che non ha risparmiato nessun settore &#8211; conclude il sindaco -. Nonostante questo stiamo lavorando alla definizione del bilancio di previsione 2021, che contiamo di approvare nei primi mesi del nuovo anno, oltre ai tanti progetti che vi abbiamo illustrato e che danno la dimensione della volont\u00e0 di questa amministrazione, molto vicina a tutti i settori in sofferenza, e attenta a recepire le difficolt\u00e0 e i bisogni che sono subentrati. Superare questo anno non \u00e8 stato semplice e ha richiesto un lavoro di squadra per il quale vorrei ringraziare la mia giunta, gli uffici comunali, le associazioni di Protezione Civile e tutti cittadini che hanno collaborato per aiutarci a gestire al meglio questa emergenza. Auguro a tutti che il 2021 sia l&#8217;anno del rilancio e della svolta per San Miniato e per un territorio che ha dimostrato una grande capacit\u00e0 di sacrificio e di solidariet\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con 603 positivi nell&#8217;ultima settimana del mese di novembre, il Comune di San Miniato ha toccato il picco dell&#8217;emergenza sanitaria, una situazione che, alla fine dell&#8217;anno, ci presenta una serie [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":20601,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-20600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Con 603 positivi nell&#8217;ultima settimana del mese di novembre, il Comune di San Miniato ha toccato il picco dell&#8217;emergenza sanitaria, una situazione che, alla fine dell&#8217;anno, ci presenta una serie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-30T10:30:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza\",\"datePublished\":\"2020-12-30T10:30:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/\"},\"wordCount\":1477,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/\",\"name\":\"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-12-30T10:30:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2020\\\/12\\\/30\\\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/","og_locale":"it_IT","og_type":"article","og_title":"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza - San Miniato","og_description":"Con 603 positivi nell&#8217;ultima settimana del mese di novembre, il Comune di San Miniato ha toccato il picco dell&#8217;emergenza sanitaria, una situazione che, alla fine dell&#8217;anno, ci presenta una serie [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-12-30T10:30:43+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza","datePublished":"2020-12-30T10:30:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/"},"wordCount":1477,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/#primaryimage"},"thumbnailUrl":"","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/","url":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/","name":"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-12-30T10:30:43+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2020\/12\/30\/san-miniato-dal-covid-al-futuro-il-bilancio-di-un-anno-in-emergenza-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"San Miniato, dal Covid al futuro. Il bilancio di un anno in emergenza"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/20600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=20600"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/20600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=20600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=20600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=20600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}