{"id":22187,"date":"2021-01-15T14:41:52","date_gmt":"2021-01-15T13:41:52","guid":{"rendered":"https:\/\/comune.san-miniato.pi.it\/?p=22187"},"modified":"2021-01-15T14:41:52","modified_gmt":"2021-01-15T13:41:52","slug":"casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/","title":{"rendered":"Casa Museo Lotti, prosegue la catalogazione di opere e documenti"},"content":{"rendered":"<div>Pi\u00f9 di\u00a0<b>4mila<\/b>\u00a0documenti tra lettere, carte e appunti. Circa\u00a0<b>10mila<\/b>\u00a0opere tra sculture, pitture e oggettistica di interesse storico-artistico, oltre a\u00a0<b>10mila\u00a0<\/b>pezzi tra volumi e libri rari. E&#8217; questo, a grandi linee, il patrimonio della\u00a0<b>Fondazione Casa Museo Dilvo Lotti<\/b>, di propriet\u00e0 del\u00a0<b>Comune di San Miniato<\/b>, per il quale \u00e8 in corso un complesso lavoro di catalogazione.<\/div>\n<div><\/div>\n<div>&#8220;Abbiamo iniziato nel mese di luglio scorso affidando l&#8217;incarico alla storica dell&#8217;arte Daria Gastone, alla quale contiamo di affiancare molto presto anche un&#8217;altra persona &#8211; spiega il presidente della Fondazione Casa Museo Dilvo Lotti e direttore dei Musei Civici,\u00a0<b>Lorenzo Fatticcioni<\/b>\u00a0-. A lei il compito di catalogare i documenti, la mobilia e l&#8217;oggettistica di interesse storico-artistico, mentre per la parte relativa ai libri, ci avvaliamo della collaborazione con l&#8217;associazione<b>\u00a0Moti Carbonari<\/b>, grazie alla quale abbiamo creato un gruppo di lavoro che coordiner\u00f2 io, dedicato proprio a questa parte. Tutti i materiali saranno schedati, fotografati ed inseriti in due database distinti (uno per i libri e uno per il resto delle opere) che, una volta terminata l&#8217;opera di catalogazione, saranno messi in rete&#8221;.<\/div>\n<div><\/div>\n<div>&#8220;L&#8217;impegno di questa catalogazione riguarda innanzitutto la tutela del patrimonio locale &#8211; spiega la storica dell&#8217;arte\u00a0<b>Daria Gastone<\/b>\u00a0-. Molti dei documenti che sto valutando sono relativi alle numerose iniziative del pittore Lotti, impegnato tutta la vita nella valorizzazione del patrimonio artistico locale, sui quali sono spesso annotati schizzi o disegni a corredo, un archivio nell&#8217;archivio, che ogni volta racconta sempre qualcosa di nuovo&#8221;.<\/div>\n<div><\/div>\n<div>Fino alla conclusione di tutto l&#8217;inventario delle opere e dei numerosi materiali, che pu\u00f2 richiedere da uno a due anni, la Casa-Museo non potr\u00e0 infatti essere aperta al pubblico. &#8220;Nel bilancio 2020 abbiamo stanziato eccezionalmente altri\u00a0<b>10mila euro<\/b>\u00a0per la catalogazione, in modo da poter avere un&#8217;altra persona in affiancamento e sveltire la procedura, arrivando a concludere l&#8217;inventario della propriet\u00e0 gi\u00e0 alla fine dell&#8217;anno &#8211; dichiara l&#8217;assessore alla cultura\u00a0<b>Loredano Arzilli<\/b>\u00a0-. Sappiamo bene che non \u00e8 un lavoro semplice e che \u00e8 fondamentale per poter pensare di organizzare iniziative che, a quel punto, possano far parte di un percorso culturale perfettamente inserito nel contesto cittadino. Trovare queste risorse \u00e8 stato un impegno grande, reso possibile dall&#8217;aver dovuto eliminare molte delle iniziative culturali che ogni anno mettiamo in campo: il Covid ha sacrificato la cultura, e noi abbiamo cercato di darle respiro attivandoci in altri modi. E uno \u00e8 stato proprio quello di destinare le risorse ad un lavoro forse poco evidente all&#8217;esterno, ma estremamente importante per l&#8217;attivit\u00e0 di tutta la nostra Fondazione &#8211; e conclude\u00a0-. Questo \u00e8 un passo importante con cui, come amministrazione, vogliamo far crescere una realt\u00e0 nella quale crediamo e abbiamo investito molto, perch\u00e9 \u00e8 fondamentale per la nostra citt\u00e0. Da qui si parte per dare una vita lunga e piena di attivit\u00e0 alla Casa-Museo Lotti, un luogo magico, un dono a San Miniato, che vogliamo rendere di nuovo visitabile e accessibile&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pi\u00f9 di\u00a04mila\u00a0documenti tra lettere, carte e appunti. Circa\u00a010mila\u00a0opere tra sculture, pitture e oggettistica di interesse storico-artistico, oltre a\u00a010mila\u00a0pezzi tra volumi e libri rari. E&#8217; questo, a grandi linee, il patrimonio [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":22188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-22187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa Museo Lotti, prosegue la catalogazione di opere e documenti - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa Museo Lotti, prosegue la catalogazione di opere e documenti - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Pi\u00f9 di\u00a04mila\u00a0documenti tra lettere, carte e appunti. Circa\u00a010mila\u00a0opere tra sculture, pitture e oggettistica di interesse storico-artistico, oltre a\u00a010mila\u00a0pezzi tra volumi e libri rari. E&#8217; questo, a grandi linee, il patrimonio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T13:41:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Casa Museo Lotti, prosegue la catalogazione di opere e documenti\",\"datePublished\":\"2021-01-15T13:41:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/\"},\"wordCount\":486,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/\",\"name\":\"Casa Museo Lotti, prosegue la catalogazione di opere e documenti - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-01-15T13:41:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/01\\\/15\\\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa Museo Lotti, prosegue la catalogazione di opere e documenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa Museo Lotti, prosegue la catalogazione di opere e documenti - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/","og_locale":"it_IT","og_type":"article","og_title":"Casa Museo Lotti, prosegue la catalogazione di opere e documenti - San Miniato","og_description":"Pi\u00f9 di\u00a04mila\u00a0documenti tra lettere, carte e appunti. Circa\u00a010mila\u00a0opere tra sculture, pitture e oggettistica di interesse storico-artistico, oltre a\u00a010mila\u00a0pezzi tra volumi e libri rari. E&#8217; questo, a grandi linee, il patrimonio [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-01-15T13:41:52+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png","height":600,"width":1200,"type":""}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Casa Museo Lotti, prosegue la catalogazione di opere e documenti","datePublished":"2021-01-15T13:41:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/"},"wordCount":486,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/#primaryimage"},"thumbnailUrl":"","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/","url":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/","name":"Casa Museo Lotti, prosegue la catalogazione di opere e documenti - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-01-15T13:41:52+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/01\/15\/casa-museo-lotti-prosegue-la-catalogazione-di-opere-e-documenti-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Casa Museo Lotti, prosegue la catalogazione di opere e documenti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/22187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=22187"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/22187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=22187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=22187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=22187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}