{"id":23022,"date":"2021-02-10T13:41:53","date_gmt":"2021-02-10T12:41:53","guid":{"rendered":"https:\/\/comune.san-miniato.pi.it\/?p=23022"},"modified":"2021-02-10T13:41:53","modified_gmt":"2021-02-10T12:41:53","slug":"dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/","title":{"rendered":"Dal 15 febbraio riapre lo sportello dell&#8217;Agenzia delle Entrate"},"content":{"rendered":"<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">A partire da luned\u00ec 15 febbraio, lo sportello di San Miniato dell\u2019Ufficio territoriale di Pontedera dell\u2019Agenzia delle Entrate riapre al pubblico. Lo sportello situato in via Ser Ridolfo 3 a San Miniato sar\u00e0 aperto al pubblico il luned\u00ec mattina, con orario 8.30 &#8211; 12.45, e ricever\u00e0 gli utenti esclusivamente su appuntamento<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Per info e contatti guarda il sito dell&#8217;<a href=\"https:\/\/bit.ly\/2Z38Baa\">Agenzia delle Entrate<\/a><\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A partire da luned\u00ec 15 febbraio, lo sportello di San Miniato dell\u2019Ufficio territoriale di Pontedera dell\u2019Agenzia delle Entrate riapre al pubblico. Lo sportello situato in via Ser Ridolfo 3 a [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":23023,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-23022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dal 15 febbraio riapre lo sportello dell&#039;Agenzia delle Entrate - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal 15 febbraio riapre lo sportello dell&#039;Agenzia delle Entrate - San Miniato\" \/>\n<meta property=\"og:description\" content=\"A partire da luned\u00ec 15 febbraio, lo sportello di San Miniato dell\u2019Ufficio territoriale di Pontedera dell\u2019Agenzia delle Entrate riapre al pubblico. Lo sportello situato in via Ser Ridolfo 3 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-10T12:41:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Dal 15 febbraio riapre lo sportello dell&#8217;Agenzia delle Entrate\",\"datePublished\":\"2021-02-10T12:41:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/\"},\"wordCount\":67,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/\",\"name\":\"Dal 15 febbraio riapre lo sportello dell'Agenzia delle Entrate - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-02-10T12:41:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/02\\\/10\\\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal 15 febbraio riapre lo sportello dell&#8217;Agenzia delle Entrate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dal 15 febbraio riapre lo sportello dell'Agenzia delle Entrate - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/","og_locale":"it_IT","og_type":"article","og_title":"Dal 15 febbraio riapre lo sportello dell'Agenzia delle Entrate - San Miniato","og_description":"A partire da luned\u00ec 15 febbraio, lo sportello di San Miniato dell\u2019Ufficio territoriale di Pontedera dell\u2019Agenzia delle Entrate riapre al pubblico. Lo sportello situato in via Ser Ridolfo 3 a [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-02-10T12:41:53+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Dal 15 febbraio riapre lo sportello dell&#8217;Agenzia delle Entrate","datePublished":"2021-02-10T12:41:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/"},"wordCount":67,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/#primaryimage"},"thumbnailUrl":"","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/","url":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/","name":"Dal 15 febbraio riapre lo sportello dell'Agenzia delle Entrate - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-02-10T12:41:53+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/02\/10\/dal-15-febbraio-riapre-lo-sportello-dellagenzia-delle-entrate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Dal 15 febbraio riapre lo sportello dell&#8217;Agenzia delle Entrate"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/23022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=23022"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/23022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=23022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=23022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=23022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}