{"id":24041,"date":"2021-03-29T15:31:57","date_gmt":"2021-03-29T13:31:57","guid":{"rendered":"https:\/\/comune.san-miniato.pi.it\/?p=24041"},"modified":"2021-03-29T15:31:57","modified_gmt":"2021-03-29T13:31:57","slug":"isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/","title":{"rendered":"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso"},"content":{"rendered":"<div><b>&#8220;Se non si rispetteranno le regole sar\u00f2 costretto ad reintrodurre l&#8217;appuntamento&#8221;<\/b><\/div>\n<div><\/div>\n<div>&#8220;I cittadini che si recano all&#8217;isola ecologica di San Miniato Basso devono rispettare le regole e mantenere comportamenti adeguati, altrimenti saremo costretti a reintrodurre il conferimento solo su appuntamento&#8221;. Il sindaco di San Miniato\u00a0<b>Simone Giglioli<\/b>, dopo alcuni episodi di maleducazione che si sono verificati sabato scorso al centro di raccolta comunale, interviene in maniera decisa invitando a mantenere la calma e a rispettare le regole. &#8220;Il sabato \u00e8 il giorno nel quale si registrano il maggior numero di accessi, per questo motivo facciamo sostare una pattuglia davanti all&#8217;ingresso dell&#8217;isola ecologica, in modo da evitare che si creino tensioni tra chi \u00e8 in fila per andare a conferire e anche verso i nostri operatori &#8211; dichiara -. Purtroppo sabato scorso si sono verificati episodi spiacevoli con cittadini che hanno manifestato il loro disappunto in maniera maleducata e irrispettosa sia verso gli agenti di Polizia Municipale, sia verso i dipendenti dell&#8217;isola ecologica, e questo non lo possiamo tollerare. Gli accessi sono rallentati anche dalle norme anti Covid che dobbiamo far rispettare, per questo invito coloro che hanno pochi oggetti da conferire, se\u00a0in quel momento l&#8217;accesso \u00e8 congestionato, ad utilizzare il buon senso e a tornare in un secondo tempo lasciando spazio a chi ha da depositare un carico pi\u00f9 grande &#8211; e conclude\u00a0-. L&#8217;isola ecologica continua a stare regolarmente aperta anche in zona rossa, per questo \u00e8 importante che ci siano comportamenti adeguati: se si verificheranno altri episodi simili sar\u00f2 costretto a reintrodurre il conferimento su appuntamento, in modo da scaglionare gli accessi e ridurre la coda&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Se non si rispetteranno le regole sar\u00f2 costretto ad reintrodurre l&#8217;appuntamento&#8221; &#8220;I cittadini che si recano all&#8217;isola ecologica di San Miniato Basso devono rispettare le regole e mantenere comportamenti adeguati, [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":24042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,13],"tags":[],"class_list":["post-24041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso - San Miniato\" \/>\n<meta property=\"og:description\" content=\"&#8220;Se non si rispetteranno le regole sar\u00f2 costretto ad reintrodurre l&#8217;appuntamento&#8221; &#8220;I cittadini che si recano all&#8217;isola ecologica di San Miniato Basso devono rispettare le regole e mantenere comportamenti adeguati, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-29T13:31:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/ambiente.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso\",\"datePublished\":\"2021-03-29T13:31:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/\"},\"wordCount\":277,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Ambiente\",\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/\",\"name\":\"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-03-29T13:31:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/03\\\/29\\\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/","og_locale":"it_IT","og_type":"article","og_title":"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso - San Miniato","og_description":"&#8220;Se non si rispetteranno le regole sar\u00f2 costretto ad reintrodurre l&#8217;appuntamento&#8221; &#8220;I cittadini che si recano all&#8217;isola ecologica di San Miniato Basso devono rispettare le regole e mantenere comportamenti adeguati, [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-03-29T13:31:57+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/ambiente.png","height":600,"width":1200,"type":""}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso","datePublished":"2021-03-29T13:31:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/"},"wordCount":277,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/#primaryimage"},"thumbnailUrl":"","articleSection":["Ambiente","Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/","url":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/","name":"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-03-29T13:31:57+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/03\/29\/isola-ecologica-il-sindaco-giglioli-invita-a-rispettare-le-regole-di-accesso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Isola ecologica, il sindaco Giglioli invita a rispettare le regole di accesso"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/24041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=24041"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/24041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=24041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=24041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=24041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}