{"id":24840,"date":"2021-05-21T13:59:59","date_gmt":"2021-05-21T11:59:59","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/?p=24840"},"modified":"2021-05-26T14:00:35","modified_gmt":"2021-05-26T12:00:35","slug":"storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/","title":{"rendered":"Storie di donne, sulle orme delle grandi figure femminili di San Miniato"},"content":{"rendered":"<p>Ciclo di appuntamenti organizzato dal Comune di San Miniato, dalla Commissione Pari Opportunit\u00e0 di San Miniato e da La conchiglia di Santiago<\/p>\n<p>Il secondo appuntamento \u00e8 dedicato a ISOLINA PIGNATARI &#8211; L&#8217;OSTETRICA E IL &#8220;BASTARDAIO&#8221;, sabato 5 giugno, ore 16.00, quartiere Scioa, San Miniato.<\/p>\n<p>Interverranno:<br \/>\nElisa Montanelli, Assessore alle Pari Opportunit\u00e0<br \/>\nElise Bianchi, Presidente della Commissione Comunale per le Pari Opportunit\u00e0<br \/>\nAndrea Mancini, Regista e Scrittore<\/p>\n<p>La partecipazione \u00e8 gratuita<br \/>\nLa prenotazione \u00e8 obbligatoria e pu\u00f2 essere effettuata per telefono al n. 0571 406640 o tramite Whatsapp\/Telegram al n. 329 7518568<\/p>\n<p>I posti sono limitati a n. 70 nel rispetto della normativa anti Covid-19<br \/>\nLe richieste saranno accolte in base a giorno e ora di arrivo e seguir\u00e0 conferma.<\/p>\n<p>Il programma completo degli incontri \u00e8 consultabile nella locandina scaricabile sotto.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Ciclo di appuntamenti organizzato dal Comune di San Miniato, dalla Commissione Pari Opportunit\u00e0 di San Miniato e da La conchiglia di Santiago Il secondo appuntamento \u00e8 dedicato a ISOLINA PIGNATARI [&hellip;]<\/p>\n","protected":false},"author":282,"featured_media":24841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-24840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Storie di donne, sulle orme delle grandi figure femminili di San Miniato - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storie di donne, sulle orme delle grandi figure femminili di San Miniato - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Ciclo di appuntamenti organizzato dal Comune di San Miniato, dalla Commissione Pari Opportunit\u00e0 di San Miniato e da La conchiglia di Santiago Il secondo appuntamento \u00e8 dedicato a ISOLINA PIGNATARI [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-21T11:59:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-26T12:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/05\/dido.png\" \/>\n\t<meta property=\"og:image:width\" content=\"442\" \/>\n\t<meta property=\"og:image:height\" content=\"226\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"gestoreyic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestoreyic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/\"},\"author\":{\"name\":\"gestoreyic\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"headline\":\"Storie di donne, sulle orme delle grandi figure femminili di San Miniato\",\"datePublished\":\"2021-05-21T11:59:59+00:00\",\"dateModified\":\"2021-05-26T12:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/05\\\/dido.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/\",\"name\":\"Storie di donne, sulle orme delle grandi figure femminili di San Miniato - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/05\\\/dido.png\",\"datePublished\":\"2021-05-21T11:59:59+00:00\",\"dateModified\":\"2021-05-26T12:00:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/05\\\/dido.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/05\\\/dido.png\",\"width\":442,\"height\":226},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/05\\\/21\\\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Storie di donne, sulle orme delle grandi figure femminili di San Miniato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\",\"name\":\"gestoreyic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"caption\":\"gestoreyic\"},\"description\":\"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/gestoreyic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Storie di donne, sulle orme delle grandi figure femminili di San Miniato - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/","og_locale":"it_IT","og_type":"article","og_title":"Storie di donne, sulle orme delle grandi figure femminili di San Miniato - San Miniato","og_description":"Ciclo di appuntamenti organizzato dal Comune di San Miniato, dalla Commissione Pari Opportunit\u00e0 di San Miniato e da La conchiglia di Santiago Il secondo appuntamento \u00e8 dedicato a ISOLINA PIGNATARI [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-05-21T11:59:59+00:00","article_modified_time":"2021-05-26T12:00:35+00:00","og_image":[{"width":442,"height":226,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/05\/dido.png","type":"image\/png"}],"author":"gestoreyic","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"gestoreyic","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/"},"author":{"name":"gestoreyic","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"headline":"Storie di donne, sulle orme delle grandi figure femminili di San Miniato","datePublished":"2021-05-21T11:59:59+00:00","dateModified":"2021-05-26T12:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/"},"wordCount":132,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/05\/dido.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/","url":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/","name":"Storie di donne, sulle orme delle grandi figure femminili di San Miniato - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/05\/dido.png","datePublished":"2021-05-21T11:59:59+00:00","dateModified":"2021-05-26T12:00:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/05\/dido.png","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/05\/dido.png","width":442,"height":226},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/05\/21\/storie-di-donne-sulle-orme-delle-grandi-figure-femminili-di-san-miniato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Storie di donne, sulle orme delle grandi figure femminili di San Miniato"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196","name":"gestoreyic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","caption":"gestoreyic"},"description":"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it","url":"https:\/\/comunicacity.net\/sanminiato\/author\/gestoreyic\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"13"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/24840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/282"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=24840"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/24840\/revisions"}],"predecessor-version":[{"id":24842,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/24840\/revisions\/24842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/24841"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=24840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=24840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=24840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}