{"id":24990,"date":"2021-09-12T14:00:23","date_gmt":"2021-09-12T12:00:23","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2021\/06\/29\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/"},"modified":"2021-09-13T12:39:40","modified_gmt":"2021-09-13T10:39:40","slug":"san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/","title":{"rendered":"&#8220;Noi &amp; N.&#8221;, fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone"},"content":{"rendered":"<p style=\"text-align: center\"><strong>Giglioli e Arzilli: &#8220;Cos\u00ec vengono ricordate figure che hanno fatto la storia della citt\u00e0&#8221;<\/strong><\/p>\n<p>SAN MINIATO, 29 giugno 2021 &#8211; Ha aperto i battenti la mostra <strong>&#8220;Noi &amp; N. &#8211; Napoleone tra storia e memoria&#8221;<\/strong>, organizzata nelle sale della Fondazione Conservatorio Santa Chiara dal Comune di San Miniato e dalla Fondazione casa del pittore Dilvo Lotti, in collaborazione con quattro entit\u00e0 del Sistema Museale di San Miniato (Musei Civici di San Miniato, Museo Diocesano, Accademia degli Euteleti, Conservatorio di Santa Chiara) e con l&#8217;Archivio storico del Comune di San Miniato. L\u2019esposizione, che rester\u00e0 aperta al pubblico fino al 30 settembre, \u00e8 stata inaugurata il 29 giugno dal sindaco di San Miniato Simone Giglioli, dal presidente della Regione Eugenio Giani, del presidente del consiglio regionale Antonio Mazzeo, dall&#8217;assessore alla cultura Loredano Arzilli, dal professor Luigi Ambrosio presidente della Fondazione Conservatorio Santa Chiara e direttore della Scuola Normale Superiore di Pisa, dal direttore dei Musei Civici e presidente della Fondazione casa del pittore Dilvo Lotti Lorenzo Fatticcioni che, insieme al pittore Luca Macchi e all\u2019archivista Laura Guiducci ne \u00e8 il curatore, e da Francesco Mugnari dell&#8217;associazione Tra i Binari, coordinatore della rievocazione storica, che ha introdotto all\u2019evento in costume del 10 luglio, organizzato anche dal Movimento Shalom, dal Corteo Storico e dalla Pro Loco.<\/p>\n<p style=\"text-align: center\"><strong>Noi &amp; N. &#8211; Napoleone tra storia e memoria<\/strong><\/p>\n<p>L\u2019esposizione \u00e8 un viaggio che ripercorre le tappe della formazione della memoria \u201cspeciale\u201d che lega la citt\u00e0 all&#8217;immaginario napoleonico. E\u2019 stata inaugurata oggi, 29 giugno, giorno dell\u2019anniversario dell\u2019incontro tra il giovane Napoleone, generale in capo dell&#8217;Armata d&#8217;Italia, e il canonico Filippo, suo anziano parente del ramo toscano della famiglia, avvenuto proprio il 29 giugno 1796. Molto di questo immaginario si aggrega intorno ad alcuni oggetti e luoghi divenuti, nel corso di oltre due secoli di rielaborazione culturale, quasi iconici della sua identit\u00e0. Dagli anni \u201980 del secolo scorso le attivit\u00e0 di alcuni artisti e importanti operatori culturali di San Miniato, incentrate sulla figura di Napoleone, hanno contribuito a infittire la trama delle iniziative commemorative e ad arricchire l&#8217;immaginario napoleonico delle loro opere. Tra questi ricoprono particolare rilevanza Dilvo Lotti, che dedica una parte cospicua della sua ultima produzione artistica a Napoleone, Marianella Marianelli con il racconto in plaquette incentrato sull&#8217;incontro del 29 giugno 1796 ed il romanzo storico di ispirazione napoleonica Ipotesi per un fantasma, infine i fratelli Taviani che dedicano al passaggio delle truppe francesi in Toscana diverse scene di Fiorile, uno dei loro film pi\u00f9 intensi. L&#8217;esposizione \u00e8 stata allestita all&#8217;interno del Museo del Conservatorio di Santa Chiara, luogo scelto perch\u00e9 mostra un legame avuto per secoli con la famiglia Buonaparte, oltre alla presenza nel Museo di due importanti testimonianze di questo legame, insieme alla volont\u00e0 di valorizzare un luogo del Sistema Museale ancora poco toccato dai flussi turistici.<\/p>\n<p>&#8220;Il filo rosso dell&#8217;esposizione \u00e8 costituito da una linea del tempo mediante la quale viene messo in evidenza il legame tra storia e memoria \u2013 dichiara il direttore dei Musei Civici Lorenzo Fatticcioni, uno dei curatori della mostra -. Le prime due sezioni, relative alla storia, sono dedicate alle testimonianze della plurisecolare presenza della famiglia Buonaparte a San Miniato e al periodo dell&#8217;occupazione francese della Toscana, mentre le sezioni relative alla memoria mostrano materiali documentari relativi agli studi dell\u2019erudizione locale, aggregata intorno all\u2019Accademia degli Euteleti, alcuni cimeli fortemente evocativi dell\u2019immaginario napoleonico a San Miniato, una scelta dalle opere di Dilvo Lotti dedicate a Napoleone, infine una rassegna di pubblicazioni relative ad iniziative scientifiche e rievocative promosse a San Miniato in tempi recenti&#8221;.<\/p>\n<p>&#8220;Il legame di Napoleone con San Miniato \u00e8 documentato e oramai pienamente riconosciuto &#8211; precisano il sindaco di San Miniato Simone Giglioli e l&#8217;assessore Loredano Arzilli -; volevamo ricordare la sua figura nell&#8217;anniversario dei 200 anni dalla sua morte, con una mostra che, per la prima volta, ci permette di unire in uno stesso luogo molti degli oggetti e delle carte che ci raccontano di Napoleone a San Miniato, un\u2019esposizione che ha, come fulcro centrale, il famoso dipinto di Egisto Sarri gentilmente concesso da Cr\u00e9dit Agricole che ringraziamo. Oltre alla mostra, il 10 luglio faremo anche una rievocazione, dopo quella realizzata da Dilvo Lotti nel 1996, per celebrare i 200 anni dell&#8217;incontro tra Napoleone e lo zio canonico Filippo. L\u2019intenzione era quella di ricordare non solo il generale francese a 200 anni dalla sua morte, ma anche altre figure che hanno reso San Miniato la splendida e rinomata citt\u00e0 che conosciamo oggi: Dilvo Lotti e i fratelli Taviani \u2013 e concludono -. Ringraziamo il Sistema Museale e la Diocesi per aver recepito le nostre istanze, tutte le associazioni e gli Enti cittadini che, con il loro lavoro e il loro prezioso supporto, hanno reso tutto questo possibile, i nostri sponsor per aver capito l\u2019importanza del sostegno ad un progetto cos\u00ec importante e la Regione Toscana, sempre vicina alla nostra Citt\u00e0 e alle iniziative culturali di grande valore&#8221;.<\/p>\n<p>La mostra si avvale dei patrocini di Regione Toscana e Provincia di Pisa, ed \u00e8 stata realizzata grazie al sostegno di: Fondazione Cassa di Risparmio di San Miniato, Cr\u00e9dit Agricole, Azienda Speciale Farmacie, Figli di Guido Lapi spa, Conceria La Scarpa spa, Ghiropelli srl, Organazoto spa, Consorzio Conciatori di Ponte a Egola, Pallets Bertini Group srl, Leather Kem srl, Ausonia srl, Lotti Franco, Gruppo Nuti Ivo spa, Fracopel, Nuova Antilope e Centro Studi Enti Locali.<\/p>\n<p>La mostra sar\u00e0 aperta fino al 30 settembre, con i seguenti orari: dal luned\u00ec al venerd\u00ec 9.00 &#8211; 12.30 solo su appuntamento (tel. 0571\/43050) nei mesi di luglio e settembre; venerd\u00ec 18.00 \u2013 21.00; sabato e domenica 10.00 &#8211; 12.00 e 15.00 \u2013 19.00. Marted\u00ec 29 giugno rester\u00e0 eccezionalmente aperta dalle 19.00 alle 21.30.<\/p>\n<p>Info: tel. 0571.43050 &#8211; 406700, email: cultura@comune.san-miniato.pi.it oppure sistemamuseale@comune.san-miniato.pi.it<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Giglioli e Arzilli: &#8220;Cos\u00ec vengono ricordate figure che hanno fatto la storia della citt\u00e0&#8221; SAN MINIATO, 29 giugno 2021 &#8211; Ha aperto i battenti la mostra &#8220;Noi &amp; N. &#8211; [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":26261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-24990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Noi &amp; N.&quot;, fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Noi &amp; N.&quot;, fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Giglioli e Arzilli: &#8220;Cos\u00ec vengono ricordate figure che hanno fatto la storia della citt\u00e0&#8221; SAN MINIATO, 29 giugno 2021 &#8211; Ha aperto i battenti la mostra &#8220;Noi &amp; N. &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-12T12:00:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-13T10:39:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/mostra_napoleone-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"&#8220;Noi &amp; N.&#8221;, fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone\",\"datePublished\":\"2021-09-12T12:00:23+00:00\",\"dateModified\":\"2021-09-13T10:39:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/\"},\"wordCount\":944,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/09\\\/mostra_napoleone-1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/\",\"name\":\"\\\"Noi &amp; N.\\\", fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/09\\\/mostra_napoleone-1.jpg\",\"datePublished\":\"2021-09-12T12:00:23+00:00\",\"dateModified\":\"2021-09-13T10:39:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/09\\\/mostra_napoleone-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/09\\\/mostra_napoleone-1.jpg\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/12\\\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Noi &amp; N.&#8221;, fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Noi &amp; N.\", fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/","og_locale":"it_IT","og_type":"article","og_title":"\"Noi &amp; N.\", fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone - San Miniato","og_description":"Giglioli e Arzilli: &#8220;Cos\u00ec vengono ricordate figure che hanno fatto la storia della citt\u00e0&#8221; SAN MINIATO, 29 giugno 2021 &#8211; Ha aperto i battenti la mostra &#8220;Noi &amp; N. &#8211; [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-09-12T12:00:23+00:00","article_modified_time":"2021-09-13T10:39:40+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/mostra_napoleone-1.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"&#8220;Noi &amp; N.&#8221;, fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone","datePublished":"2021-09-12T12:00:23+00:00","dateModified":"2021-09-13T10:39:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/"},"wordCount":944,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/mostra_napoleone-1.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/","url":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/","name":"\"Noi &amp; N.\", fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/mostra_napoleone-1.jpg","datePublished":"2021-09-12T12:00:23+00:00","dateModified":"2021-09-13T10:39:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/mostra_napoleone-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/mostra_napoleone-1.jpg","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/12\/san-miniato-inaugurata-la-mostra-per-i-200-anni-dalla-morte-di-napoleone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"&#8220;Noi &amp; N.&#8221;, fino al 30 settembre la mostra per i 200 anni dalla morte di Napoleone"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"25099"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/24990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=24990"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/24990\/revisions"}],"predecessor-version":[{"id":25335,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/24990\/revisions\/25335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/26261"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=24990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=24990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=24990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}