{"id":26309,"date":"2021-09-20T13:01:56","date_gmt":"2021-09-20T11:01:56","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/"},"modified":"2021-09-20T13:01:56","modified_gmt":"2021-09-20T11:01:56","slug":"noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/","title":{"rendered":"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero"},"content":{"rendered":"<div>Proseguono gli incontri collaterali alla mostra <strong>&#8220;Noi &amp; N. &#8211; Napoleone e San Miniato tra Storia e Memoria&#8221;<\/strong>, con temi dedicati alla figura del grande Generale. Gioved\u00ec <b>23 settembre<\/b>, alle 18.30, al Conservatorio di Santa Chiara,\u00a0<b>Pier Giuseppe Leo<\/b>\u00a0terr\u00e0 una conferenza dal titolo\u00a0<b>&#8220;Memorie di un collezionista: mercato e critica dell&#8217;arte italiana dell&#8217;800. L&#8217;acquisizione del dipinto di Egisto Sarri&#8221;<\/b>. Leo, per anni responsabile delle collezioni d&#8217;arte della Fondazione Cassa di Risparmio di San Miniato, racconta della sua esperienza di collezionista all&#8217;interno del mondo del mercato dell&#8217;arte italiana dell&#8217;800 e di come individu\u00f2 il dipinto di Sarri &#8220;Napoleone Bonaparte che visita lo zio canonico a San Miniato al Tedesco&#8221;, proponendone l&#8217;acquisto.<\/div>\n<div><\/div>\n<div>Luned\u00ec\u00a0<b>27 settembre<\/b>, alle 18.30, ancora una volta al Conservatorio di Santa Chiara\u00a0<b>Giulia Perni<\/b>\u00a0terr\u00e0 un incontro dal titolo\u00a0<b>&#8220;Napoleone e la musica. Un itinerario musicale&#8221;<\/b>, proponendo un itinerario musicale sull&#8217;uso che Napoleone fece della musica, intuendo che poteva diventare funzionale all&#8217;affermazione del proprio potere personale. Durante gli anni del suo potere, e anche nei giorni dell&#8217;esilio all&#8217;isola d&#8217;Elba, si circond\u00f2 infatti dei pi\u00f9 importanti e geniali compositori e musicisti del tempo, da Le Sueur a M\u00e9hul, da Paisiello a Cherubini e Spontini. Famosa la dedica a Napoleone, poi violentemente cancellata dal frontespizio, che il geniale Beethoven appose alla sua Terza Sinfonia, l&#8217;Eroica e stupenda la sonata &#8220;Napol\u00e9on&#8221; che Paganini compose per la sola quarta corda del violino, accompagnata dall&#8217;orchestra.<\/div>\n<div><\/div>\n<div>La mostra sar\u00e0 aperta dal luned\u00ec al venerd\u00ec 9.00 \u2013 12.30 solo su appuntamento (tel. 0571\/43050), venerd\u00ec 18.00-21.00, sabato e domenica 10.00-12.00 e 15.00-19.00. Gli incontri sono ad ingresso libero, per partecipare (e per l&#8217;ingresso alla mostra) sar\u00e0 necessario essere in possesso del green pass.<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Proseguono gli incontri collaterali alla mostra &#8220;Noi &amp; N. &#8211; Napoleone e San Miniato tra Storia e Memoria&#8221;, con temi dedicati alla figura del grande Generale. Gioved\u00ec 23 settembre, alle [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":26310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-26309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Proseguono gli incontri collaterali alla mostra &#8220;Noi &amp; N. &#8211; Napoleone e San Miniato tra Storia e Memoria&#8221;, con temi dedicati alla figura del grande Generale. Gioved\u00ec 23 settembre, alle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-20T11:01:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/Noi-N_3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero\",\"datePublished\":\"2021-09-20T11:01:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/\"},\"wordCount\":281,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/09\\\/Noi-N_3.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/\",\"name\":\"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/09\\\/Noi-N_3.jpeg\",\"datePublished\":\"2021-09-20T11:01:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/09\\\/Noi-N_3.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/09\\\/Noi-N_3.jpeg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/09\\\/20\\\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/","og_locale":"it_IT","og_type":"article","og_title":"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero - San Miniato","og_description":"Proseguono gli incontri collaterali alla mostra &#8220;Noi &amp; N. &#8211; Napoleone e San Miniato tra Storia e Memoria&#8221;, con temi dedicati alla figura del grande Generale. Gioved\u00ec 23 settembre, alle [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-09-20T11:01:56+00:00","og_image":[{"width":2016,"height":1512,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/Noi-N_3.jpeg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero","datePublished":"2021-09-20T11:01:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/"},"wordCount":281,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/Noi-N_3.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/","url":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/","name":"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/Noi-N_3.jpeg","datePublished":"2021-09-20T11:01:56+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/Noi-N_3.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/09\/Noi-N_3.jpeg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/09\/20\/noi-n-due-eventi-collaterali-alla-mostra-ingresso-libero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Noi &amp; N., due eventi collaterali alla mostra. Ingresso libero"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"26443"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/26309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=26309"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/26309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/26310"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=26309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=26309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=26309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}