{"id":26666,"date":"2021-10-25T12:25:24","date_gmt":"2021-10-25T10:25:24","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/21\/26666\/"},"modified":"2021-10-28T13:12:35","modified_gmt":"2021-10-28T11:12:35","slug":"26666","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/","title":{"rendered":"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli"},"content":{"rendered":"<div><\/div>\n<div>\n<div>Una giornata di studio per ricordare Marinella Marianelli, una figura che ha lasciato un&#8217;impronta indelebile nel panorama culturale di San Miniato. A cento anni dalla sua nascita (1921-2021), il Comune di San Miniato vuole renderle omaggio con un&#8217;iniziativa che si articoler\u00e0 in diversi momenti, dove le testimonianze degli amici, dei conoscenti e di chi ha lavorato a stretto contatto con lei, saranno la parte pi\u00f9 ampia di questo evento. L&#8217;appuntamento \u00e8\u00a0<b>sabato 30 ottobre, dalle 10.00<\/b>, all&#8217;auditorium dell&#8217;It Cattaneo che, per l&#8217;appunto, porta proprio il suo nome.<\/div>\n<div><\/div>\n<div><i>&#8220;Quando pensiamo ad una figura che ha lasciato un&#8217;impronta indelebile nel tessuto culturale cittadino, la mente va subito a Marinella Marianelli\u00a0<\/i>&#8211; dichiarano il sindaco di San Miniato\u00a0<b>Simone Giglioli<\/b>\u00a0e l&#8217;assessore alla cultura\u00a0<b>Loredano Arzilli<\/b>\u00a0-.<i>\u00a0Con lei San Miniato ha vissuto una stagione prolifica e ha messo le basi per tutte quelle che sono venute, tracciando un solco che ancora oggi stiamo percorrendo.\u00a0Donna di azione e di cultura, da sempre innamorata degli ideali di giustizia e libert\u00e0, ci ha lasciato un&#8217;eredit\u00e0 meravigliosa, tutt&#8217;oggi presente nelle nostre iniziative: dal Centro studi per il Tardo Medioevo a La Luna \u00e8 Azzurra, fino all&#8217;Universit\u00e0 del Tempo Libero, molte delle nostre attivit\u00e0 risentono ancora della sua opera. Per questo a<\/i><i>bbiamo voluto renderle omaggio costruendo una giornata di studi che non vuole essere solo un momento di ricordo e di discussione attorno alla sua produzione letteraria, ma molto di pi\u00f9. Vogliamo che sia l&#8217;occasione per ritrovare molti amici di Marinella, per rivivere attraverso i loro racconti la donna che cos\u00ec tanto ha lasciato a questo territorio e verso la quale siamo ancora cos\u00ec profondamente grati&#8221;.<\/i><\/div>\n<div><\/div>\n<div>L\u2019iniziativa si svolge nel pieno rispetto delle norme anti Covid in vigore. Per accedere sar\u00e0 necessario essere muniti di green pass. Per partecipare \u00e8 obbligatorio prenotarsi scrivendo a\u00a0<a href=\"mailto:prestito@comune.san-miniato.pi.it\" target=\"_blank\" rel=\"noopener\">prestito@comune.san-miniato.pi.it<\/a>\u00a0oppure chiamando il numero 0571 406710.<\/div>\n<\/div>\n<div><\/div>\n<div><strong><br \/>\nIL PROGRAMMA<\/strong><\/div>\n<div>\n<p><strong>Ore 10.00 &#8211; Saluti istituzionali<\/strong><br \/>\n<strong>Alessandro Frosini<\/strong>\u00a0<em>Dirigente scolastico I.T. \u201cC. Cattaneo\u201d<\/em>,\u00a0<strong>Simone Giglioli<\/strong>\u00a0<em>Sindaco di San Miniato<\/em>,\u00a0<strong>Loredano Arzilli<\/strong>\u00a0<em>Assessore alla Cultura<\/em><\/p>\n<p><strong>Ore 10.30 &#8211;\u00a0Relazioni<\/strong><br \/>\n<em>Modera Maria Fancelli<\/em><br \/>\n<strong>Giovanni Cipriani<\/strong>\u00a0&#8211;\u00a0<em>Il progetto educativo di Marinella Marianelli<\/em><br \/>\n<strong>Isabella Gagliardi<\/strong>\u00a0&#8211;\u00a0<em>Il Medioevo moderno<\/em><br \/>\n<strong>Ernestina Pellegrini\u00a0<\/strong>&#8211;\u00a0<em>Pagine di letteratura<\/em><br \/>\n<strong>Giorgio Pizziolo, Rita Micarelli<\/strong>\u00a0&#8211;\u00a0<em>Le piccole citt\u00e0 storiche nella prospettiva odierna<\/em><\/p>\n<p><strong>Ore 12.00 &#8211; Buffet<\/strong><\/p>\n<p><strong>Ore 14.00 &#8211; Testimonianze<\/strong><br \/>\n<strong><em>Giuseppe De Juliis, Giuseppe D\u2019Alloro, Delio Fiordispina, Marzio Gabbanini, Raffaella Grana, Mara Mari, Maria Grazia Messerini,\u00a0Manola Guazzini<\/em><\/strong><\/p>\n<p><em>Lettura di testi poetici di Marinella accompagnati dal commento musicale di Marzio Matteoli<\/em><\/p>\n<p><strong>Ore 16.00 &#8211; Proiezione video<\/strong><br \/>\nPresentazione del promo del docu-film<br \/>\n<strong><em>\u201cMarinella Marianelli, una storia di vita\u201d<\/em><\/strong><br \/>\na cura di Filippo Lotti, regia di Viacheslav Zakharov<\/p>\n<p><strong>Ore 16.30 &#8211; Interventi del pubblico<\/strong><\/p>\n<p><strong>Ore 17.00 &#8211; Conclusioni<\/strong><\/p>\n<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Una giornata di studio per ricordare Marinella Marianelli, una figura che ha lasciato un&#8217;impronta indelebile nel panorama culturale di San Miniato. A cento anni dalla sua nascita (1921-2021), il Comune [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":26799,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-26666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Una giornata di studio per ricordare Marinella Marianelli, una figura che ha lasciato un&#8217;impronta indelebile nel panorama culturale di San Miniato. A cento anni dalla sua nascita (1921-2021), il Comune [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-25T10:25:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-28T11:12:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/10\/Marinella-Marianelli-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli\",\"datePublished\":\"2021-10-25T10:25:24+00:00\",\"dateModified\":\"2021-10-28T11:12:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/\"},\"wordCount\":449,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/10\\\/Marinella-Marianelli-7.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/\",\"name\":\"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/10\\\/Marinella-Marianelli-7.jpg\",\"datePublished\":\"2021-10-25T10:25:24+00:00\",\"dateModified\":\"2021-10-28T11:12:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/10\\\/Marinella-Marianelli-7.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/10\\\/Marinella-Marianelli-7.jpg\",\"width\":1748,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2021\\\/10\\\/25\\\/26666\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/","og_locale":"it_IT","og_type":"article","og_title":"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli - San Miniato","og_description":"Una giornata di studio per ricordare Marinella Marianelli, una figura che ha lasciato un&#8217;impronta indelebile nel panorama culturale di San Miniato. A cento anni dalla sua nascita (1921-2021), il Comune [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-10-25T10:25:24+00:00","article_modified_time":"2021-10-28T11:12:35+00:00","og_image":[{"width":1748,"height":1240,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/10\/Marinella-Marianelli-7.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli","datePublished":"2021-10-25T10:25:24+00:00","dateModified":"2021-10-28T11:12:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/"},"wordCount":449,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/10\/Marinella-Marianelli-7.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/","url":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/","name":"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/10\/Marinella-Marianelli-7.jpg","datePublished":"2021-10-25T10:25:24+00:00","dateModified":"2021-10-28T11:12:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/10\/Marinella-Marianelli-7.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/10\/Marinella-Marianelli-7.jpg","width":1748,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2021\/10\/25\/26666\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"30 ottobre, una giornata di studio dedicata alla figura di Marinella Marianelli"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"26757"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/26666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=26666"}],"version-history":[{"count":5,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/26666\/revisions"}],"predecessor-version":[{"id":26762,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/26666\/revisions\/26762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/26799"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=26666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=26666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=26666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}