{"id":28085,"date":"2022-02-25T12:04:33","date_gmt":"2022-02-25T11:04:33","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/?p=28085"},"modified":"2022-02-25T12:06:17","modified_gmt":"2022-02-25T11:06:17","slug":"vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/","title":{"rendered":"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino &#8220;adottati&#8221; dai Moti Carbonari"},"content":{"rendered":"<div><b>Siglata la convenzione con il Comune. Giglioli e Fattori: &#8220;Cos\u00ec possiamo prenderci cura di questi luoghi&#8221;<\/b><\/div>\n<div><\/div>\n<div>\n<div>Per cinque anni l&#8217;associazione <b>Moti Carbonari &#8211; Ritrovare la strada<\/b> avr\u00e0 la gestione del <b>vicolo carbonaio<\/b>, della <b>chiesa di San Rocco<\/b> in Piazza Bonaparte e del <b>vicolo del Bellorino<\/b>. Sottoscritta la convenzione con il <b>Comune<\/b>, grazie alla quale, fino al <b>31 gennaio 2026<\/b>, l&#8217;associazione sanminiatese, grazie ad un rimborso spese di <b>12.500 euro<\/b> complessivi, dovr\u00e0 occuparsi della manutenzione di questi spazi.<\/div>\n<div>&#8220;<i>I Moti Carbonari sono attivi da diversi anni sul nostro territorio e, da tempo, avevano iniziato a prendersi cura del vicolo carbonaio, il tratto compreso tra via Carducci, via Gargozzi e l&#8217;Auditorium di Cr\u00e9dit Agricole, facendo un ottimo lavoro <\/i>&#8211; spiegano il sindaco <b>Simone Giglioli<\/b> e l&#8217;assessore ai lavori pubblici <b>Marzia Fattori<\/b> &#8211;<i>. Da qui abbiamo pensato di costruire una vera e propria convenzione che potesse dare all&#8217;associazione garanzie e interventi di manutenzione specifici, aggiungendo a questo spazio anche la Chiesa di San Rocco e il vicolo del Bellorino,\u00a0indicandone le necessit\u00e0 e le mansioni specifiche&#8221;.<\/i><\/div>\n<div>Per quanto riguarda il vicolo carbonaio, l&#8217;associazione dovr\u00e0 occuparsi dello sfalcio dell&#8217;erba, del taglio e dalla potatura di piccole piante per garantire la percorribilit\u00e0 del tratto, della messa a dimora di nuove piante, oltre al contenimento di fenomeni corrosivi superficiali e alla pulizia del percorso; per la Chiesa di San Rocco sar\u00e0 invece loro compito garantire le aperture e le chiusure, le pulizie e le fioriere di fronte alla facciata, mentre per il vicolo del Bellorino l&#8217;impegno riguarda essenzialmente la manutenzione del percorso e il riordino delle situazioni critiche.<\/div>\n<div><i>&#8220;La convenzione sancisce un rapporto con l&#8217;amministrazione che va avanti ormai da 11 anni <\/i>&#8211; dichiara <b>Alessio Guardini<\/b>, presidente associazione Moti Carbonari &#8211; Ritrovare la strada &#8211;<i>. Siamo molto contenti di aver sottoscritto questo documento perch\u00e9 ci d\u00e0 molti vantaggi: per prima cosa un aiuto economico sulle spese che ci sono per la manutenzione e poi perch\u00e9, oltre al vicolo, tiene in considerazione anche altre aree\u00a0su cui, negli anni, abbiamo fatto progetti, come ad esempio il tratto che congiunge Gargozzi al Bellorino<\/i>\u00a0e\u00a0<i>la chiesa di San Rocco, aprendoci a nuove prospettive e dandoci la possibilit\u00e0 di sviluppare tutti quei progetti che avevamo nel cassetto e che adesso possono prendere finalmente vita&#8221;.<\/i><\/div>\n<div><i>&#8220;La collaborazione dell&#8217;amministrazione con le associazioni del comune \u00e8 un aspetto che acquista sempre maggiore importanza <\/i>&#8211; dichiarano i due amministratori -.<i> La manutenzione degli spazi \u00e8 complessa e difficile, ma grazie all&#8217;aiuto delle realt\u00e0 del nostro territorio, associazioni che da tanti anni collaborano con noi per il bene del territorio, \u00e8 possibile strutturare accordi e convenzioni come questa, finalizzati alla creazione di progetti a beneficio di luoghi utilizzati da tutta la comunit\u00e0 e dai visitatori. Si tratta infatti di luoghi ad alto richiamo turistico, sui quali \u00e8 fondamentale costruire progetti che ne sviluppino l&#8217;attrattiva e l&#8217;interesse, e grazie a queste collaborazioni \u00e8 possibile andare proprio in questa direzione&#8221;.\u00a0\u00a0<\/i><\/div>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Siglata la convenzione con il Comune. Giglioli e Fattori: &#8220;Cos\u00ec possiamo prenderci cura di questi luoghi&#8221; Per cinque anni l&#8217;associazione Moti Carbonari &#8211; Ritrovare la strada avr\u00e0 la gestione del [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":28092,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-28085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino &quot;adottati&quot; dai Moti Carbonari - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino &quot;adottati&quot; dai Moti Carbonari - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Siglata la convenzione con il Comune. Giglioli e Fattori: &#8220;Cos\u00ec possiamo prenderci cura di questi luoghi&#8221; Per cinque anni l&#8217;associazione Moti Carbonari &#8211; Ritrovare la strada avr\u00e0 la gestione del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-25T11:04:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-25T11:06:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2022\/02\/vicolo-carbonaio_1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino &#8220;adottati&#8221; dai Moti Carbonari\",\"datePublished\":\"2022-02-25T11:04:33+00:00\",\"dateModified\":\"2022-02-25T11:06:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/\"},\"wordCount\":490,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2022\\\/02\\\/vicolo-carbonaio_1-2.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/\",\"name\":\"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino \\\"adottati\\\" dai Moti Carbonari - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2022\\\/02\\\/vicolo-carbonaio_1-2.jpg\",\"datePublished\":\"2022-02-25T11:04:33+00:00\",\"dateModified\":\"2022-02-25T11:06:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2022\\\/02\\\/vicolo-carbonaio_1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2022\\\/02\\\/vicolo-carbonaio_1-2.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2022\\\/02\\\/25\\\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino &#8220;adottati&#8221; dai Moti Carbonari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino \"adottati\" dai Moti Carbonari - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/","og_locale":"it_IT","og_type":"article","og_title":"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino \"adottati\" dai Moti Carbonari - San Miniato","og_description":"Siglata la convenzione con il Comune. Giglioli e Fattori: &#8220;Cos\u00ec possiamo prenderci cura di questi luoghi&#8221; Per cinque anni l&#8217;associazione Moti Carbonari &#8211; Ritrovare la strada avr\u00e0 la gestione del [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-02-25T11:04:33+00:00","article_modified_time":"2022-02-25T11:06:17+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2022\/02\/vicolo-carbonaio_1-2.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino &#8220;adottati&#8221; dai Moti Carbonari","datePublished":"2022-02-25T11:04:33+00:00","dateModified":"2022-02-25T11:06:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/"},"wordCount":490,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2022\/02\/vicolo-carbonaio_1-2.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/","url":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/","name":"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino \"adottati\" dai Moti Carbonari - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2022\/02\/vicolo-carbonaio_1-2.jpg","datePublished":"2022-02-25T11:04:33+00:00","dateModified":"2022-02-25T11:06:17+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2022\/02\/vicolo-carbonaio_1-2.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2022\/02\/vicolo-carbonaio_1-2.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2022\/02\/25\/vicolo-carbonaio-chiesa-di-san-rocco-e-vicolo-del-bellorino-adottati-dai-moti-carbonari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Vicolo carbonaio, chiesa di San Rocco e vicolo del Bellorino &#8220;adottati&#8221; dai Moti Carbonari"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"27991"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/28085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=28085"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/28085\/revisions"}],"predecessor-version":[{"id":28091,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/28085\/revisions\/28091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/28092"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=28085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=28085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=28085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}