{"id":32441,"date":"2023-08-25T10:00:15","date_gmt":"2023-08-25T08:00:15","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/"},"modified":"2023-09-06T11:44:30","modified_gmt":"2023-09-06T09:44:30","slug":"geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2023\/08\/25\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/","title":{"rendered":"Geofor, aperto lo sportello ambiente a San Miniato Basso"},"content":{"rendered":"<p>Riapre lo sportello ambiente nel Comune di San Miniato. La sede di <strong>via Aldo Moro, al numero 133 A<\/strong>, dal <strong>18 luglio<\/strong> sar\u00e0 aperta per due giorni la settimana, ovvero il <strong>marted\u00ec<\/strong> (dalle 8.30 alle 12.30) e il <strong>venerd\u00ec<\/strong> (dalle 14 alle 18).<br \/>\nTra le attivit\u00e0 possibili presso lo sportello ambiente, oltre a fungere anche da punto informativo per tutto ci\u00f2 che concerne le attivit\u00e0 di Geofor, vi \u00e8 anche la possibilit\u00e0 di ritirare, per le utenze domestiche e quelle non domestiche, il materiale necessario alla raccolta differenziata (ad esempio, sacchi e mastelli).<br \/>\nPotranno essere ritirati anche i sacchi PSA (per raccolta pannolini e pannoloni)e il modulo per l&#8217;attivazione annuale di questo servizio.<br \/>\n<em>&#8220;Esprimo soddisfazione per questa attivit\u00e0 mirata a risolvere le esigenze della cittadinanza<\/em> &#8211; ha commentato il sindaco di San Miniato, <strong>Simone Giglioli<\/strong> -. I<em>l punto informativo \u00e8 un servizio pensato assieme a Geofor e utile per i cittadini. Ma pu\u00f2 essere considerato anche un valido strumento di crescita ulteriore per l&#8217;azienda, in quanto tramite il confronto con l&#8217;utenza si possono ricevere quegli input mirati al costante miglioramento sul territorio. Abbiamo inoltre pensato anche ad un&#8217;alternativa per quei cittadini che risiedono in zone non vicine allo sportello&#8221;.<\/em><br \/>\nDal 17 al 22 luglio, infatti, verr\u00e0 attivata un&#8217;unit\u00e0 mobile per la distribuzione del materiale utile nella raccolta differenziata e nel porta a porta, in alcune zone, secondo il seguente calendario:<\/p>\n<ul>\n<li>Stibbio, 17 luglio, 8.30 &#8211; 12.30, loc. Stibbio via San Bartolomeo &#8211; Piazza lato Chiesa<\/li>\n<li>Balconevisi, 18 luglio, 8.30 &#8211; 12.30, loc. Balconevisi Piazza 1 Maggio<\/li>\n<li>Cusignano Marzana\/Parrino Corniano Moriolo, 19 luglio, 8.30 &#8211; 12.30, loc. Marzana &#8211; parcheggio della Chiesa via Bassa<\/li>\n<li>Corazzano\/Collebrunacchi, 20 luglio, 8.30 &#8211; 12.30, loc. Corazzano c\/o Parcheggio Campo Sportivo in piazza Tonelli<\/li>\n<li>Calenzano\/San Quintino\/Canneto, 21 luglio, 8.30 &#8211; 12.30, loc. Calenzano via Ferrucci parcheggio delle ex casine<\/li>\n<li>La Serra\/Montebicchieri\/Bucciano, 22 luglio, 8.30 &#8211; 12.30 e 14.00 &#8211; 18.00, loc. La Serra Piazza Don Milani lato parcheggio opposto al fontanello<\/li>\n<\/ul>\n<p>Per ritirare il kit \u00e8 necessario presentarsi muniti di tessera sanitaria o bolletta Tari. Si pu\u00f2 ritirare il kit annuale oppure il necessario ed \u00e8 possibile ritirare il kit anche per altri utenti, purch\u00e9 muniti della loro tessera sanitaria o della loro bolletta Tari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riapre lo sportello ambiente nel Comune di San Miniato. La sede di via Aldo Moro, al numero 133 A, dal 18 luglio sar\u00e0 aperta per due giorni la settimana, ovvero [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":32763,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-32441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geofor, aperto lo sportello ambiente a San Miniato Basso - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geofor, aperto lo sportello ambiente a San Miniato Basso - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Riapre lo sportello ambiente nel Comune di San Miniato. La sede di via Aldo Moro, al numero 133 A, dal 18 luglio sar\u00e0 aperta per due giorni la settimana, ovvero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-25T08:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-06T09:44:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2023\/07\/kit_differenziata.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Geofor, aperto lo sportello ambiente a San Miniato Basso\",\"datePublished\":\"2023-08-25T08:00:15+00:00\",\"dateModified\":\"2023-09-06T09:44:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/\"},\"wordCount\":353,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2023\\\/09\\\/kit_differenziata.png\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/\",\"name\":\"Geofor, aperto lo sportello ambiente a San Miniato Basso - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2023\\\/09\\\/kit_differenziata.png\",\"datePublished\":\"2023-08-25T08:00:15+00:00\",\"dateModified\":\"2023-09-06T09:44:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2023\\\/09\\\/kit_differenziata.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2023\\\/09\\\/kit_differenziata.png\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2023\\\/07\\\/13\\\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geofor, il 18 luglio riapre lo sportello ambiente a San Miniato Basso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geofor, aperto lo sportello ambiente a San Miniato Basso - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/","og_locale":"it_IT","og_type":"article","og_title":"Geofor, aperto lo sportello ambiente a San Miniato Basso - San Miniato","og_description":"Riapre lo sportello ambiente nel Comune di San Miniato. La sede di via Aldo Moro, al numero 133 A, dal 18 luglio sar\u00e0 aperta per due giorni la settimana, ovvero [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-08-25T08:00:15+00:00","article_modified_time":"2023-09-06T09:44:30+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2023\/07\/kit_differenziata.png","type":"image\/png"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Geofor, aperto lo sportello ambiente a San Miniato Basso","datePublished":"2023-08-25T08:00:15+00:00","dateModified":"2023-09-06T09:44:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/"},"wordCount":353,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2023\/09\/kit_differenziata.png","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/","url":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/","name":"Geofor, aperto lo sportello ambiente a San Miniato Basso - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2023\/09\/kit_differenziata.png","datePublished":"2023-08-25T08:00:15+00:00","dateModified":"2023-09-06T09:44:30+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2023\/09\/kit_differenziata.png","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2023\/09\/kit_differenziata.png","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2023\/07\/13\/geofor-il-18-luglio-riapre-lo-sportello-ambiente-a-san-miniato-basso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Geofor, il 18 luglio riapre lo sportello ambiente a San Miniato Basso"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"31981"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/32441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=32441"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/32441\/revisions"}],"predecessor-version":[{"id":32762,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/32441\/revisions\/32762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/32763"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=32441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=32441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=32441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}