{"id":33943,"date":"2024-01-18T12:43:00","date_gmt":"2024-01-18T11:43:00","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/"},"modified":"2024-01-19T11:40:47","modified_gmt":"2024-01-19T10:40:47","slug":"21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/18\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/","title":{"rendered":"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali"},"content":{"rendered":"<p>Domenica 21 gennaio, in concomitanza con il Mercatale \u2013 Mercato dei prodotti di San Miniato, si svolger\u00e0 la tradizionale benedizione degli animali, organizzata dalla Fondazione San Miniato Promozione in collaborazione con Pro Loco San Miniato, CCN San Miniato e Mercatale San Miniato \ud83d\udc15\ud83d\udc10\ud83d\udc08 \ud83d\udc0e\ud83e\udd94\ud83d\udc04\ud83e\udd86\ud83d\udc01<\/p>\n<p>Una giuria speciale di bambini e bambine sceglier\u00e0 il podio nominando i tre animali pi\u00f9 simpatici.<\/p>\n<p>Seguir\u00e0 una merenda offerta dal Mercatale di San Miniato.<\/p>\n<p>&nbsp;<\/p>\n<p>Programma:<\/p>\n<p>Ore 8:30 \u2013 13:30<br \/>\n<em>Loggiati San Domenico<br \/>\n<\/em><strong>Mercatale di San Miniato<\/strong><\/p>\n<p>Ore 10:30<br \/>\n<em>Piazza Dante Alighieri<br \/>\n<\/em><strong>Benedizione degli animali<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Vi invitiamo a partecipare numerosi, insieme al vostro animale da compagnia!<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Domenica 21 gennaio, in concomitanza con il Mercatale \u2013 Mercato dei prodotti di San Miniato, si svolger\u00e0 la tradizionale benedizione degli animali, organizzata dalla Fondazione San Miniato Promozione in collaborazione [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":34022,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-33943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Domenica 21 gennaio, in concomitanza con il Mercatale \u2013 Mercato dei prodotti di San Miniato, si svolger\u00e0 la tradizionale benedizione degli animali, organizzata dalla Fondazione San Miniato Promozione in collaborazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-18T11:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T10:40:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/01\/benedizione-degli-animali-3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali\",\"datePublished\":\"2024-01-18T11:43:00+00:00\",\"dateModified\":\"2024-01-19T10:40:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/\"},\"wordCount\":105,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/01\\\/benedizione-degli-animali-3-6.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/\",\"name\":\"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/01\\\/benedizione-degli-animali-3-6.jpg\",\"datePublished\":\"2024-01-18T11:43:00+00:00\",\"dateModified\":\"2024-01-19T10:40:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/01\\\/benedizione-degli-animali-3-6.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/01\\\/benedizione-degli-animali-3-6.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/01\\\/02\\\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/","og_locale":"it_IT","og_type":"article","og_title":"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali - San Miniato","og_description":"Domenica 21 gennaio, in concomitanza con il Mercatale \u2013 Mercato dei prodotti di San Miniato, si svolger\u00e0 la tradizionale benedizione degli animali, organizzata dalla Fondazione San Miniato Promozione in collaborazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-01-18T11:43:00+00:00","article_modified_time":"2024-01-19T10:40:47+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/01\/benedizione-degli-animali-3-1.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali","datePublished":"2024-01-18T11:43:00+00:00","dateModified":"2024-01-19T10:40:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/"},"wordCount":105,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/01\/benedizione-degli-animali-3-6.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/","name":"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/01\/benedizione-degli-animali-3-6.jpg","datePublished":"2024-01-18T11:43:00+00:00","dateModified":"2024-01-19T10:40:47+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/01\/benedizione-degli-animali-3-6.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/01\/benedizione-degli-animali-3-6.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/01\/02\/21-gennaio-doppio-appuntamento-con-il-mercatale-e-la-benedizione-degli-animali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"21 gennaio, doppio appuntamento con il Mercatale e la Benedizione degli animali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"33421"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/33943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=33943"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/33943\/revisions"}],"predecessor-version":[{"id":34021,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/33943\/revisions\/34021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/34022"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=33943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=33943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=33943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}