{"id":34221,"date":"2024-02-27T11:30:03","date_gmt":"2024-02-27T10:30:03","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/"},"modified":"2024-02-27T11:40:58","modified_gmt":"2024-02-27T10:40:58","slug":"9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/","title":{"rendered":"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese"},"content":{"rendered":"<p><strong>Sabato 9 marzo 2024, alle 10.30<\/strong>, nella Sala piccola della Casa Culturale (via Pizzigoni, San Miniato Basso), si svolger\u00e0 la terza edizione di <b><i>&#8220;Una scuola a colori&#8221;<\/i><\/b>, il premio in memoria del\u00a0<b>Dott. Marco\u00a0Pugliese<\/b>, rivolto alle classi delle scuole primarie dell\u2019<b>Istituto Comprensivo \u201cFranco Sacchetti\u201d<\/b>\u00a0e dell\u2019<b>Istituto Comprensivo \u201cMichelangelo Buonarroti\u201d,\u00a0<\/b>organizzato dal\u00a0<b>Comune di San Miniato<\/b>\u00a0con il sostegno dell&#8217;<b>Azienda Speciale Farmacie<\/b>.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sabato 9 marzo 2024, alle 10.30, nella Sala piccola della Casa Culturale (via Pizzigoni, San Miniato Basso), si svolger\u00e0 la terza edizione di &#8220;Una scuola a colori&#8221;, il premio in [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":34224,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-34221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Sabato 9 marzo 2024, alle 10.30, nella Sala piccola della Casa Culturale (via Pizzigoni, San Miniato Basso), si svolger\u00e0 la terza edizione di &#8220;Una scuola a colori&#8221;, il premio in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-27T10:30:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-27T10:40:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/02\/Una-scuola-a-colori-III-edizione-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese\",\"datePublished\":\"2024-02-27T10:30:03+00:00\",\"dateModified\":\"2024-02-27T10:40:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/\"},\"wordCount\":73,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/02\\\/Una-scuola-a-colori-III-edizione-1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/\",\"name\":\"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/02\\\/Una-scuola-a-colori-III-edizione-1.jpg\",\"datePublished\":\"2024-02-27T10:30:03+00:00\",\"dateModified\":\"2024-02-27T10:40:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/02\\\/Una-scuola-a-colori-III-edizione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/02\\\/Una-scuola-a-colori-III-edizione-1.jpg\",\"width\":1748,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/02\\\/27\\\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/","og_locale":"it_IT","og_type":"article","og_title":"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese - San Miniato","og_description":"Sabato 9 marzo 2024, alle 10.30, nella Sala piccola della Casa Culturale (via Pizzigoni, San Miniato Basso), si svolger\u00e0 la terza edizione di &#8220;Una scuola a colori&#8221;, il premio in [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-02-27T10:30:03+00:00","article_modified_time":"2024-02-27T10:40:58+00:00","og_image":[{"width":1748,"height":1240,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/02\/Una-scuola-a-colori-III-edizione-1.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese","datePublished":"2024-02-27T10:30:03+00:00","dateModified":"2024-02-27T10:40:58+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/"},"wordCount":73,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/02\/Una-scuola-a-colori-III-edizione-1.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/","name":"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/02\/Una-scuola-a-colori-III-edizione-1.jpg","datePublished":"2024-02-27T10:30:03+00:00","dateModified":"2024-02-27T10:40:58+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/02\/Una-scuola-a-colori-III-edizione-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/02\/Una-scuola-a-colori-III-edizione-1.jpg","width":1748,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/02\/27\/9-marzo-la-terza-edizione-del-premio-in-memoria-del-pediatra-marco-pugliese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"9 marzo, la terza edizione del premio in memoria del pediatra Marco Pugliese"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"33794"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/34221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=34221"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/34221\/revisions"}],"predecessor-version":[{"id":34223,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/34221\/revisions\/34223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/34224"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=34221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=34221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=34221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}