{"id":34282,"date":"2024-03-07T13:12:35","date_gmt":"2024-03-07T12:12:35","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/"},"modified":"2024-03-07T13:16:52","modified_gmt":"2024-03-07T12:16:52","slug":"la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/","title":{"rendered":"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024"},"content":{"rendered":"<p>In allegato il programma degli eventi organizzati dalle associazioni del territorio in collaborazione con il Comune di San Miniato e la Commissione per le Pari Opportunit\u00e0, in occasione della <em>Giornata Internazionale della Donna<\/em>, 8 marzo 2024.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>In allegato il programma degli eventi organizzati dalle associazioni del territorio in collaborazione con il Comune di San Miniato e la Commissione per le Pari Opportunit\u00e0, in occasione della Giornata [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":34296,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-34282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024 - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024 - San Miniato\" \/>\n<meta property=\"og:description\" content=\"In allegato il programma degli eventi organizzati dalle associazioni del territorio in collaborazione con il Comune di San Miniato e la Commissione per le Pari Opportunit\u00e0, in occasione della Giornata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T12:12:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:16:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/03\/8-marzo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024\",\"datePublished\":\"2024-03-07T12:12:35+00:00\",\"dateModified\":\"2024-03-07T12:16:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/\"},\"wordCount\":47,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/03\\\/8-marzo.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/\",\"name\":\"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024 - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/03\\\/8-marzo.png\",\"datePublished\":\"2024-03-07T12:12:35+00:00\",\"dateModified\":\"2024-03-07T12:16:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/03\\\/8-marzo.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/03\\\/8-marzo.png\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/03\\\/07\\\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024 - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024 - San Miniato","og_description":"In allegato il programma degli eventi organizzati dalle associazioni del territorio in collaborazione con il Comune di San Miniato e la Commissione per le Pari Opportunit\u00e0, in occasione della Giornata [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-03-07T12:12:35+00:00","article_modified_time":"2024-03-07T12:16:52+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/03\/8-marzo.png","type":"image\/png"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024","datePublished":"2024-03-07T12:12:35+00:00","dateModified":"2024-03-07T12:16:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/"},"wordCount":47,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/03\/8-marzo.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/","name":"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024 - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/03\/8-marzo.png","datePublished":"2024-03-07T12:12:35+00:00","dateModified":"2024-03-07T12:16:52+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/03\/8-marzo.png","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/03\/8-marzo.png","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/03\/07\/la-primavera-delle-donne-cartellone-di-iniziative-per-la-giornata-internazionale-della-donna-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"\u201cLa Primavera delle donne\u201d. Cartellone di iniziative per la Giornata Internazionale della Donna 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"33854"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/34282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=34282"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/34282\/revisions"}],"predecessor-version":[{"id":34286,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/34282\/revisions\/34286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/34296"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=34282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=34282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=34282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}