{"id":34794,"date":"2024-05-07T13:33:23","date_gmt":"2024-05-07T11:33:23","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/"},"modified":"2024-05-07T13:33:23","modified_gmt":"2024-05-07T11:33:23","slug":"sportivo-dellanno-una-dodicesima-edizione-da-record","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/","title":{"rendered":"Sportivo dell&#8217;anno, una dodicesima edizione da record"},"content":{"rendered":"<div>Grande successo per la dodicesima edizione dello <b>\u201cSportivo dell\u2019anno\u201d<\/b>, la manifestazione organizzata dal <b>Comune di San Miniato<\/b> in collaborazione con la <b>Consulta dello sport<\/b> e l\u2019associazione <b>Sport &amp; Solidariet\u00e0<\/b>. In un Auditorium Cr\u00e9dit-Agricole gremito, sono stati consegnati quaranta riconoscimenti per un totale di oltre cento premiati fra atleti, atlete, societ\u00e0 sportive, volontari, volontarie e dirigenti che, nel corso del 2023, si sono particolarmente distinti. Testimonial della serata sono stati: <b>Stefano Mei<\/b> presidente FIDAL, <b>Alessio Piscini<\/b> consigliere FIDAL, <b>Andy Diaz Hernandez<\/b> triplista, <b>Fabrizio Donato<\/b> triplista campione olimpionico e<b> Alessandro Santangelo<\/b> mezzofondista. Al centro della serata lo sport in tutte le sue forme, con premi e riconoscimenti anche verso coloro che operano in questo mondo e con un&#8217;attenzione particolare agli atleti e alle atlete disabili.<\/div>\n<div><\/div>\n<div>Di seguito l\u2019elenco dei premiati suddivisi per categorie:<\/div>\n<div><b>Squadre della Citt\u00e0 di San Miniato:<\/b> Ciclismo San Miniato\/Santa Croce asd cat. giovanissimi, Folgore San Miniato Under 18 maschile, Etrusca Basket San Miniato Under 19 gold, Adc Polisportiva Rosselli e Atletica La Rocca categoria Esordienti.<\/div>\n<div><b>Squadre non del Comune di San Miniato ma con atleti di San Miniato:<\/b> Calciando Insieme.<\/div>\n<div><b>Atleti e associazioni sportive di San Miniato:<\/b> Associazione Dojo Kintsugi asd (Tommaso Accardi, Mirko Attanasio, Gianni Benassi, Mirco Chiappara, Leonardo Cipollini, Sergio Conti, Sofia Cubattoli, Matteo Del Guerra, Davide Di Domenico, Riccardo Di Domenico, Greta Di Miele, Olivia Gregori, Alberto Guadagnino, Lea Ortenzi e Damiano Rovini; Gruppo pattinaggio asd (Olga Poli, Alessandro Peccianti, Filippo D&#8217;alloro, Noemi Bonsignore); Tennis Club San Miniato (Sofia Gagliardi, Edoardo Sensi, Guido Giraldi e Vittoria Pierini) e Atletica La Rocca &#8220;Luigi Ocone&#8221; (Carlotta Profumo e Francesco Masini).<\/div>\n<div><b>Atleti di San Miniato che militano in societ\u00e0 sportive fuori dal Comune di San Miniato:<\/b>\u00a0Asd Aquateam (Martina Alfei, Stefania Gemignani e Lorenzo Vannucci), Associazione Il Cigno Blu Fucecchio (Alice Marrucci, Francesca Carduccio, Gemma Lelli, Eva Masoni, Sara Gentili, Clizia Giani, Ambra Ciampalini, Anna Ermelani), Volleyro&#8217; Roma (Sara Mori) e Associazione asd Empoli Swarm Dodgeball (Annunziata Ferrulli), Asd Roller Club Luna Rossa Santa Maria a Monte (Elena Daddi, Giulia Lo Re, Elisa Campani, Giulia Aiello, Anna Gazzarrini, Roberta Cantini, Matilda Lami, Greta Bacchi, Viola Baglioni, Ginevra Mantelli, Sofia Fornino, Jessica Sofia\u00a0Mazzucca,\u00a0Giorgia Tognetti, Azzurra Taddei, Adele Matteoli, Costanza Scappini e Noemi Giorgetti), Scuola Danza Style Academy 2.0 di Monsummano Terme (Noemi Frosini e Jennifer Frosini), Calcio per tutti onlus (Dario Orlandini), Polisportiva Stella Rossa (Aurora Bolzan, Francesca Ciampalini, Giada Profeti, Valentina Paterno), Asd Rockonda Rafting &#8211; Garfagnana Rafting (Chiara Corsi).<\/div>\n<div><b>Categoria dirigenti, allenatori e volontari delle associazioni sportive del Comune di San Miniato:<\/b> Asd giovanile San Miniato Basso Calcio (Pierpaolo Veracini), Romaiano Calcio (Luca Fattori).<\/div>\n<div><b>Sport e solidariet\u00e0:<\/b> Etrusca Basket San Miniato e Associazione Abbracciami (Sabina Marmeggi, Tommaso Cino, Emy Tecce, Olga Gasparri, Alberto Parrini, Francesca De Rosa, Marco Ermelani, Alessio Priami, Luce Brazzo, Jenny Narcisi).<\/div>\n<div><b>Sport e territorio:<\/b> Ciclismo San Miniato\/Santa Croce asd evento sportivo &#8220;Pasqualando\u00a0&#8211; edizione 2023&#8221;.<\/div>\n<div><b>Ambasciatori dello sport sanminiatese:<\/b>\u00a0Circolo\u00a0Velico Antignano (Elena Sofia Urti).<\/div>\n<div><b>Sport e scuola:<\/b> Azienda Speciale Farmacie (Andrea Gronchi, Luigi\u00a0Giglioli e Emanuela Biancalani).<\/div>\n<div><b>Premio speciale alla carriera:<\/b> Moreno Gazzarrini.<\/div>\n<div><b>Premio speciale &#8220;Giuseppe Cerone&#8221;:<\/b> Aquateam asd (Letizia Matteoli).<\/div>\n<div><\/div>\n<div>Si ringraziano Cr\u00e9dit-Agricole e Fondazione CRSM per la concessione dell\u2019Auditorium, il fotografo Francesco Sgherri, l\u2019azienda Rosi di Lepri Alessio per il supporto tecnico, la Misericordia di San Miniato per il supporto alla sicurezza, l\u2019associazione Sport &amp; solidariet\u00e0, la Guardia di Finanza, tramite le Fiamme Gialle, che ha permesso agli ospiti di essere presenti alla serata, la Consulta dello sport e gli uffici comunali.<\/div>\n<div><\/div>\n<div>A questo <strong><a href=\"https:\/\/comune.san-miniato.pi.it\/sportivo-dellanno-guarda-tutte-le-foto-della-cerimonia-si-premiazione\/\">link<\/a><\/strong> tutte le foto della serata.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Grande successo per la dodicesima edizione dello \u201cSportivo dell\u2019anno\u201d, la manifestazione organizzata dal Comune di San Miniato in collaborazione con la Consulta dello sport e l\u2019associazione Sport &amp; Solidariet\u00e0. In [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":34795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-34794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sportivo dell&#039;anno, una dodicesima edizione da record - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sportivo dell&#039;anno, una dodicesima edizione da record - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Grande successo per la dodicesima edizione dello \u201cSportivo dell\u2019anno\u201d, la manifestazione organizzata dal Comune di San Miniato in collaborazione con la Consulta dello sport e l\u2019associazione Sport &amp; Solidariet\u00e0. In [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T11:33:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/05\/Sport24_060524_0041.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Sportivo dell&#8217;anno, una dodicesima edizione da record\",\"datePublished\":\"2024-05-07T11:33:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/\"},\"wordCount\":593,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/05\\\/Sport24_060524_0041.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/\",\"name\":\"Sportivo dell'anno, una dodicesima edizione da record - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/05\\\/Sport24_060524_0041.jpg\",\"datePublished\":\"2024-05-07T11:33:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/05\\\/Sport24_060524_0041.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/05\\\/Sport24_060524_0041.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/05\\\/07\\\/sportivo-dellanno-una-dodicesima-edizione-da-record\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sportivo dell&#8217;anno, una dodicesima edizione da record\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sportivo dell'anno, una dodicesima edizione da record - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/","og_locale":"it_IT","og_type":"article","og_title":"Sportivo dell'anno, una dodicesima edizione da record - San Miniato","og_description":"Grande successo per la dodicesima edizione dello \u201cSportivo dell\u2019anno\u201d, la manifestazione organizzata dal Comune di San Miniato in collaborazione con la Consulta dello sport e l\u2019associazione Sport &amp; Solidariet\u00e0. In [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-05-07T11:33:23+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/05\/Sport24_060524_0041.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Sportivo dell&#8217;anno, una dodicesima edizione da record","datePublished":"2024-05-07T11:33:23+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/"},"wordCount":593,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/05\/Sport24_060524_0041.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/","name":"Sportivo dell'anno, una dodicesima edizione da record - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/05\/Sport24_060524_0041.jpg","datePublished":"2024-05-07T11:33:23+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/05\/Sport24_060524_0041.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/05\/Sport24_060524_0041.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/05\/07\/sportivo-dellanno-una-dodicesima-edizione-da-record\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Sportivo dell&#8217;anno, una dodicesima edizione da record"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"34267"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/34794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=34794"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/34794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/34795"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=34794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=34794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=34794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}