{"id":35160,"date":"2024-06-28T13:12:40","date_gmt":"2024-06-28T11:12:40","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/?p=35160"},"modified":"2024-07-02T12:28:53","modified_gmt":"2024-07-02T10:28:53","slug":"elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/","title":{"rendered":"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029"},"content":{"rendered":"<p><strong>Sabato 5 ottobre<\/strong> dalle ore 9 alle 19 e <strong>domenica 6 ottobre 2024<\/strong> dalle ore 9 alle 13 si svolgeranno le operazioni di voto per il rinnovo degli <strong>organi dei Consorzi di bonifica regionali<\/strong>, ai sensi della L.R. 79\/2012 art. 11 c. 5 e della Delibera della Giunta Regionale n. 1394 del 10\/12\/2018.<\/p>\n<p>Per il Comune di San Miniato saranno allestiti due seggi elettorali: uno a <strong>Ponte a Egola<\/strong> presso la sede del Consorzio 4 Basso Valdarno in via Curtatone e Montanara n. 49\/c ed uno a <strong>San Miniato<\/strong> al piano terra del Palazzo Comunale.<\/p>\n<p>Maggiori informazioni sulle modalit\u00e0 di voto sono reperibili sui siti <a href=\"http:\/\/www.bassovaldarno.it\" target=\"_blank\" rel=\"noopener\">www.bassovaldarno.it<\/a> e <a href=\"http:\/\/www.bonificalvoto.toscana.it\" target=\"_blank\" rel=\"noopener\">www.bonificalvoto.toscana.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 5 ottobre dalle ore 9 alle 19 e domenica 6 ottobre 2024 dalle ore 9 alle 13 si svolgeranno le operazioni di voto per il rinnovo degli organi dei [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-35160","post","type-post","status-publish","format-standard","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029 - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029 - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Sabato 5 ottobre dalle ore 9 alle 19 e domenica 6 ottobre 2024 dalle ore 9 alle 13 si svolgeranno le operazioni di voto per il rinnovo degli organi dei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-28T11:12:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T10:28:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/ambiente.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/06\\\/28\\\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/06\\\/28\\\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029\",\"datePublished\":\"2024-06-28T11:12:40+00:00\",\"dateModified\":\"2024-07-02T10:28:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/06\\\/28\\\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\\\/\"},\"wordCount\":112,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/06\\\/28\\\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/06\\\/28\\\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\\\/\",\"name\":\"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029 - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"datePublished\":\"2024-06-28T11:12:40+00:00\",\"dateModified\":\"2024-07-02T10:28:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/06\\\/28\\\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/06\\\/28\\\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/06\\\/28\\\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029 - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029 - San Miniato","og_description":"Sabato 5 ottobre dalle ore 9 alle 19 e domenica 6 ottobre 2024 dalle ore 9 alle 13 si svolgeranno le operazioni di voto per il rinnovo degli organi dei [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-06-28T11:12:40+00:00","article_modified_time":"2024-07-02T10:28:53+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/ambiente.png","height":600,"width":1200,"type":""}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029","datePublished":"2024-06-28T11:12:40+00:00","dateModified":"2024-07-02T10:28:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/"},"wordCount":112,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/","name":"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029 - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"datePublished":"2024-06-28T11:12:40+00:00","dateModified":"2024-07-02T10:28:53+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/06\/28\/elezioni-per-rinnovo-organi-consorzio-di-bonifica-per-il-quinquennio-2024-2029\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Elezioni per rinnovo organi Consorzio di Bonifica per il quinquennio 2024-2029"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"34511"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/35160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=35160"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/35160\/revisions"}],"predecessor-version":[{"id":35199,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/35160\/revisions\/35199"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=35160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=35160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=35160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}