{"id":35387,"date":"2024-08-08T09:22:58","date_gmt":"2024-08-08T07:22:58","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/"},"modified":"2024-08-13T13:04:41","modified_gmt":"2024-08-13T11:04:41","slug":"tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/","title":{"rendered":"Tesserini venatori 2024\/2025, da luned\u00ec 12 agosto al via la consegna"},"content":{"rendered":"<div>ll servizio\u00a0di Polizia Municipale informa che da luned\u00ec <b>12 agosto<\/b> 2024 inizier\u00e0 la consegna dei tesserini venatori per la stagione di caccia 2024-2025. I cittadini interessati potranno recarsi al <b>Comando<\/b> in piazza XX Settembre, 22 a San Miniato, dal luned\u00ec al sabato dalle 9.00 alle 12.00, previo appuntamento da prenotare telefonicamente (0571.406406), presentando i seguenti documenti:<\/div>\n<ul>\n<li>tesserino venatorio della stagione precedente oppure ricevuta di avvenuta restituzione. Se il cacciatore ha smarrito il tesserino dell\u2019anno precedente deve presentare denuncia di smarrimento in originale o copia conforme;<\/li>\n<li>licenza di porto di fucile per uso caccia in corso di validit\u00e0 (validit\u00e0 anni 5 dalla data del rilascio);<\/li>\n<li>attestazione del pagamento della ATC di residenza venatoria valida per la nuova stagione venatoria;<\/li>\n<li>attestazione del pagamento tassa di concessione governativa;<\/li>\n<li>attestazione del pagamento tassa provinciale;<\/li>\n<li>allegato alla licenza di caccia.<\/li>\n<\/ul>\n<p>Si ricorda che la Regione Toscana ha creato <b>TosCaccia<\/b> un\u2019applicazione per smartphone pensata per sostituire l\u2019attuale tesserino venatorio cartaceo. Si ricorda altres\u00ec che dalla stagione venatoria 2022-2023 \u00e8 obbligatorio l&#8217;utilizzo della app per poter effettuare attivit\u00e0 venatoria in apertura anticipata della caccia e per il prelievo delle specie in deroga (piccione e tortora dal collare) come da deliberazioni della Giunta Regionale.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.regione.toscana.it\/-\/applicazione-toscaccia-specifiche-per-l-utilizzo-del-tesserino-venatorio-digitale\">Maggiori informazioni per scaricare l&#8217;app TosCaccia<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>ll servizio\u00a0di Polizia Municipale informa che da luned\u00ec 12 agosto 2024 inizier\u00e0 la consegna dei tesserini venatori per la stagione di caccia 2024-2025. I cittadini interessati potranno recarsi al Comando [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":35429,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-35387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tesserini venatori 2024\/2025, da luned\u00ec 12 agosto al via la consegna - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tesserini venatori 2024\/2025, da luned\u00ec 12 agosto al via la consegna - San Miniato\" \/>\n<meta property=\"og:description\" content=\"ll servizio\u00a0di Polizia Municipale informa che da luned\u00ec 12 agosto 2024 inizier\u00e0 la consegna dei tesserini venatori per la stagione di caccia 2024-2025. I cittadini interessati potranno recarsi al Comando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-08T07:22:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-13T11:04:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/08\/tesserini_caccia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Tesserini venatori 2024\\\/2025, da luned\u00ec 12 agosto al via la consegna\",\"datePublished\":\"2024-08-08T07:22:58+00:00\",\"dateModified\":\"2024-08-13T11:04:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/\"},\"wordCount\":207,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/08\\\/tesserini_caccia-3.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/\",\"name\":\"Tesserini venatori 2024\\\/2025, da luned\u00ec 12 agosto al via la consegna - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/08\\\/tesserini_caccia-3.jpg\",\"datePublished\":\"2024-08-08T07:22:58+00:00\",\"dateModified\":\"2024-08-13T11:04:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/08\\\/tesserini_caccia-3.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/08\\\/tesserini_caccia-3.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/08\\\/08\\\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tesserini venatori 2024\\\/2025, da luned\u00ec 12 agosto al via la consegna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tesserini venatori 2024\/2025, da luned\u00ec 12 agosto al via la consegna - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/","og_locale":"it_IT","og_type":"article","og_title":"Tesserini venatori 2024\/2025, da luned\u00ec 12 agosto al via la consegna - San Miniato","og_description":"ll servizio\u00a0di Polizia Municipale informa che da luned\u00ec 12 agosto 2024 inizier\u00e0 la consegna dei tesserini venatori per la stagione di caccia 2024-2025. I cittadini interessati potranno recarsi al Comando [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-08-08T07:22:58+00:00","article_modified_time":"2024-08-13T11:04:41+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/08\/tesserini_caccia.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Tesserini venatori 2024\/2025, da luned\u00ec 12 agosto al via la consegna","datePublished":"2024-08-08T07:22:58+00:00","dateModified":"2024-08-13T11:04:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/"},"wordCount":207,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/08\/tesserini_caccia-3.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/","name":"Tesserini venatori 2024\/2025, da luned\u00ec 12 agosto al via la consegna - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/08\/tesserini_caccia-3.jpg","datePublished":"2024-08-08T07:22:58+00:00","dateModified":"2024-08-13T11:04:41+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/08\/tesserini_caccia-3.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/08\/tesserini_caccia-3.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/08\/08\/tesserini-venatori-2024-2025-da-lunedi-12-agosto-al-via-la-consegna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Tesserini venatori 2024\/2025, da luned\u00ec 12 agosto al via la consegna"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"34735"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/35387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=35387"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/35387\/revisions"}],"predecessor-version":[{"id":35406,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/35387\/revisions\/35406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/35429"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=35387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=35387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=35387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}