{"id":36190,"date":"2024-11-12T12:48:41","date_gmt":"2024-11-12T11:48:41","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/"},"modified":"2024-11-12T12:48:41","modified_gmt":"2024-11-12T11:48:41","slug":"bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/","title":{"rendered":"Bosco didattico di UniCoop alla scuola primaria &#8220;Giusti&#8221; di La Scala"},"content":{"rendered":"<div>Al via, per il quarto anno, il progetto dei\u00a0<b>boschi didattici\u00a0<\/b>realizzati da\u00a0<b>Unicoop Firenze<\/b>\u00a0nell&#8217;ambito delle\u00a0<b>proposte educative 2024\/2025 per le scuole toscane<\/b>. Il progetto ha fatto tappa questa mattina presso la\u00a0<b>scuola primaria G. Giusti\u00a0<\/b>di\u00a0<b>San Miniato\u00a0<\/b>(PI)<b>\u00a0<\/b>con la piantagione del bosco didattico di circa 30 piante messe a dimora nel giardino dell&#8217;istituto: all\u2019iniziativa di questa mattina erano presenti i bambini e gli insegnanti della scuola primaria,\u00a0<b>Simone Giglioli<\/b>, Sindaco di San Miniato,\u00a0<b>Andrea Fubini<\/b>, Dirigente scolstico dell&#8217;Istituto Comprensivo Sacchetti di San Miniato, e\u00a0<b>Angela Bagagli<\/b>, presidente della sezione soci Coop Valdarno Inferiore.<\/div>\n<div><\/div>\n<div>Dedicate tematiche attuali ed urgenti come ambiente, solidariet\u00e0, cultura e benessere, le proposte educative Unicoop Firenze propongono anche quest\u2019anno il progetto dei\u00a0<b>boschi didattici<\/b>\u00a0realizzati nelle\u00a0<b>scuole toscane<\/b>, in collaborazione con il\u00a0<b>Comune<\/b>\u00a0e la\u00a0<b>locale sezione soci Coop<\/b>, per trasformare l\u2019area verde intorno alla scuola in un\u00a0<b>laboratorio di biodiversit\u00e0<\/b>: dopo la piantagione di questa mattina, il percorso vedr\u00e0 interagire i bambini della scuola con il bosco, con l&#8217;obiettivo di sviluppare una sensibilit\u00e0 sul tema ambientale e di accompagnare la crescita con attivit\u00e0 didattiche e ricreative sviluppate dentro questo nuovo spazio verde.<\/div>\n<div><\/div>\n<div>\n<div><b>Simone Giglioli, Sindaco del Comune San Miniato<\/b><\/div>\n<div><i>\u00abSiamo\u00a0felici\u00a0che questo importante progetto di Unicoop Firenze faccia tappa a San Miniato, e speriamo che possa proseguire anche in altre scuole del nostro territorio. E\u2019 importante\u00a0che uno spazio del giardino\u00a0<\/i>diventi<i>\u00a0un luogo dove gli studenti e le studentesse possano partecipare alla piantumazione, farsi carico della cura e della crescita delle piante, sotto la guida degli insegnanti, nell\u2019ottica di un percorso virtuoso utile per coltivare la bellezza e il rispetto dell\u2019ambiente che ci circonda\u00bb.<\/i><\/div>\n<div><\/div>\n<div><b>Tommaso Perrulli, responsabile proposte educative Unicoop Firenze<\/b><\/div>\n<div><i>\u00abPer il quarto anno riparte il progetto dei boschi didattici che, in queste settimane, ci vede impegnati nelle scuole toscane dove sta prendendo il via la piantagione di nuovi boschi, piccole riserve di biodiversit\u00e0 che arricchiscono la singola scuola e tutta la comunit\u00e0. Il progetto dei boschi didattici mette al centro la valorizzazione degli spazi all&#8217;aperto attraverso un modello molto efficace di co-progettazione con le scuole, le pubbliche amministrazioni e le nostre sezioni soci. In ogni bosco didattico mette radici una nuova comunit\u00e0 di alberi e, intorno a questi, una nuova comunit\u00e0 di persone: partecipare a questo percorso significa mettere i semi di nuove relazioni, fra le piante, fra le persone e fra l\u2019uomo e la natura, con l\u2019auspicio che questa esperienza sia un seme che germoglia nella loro vita da adulti<\/i>\u00bb.<\/div>\n<div><b>Angela Bagagli, presidente della sezione soci Coop Valdarno Inferiore<\/b><\/div>\n<div>\u00ab<i>Siamo molto felici di partire con il progetto educativo del bosco didattico alla scuola<\/i><i>primaria<\/i><i>Giusti: insieme agli alunni e agli insegnanti abbiamo inaugurato questa nuova zona verde che, piano piano, si svilupper\u00e0 e crescer\u00e0 con i ragazzi, accompagnandoli nel loro percorso scolastico. Durante la mattinata abbiamo visto l&#8217;entusiasmo e la curiosit\u00e0 degli alunni, pronti a prendersi cura di questo nuovo \u201ccompagno di giochi\u201d. L&#8217;obiettivo \u00e8 che, in questo modo, i pi\u00f9 piccoli possano toccare con mano le tematiche ambientali, in un momento in cui la crisi climatica \u00e8 la vera emergenza. Ringraziamo la scuola e il Comune con cui collaboriamo per portare sul territorio i temi dell&#8217;educazione ambientale<\/i>\u00bb.<\/div>\n<\/div>\n<div>\n<div><\/div>\n<div><b>I numeri del Bosco didattico<\/b><\/div>\n<div>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nel triennio 2021 \u2013 2024,\u00a0<b>58 boschi didattici<\/b>\u00a0realizzati e in fase di realizzazione (10 nel 2024, 16 nel 2023, 16 nel 2022, 16 nel 2021) in\u00a0<b>31\u00a0Comuni\u00a0<\/b>coinvolti<\/div>\n<div>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<b>1.500 piante\u00a0<\/b>forestali piantate<\/div>\n<div>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 circa\u00a0<b>1.500\u00a0mq<\/b>\u00a0di bosco piantato<\/div>\n<div>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 oltre\u00a0<b>320\u00a0classi<\/b>\u00a0delle\u00a0<b>scuole primarie<\/b>\u00a0coinvolte per un totale di circa\u00a0<b>8mila\u00a0bambine e bambini\u00a0<\/b>attivi nel progetto<\/div>\n<div>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 dieci ore di proposta educativa\/laboratorio che gli alunni di ogni classe hanno passato nella progettazione, piantumazione e cura del bosco didattico,<\/div>\n<div>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 per un totale di<b>\u00a0300\u00a0ore di progetto<\/b>\u00a0nel 2024 e di\u00a0<b>3500 ore<\/b>\u00a0a livello complessivo, nei quattro anni di progetto<\/div>\n<div>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 coinvolte le\u00a0<b>sette\u00a0province<\/b>\u00a0<b>toscane<\/b>\u00a0dove opera Unicoop Firenze<\/div>\n<div>\n<b>Descrizione proposta educativa &#8211; Il bosco didattico<\/b><\/div>\n<div>Scoprire il\u00a0<b>mondo della natura<\/b>\u00a0creando un boschetto nel giardino della scuola: un\u2019esperienza di\u00a0<b>educazione all\u2019aperto\u00a0<\/b>dove bambini e bambine possano sperimentare ritmi, tempi e segreti della natura, crescendo insieme e prendendosi cura l\u2019uno dell\u2019altro. Durante questo percorso ci sar\u00e0 un coinvolgimento diretto in attivit\u00e0 sensoriali, di ricerca, condivisione, scoperta e riflessione in piccolo gruppo. Questa esperienza \u00e8 pensata per sviluppare\u00a0<b>affetto<\/b>,\u00a0<b>cura<\/b>\u00a0e\u00a0<b>rispetto<\/b>\u00a0per la natura e per la comunit\u00e0. Il progetto permetter\u00e0 di far acquisire consapevolezza delle trasformazioni stagionali e del concetto di tempo in natura; allenarsi alla cura delle nuove piante anche attraverso un\u2019esperienza di cooperazione tra pari con un maggior ascolto e rispetto dell\u2019altro e delle sue necessit\u00e0; imparare ad ascoltare\u00a0<b>la lingua della Natura<\/b>, a vedere le\u00a0<b>relazioni<\/b>\u00a0tra i diversi organismi e a prepararsi a costruire una conoscenza sistemica.<\/div>\n<div><\/div>\n<div><b>Scheda: come si compone il bosco didattico<\/b><\/div>\n<div>Chiamato anche\u00a0<i>foresta giardino<\/i>, il Bosco didattico \u00e8 una\u00a0<b>coltivazione multifunzione<\/b>\u00a0in cui trovano collocazione alberi di prima grandezza, piante da frutto, erbe medicinali, ortaggi e tanto altro, in sinergia con le piante spontanee e gli animali. Gli\u00a0<b>alberi da frutto<\/b>\u00a0sono al piano superiore, mentre al di sotto ci sono\u00a0<b>arbusti di bacche commestibili<\/b>,\u00a0<b>piante perenni<\/b>\u00a0e\u00a0<b>annuali<\/b>. Insieme creano relazioni per formare un\u00a0<b>ecosistema<\/b>\u00a0in grado di ottenere elevate produzioni di cibo con meno manutenzione. II modello \u00e8 composto da un modulo di\u00a0<b>25 mq<\/b>, di 5 m x 5 m, da localizzare in base alle presenze arboree e arbustive.<\/div>\n<div>Fra le specie individuate per la piantagione del bosco, il\u00a0<b>tiglio<\/b>, che, in autunno \u2013 inverno, garantisce una pacciamatura naturale in quanto le sue foglie, degradandosi, apportano azoto al terreno. I diversi\u00a0<b>arbusti da bacca<\/b>\u00a0senza spine negli anni permetteranno la creazione di passaggi, cunicoli, percorsi in cui i bambini si immergeranno letteralmente nella foresta, oltre ad altre piante come melograno, corbezzolo, nocciolo, sambuco, ma anche mirto, rosa canina, alloro, timo serpillo, santoreggia e ginepro.<\/div>\n<div><\/div>\n<div><b>Info\u00a0<\/b><u><a id=\"m_-6410630035928673595OWA014fa891-31b4-1663-cbd7-3528b6fadc02\" href=\"http:\/\/cittadinanzaconsapevole.it\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/cittadinanzaconsapevole.it\/&amp;source=gmail&amp;ust=1731493435715000&amp;usg=AOvVaw2_6z-oQttGtIHBZnxpd4qB\">http:\/\/cittadinanzaconsapevole.it\/<\/a><\/u><\/div>\n<\/div>\n<div><\/div>\n<div><em>Fonte Ufficio Stampa UniCoop Firenze<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Al via, per il quarto anno, il progetto dei\u00a0boschi didattici\u00a0realizzati da\u00a0Unicoop Firenze\u00a0nell&#8217;ambito delle\u00a0proposte educative 2024\/2025 per le scuole toscane. Il progetto ha fatto tappa questa mattina presso la\u00a0scuola primaria G. [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":36191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-36190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bosco didattico di UniCoop alla scuola primaria &quot;Giusti&quot; di La Scala - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bosco didattico di UniCoop alla scuola primaria &quot;Giusti&quot; di La Scala - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Al via, per il quarto anno, il progetto dei\u00a0boschi didattici\u00a0realizzati da\u00a0Unicoop Firenze\u00a0nell&#8217;ambito delle\u00a0proposte educative 2024\/2025 per le scuole toscane. Il progetto ha fatto tappa questa mattina presso la\u00a0scuola primaria G. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-12T11:48:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Unicoop-Firenze-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Bosco didattico di UniCoop alla scuola primaria &#8220;Giusti&#8221; di La Scala\",\"datePublished\":\"2024-11-12T11:48:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/\"},\"wordCount\":978,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/Unicoop-Firenze-4.jpeg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/\",\"name\":\"Bosco didattico di UniCoop alla scuola primaria \\\"Giusti\\\" di La Scala - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/Unicoop-Firenze-4.jpeg\",\"datePublished\":\"2024-11-12T11:48:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/Unicoop-Firenze-4.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/Unicoop-Firenze-4.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/12\\\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bosco didattico di UniCoop alla scuola primaria &#8220;Giusti&#8221; di La Scala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bosco didattico di UniCoop alla scuola primaria \"Giusti\" di La Scala - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/","og_locale":"it_IT","og_type":"article","og_title":"Bosco didattico di UniCoop alla scuola primaria \"Giusti\" di La Scala - San Miniato","og_description":"Al via, per il quarto anno, il progetto dei\u00a0boschi didattici\u00a0realizzati da\u00a0Unicoop Firenze\u00a0nell&#8217;ambito delle\u00a0proposte educative 2024\/2025 per le scuole toscane. Il progetto ha fatto tappa questa mattina presso la\u00a0scuola primaria G. [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-11-12T11:48:41+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Unicoop-Firenze-4.jpeg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Bosco didattico di UniCoop alla scuola primaria &#8220;Giusti&#8221; di La Scala","datePublished":"2024-11-12T11:48:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/"},"wordCount":978,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Unicoop-Firenze-4.jpeg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/","name":"Bosco didattico di UniCoop alla scuola primaria \"Giusti\" di La Scala - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Unicoop-Firenze-4.jpeg","datePublished":"2024-11-12T11:48:41+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Unicoop-Firenze-4.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Unicoop-Firenze-4.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/12\/bosco-didattico-di-unicoop-alla-scuola-primaria-giusti-di-la-scala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Bosco didattico di UniCoop alla scuola primaria &#8220;Giusti&#8221; di La Scala"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"35329"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=36190"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/36191"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=36190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=36190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=36190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}