{"id":36223,"date":"2024-11-27T09:00:41","date_gmt":"2024-11-27T08:00:41","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/"},"modified":"2024-11-27T09:02:28","modified_gmt":"2024-11-27T08:02:28","slug":"dario-voltolini-a-san-miniato-per-presentare-invernale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/27\/dario-voltolini-a-san-miniato-per-presentare-invernale\/","title":{"rendered":"Il 29 novembre Dario Voltolini a San Miniato per presentare &#8220;Invernale&#8221;"},"content":{"rendered":"<div>\u00c8 la letteratura a dare il via. <b>Dario Voltolini<\/b>, secondo classificato del Premio Strega 2024, apre un fine settimana speciale per San Miniato. Conversa sul suo libro <i>\u201cInvernale\u201d<\/i>, pubblicato dalla Nave di Teseo, con lo scrittore <b>Roberto Ippolito<\/b> nell\u2019ex frantoio della Biblioteca Mario Luzi, nei Loggiati di San Domenico (ingresso libero) alle <b>18<\/b> di venerd\u00ec <b>29 novembre<\/b>, vigilia del weekend finale della 53^ Mostra Mercato del tartufo bianco. All\u2019evento, promosso dal <b>Comune di San Miniato<\/b>, intervengono il sindaco <b>Simone Giglioli<\/b> e l\u2019assessore alla cultura <b>Matteo Squicciarini<\/b>.<\/div>\n<p>San Miniato in festa con il suo pregiato e ricercato prodotto del territorio accoglie dunque Voltolini autore di uno dei libri che caratterizzano l\u2019ultimo anno e la sua carriera.\u00a0Con la partecipazione del gruppo di lettura della Biblioteca, Roberto Ippolito (suo ultimo libro <i>\u201cDelitto Neruda\u201d<\/i>, Chiarelettere, e giurato del Premio Strega) guida alla conoscenza delle pagine di \u201cInvernale\u201d, della sua scrittura tagliente e della narrazione emotiva. Con una descrizione minuziosa Dario Voltolini fa entrare sin dalla prima riga del romanzo nel mercato torinese di Porta Palazzo \u201cpreso d\u2018assalto da una massa di persone\u201d. Protagonista \u00e8 il padre Gino: il padre macellaio. Che spacca gli animali, che adopera i coltelli, divide le vertebre, prende le viscere, ricava bistecche e fettine. Tutto tecnicamente perfetto.<\/p>\n<p>Ma il coltello caler\u00e0 su un dito. La ferita sar\u00e0 grave, con la spossatezza e il dramma della malattia. \u201cInvernale\u201d, cos\u00ec tanto apprezzato al Premio Strega, racconta il macellaio Gino a quaranta anni dalla morte. \u00c8 una \u201cpadre-biografia\u201d lo definisce Voltolini che ha visto arrivare il momento giusto per tirare fuori i ricordi del Voltolini giovane, per rendere omaggio al genitore, parlare delle ferite di entrambi e mettere a fuoco il loro rapporto e quello dell\u2019uomo con la natura. La morte arriv\u00f2 nel 1982, l\u2019anno della vittoria italiana ai mondiali di calcio. In particolare con un grande mito come Omar S\u00edvori, il calcio \u00e8 presente in questo romanzo proposto alla vigilia del Mostra del tartufo bianco di San Miniato.<\/p>\n<p>Ingresso libero, fino ad esaurimento posti. Per informazioni: 0571 406710 &#8211; prestito@comune.san-miniato.pi.it<\/p>\n<p><b><i>Dario Voltolini<\/i><\/b> &#8211; <i>Autore di racconti, romanzi, radiodrammi, testi di canzoni e libretti per il teatro musicale. Ha appena inaugurato la collana di narrazioni sullo sport \u201cI Colibr\u00ec\u201d di Baldini+Castoldi con &#8220;Dagli undici metri&#8221;. \u00c8 docente presso la Holden Academy. Cura la collana di narrativa italiana Pennisole per Hopeful-monster. Fra i suoi libri \u201cUna intuizione metropolitana\u201d, \u201cRincorse\u201d e \u201cForme d\u2019onda\u201d. Ha pubblicato \u201cI confini di Torino\u201d, ritratto della sua citt\u00e0. E ancora: \u201cSotto i cieli d\u2019Italia\u201d con Giulio Mozzi, \u201cLe scimmie sono inavvertitamente uscite dalla gabbia\u201d, \u201cForav\u00eca\u201d, \u201cPacific Palisades\u201d, \u201cSedici passeggiate con Kuma\u201d e \u201cImaginations\u201d. Con La nave di Teseo \u00e8 uscito \u201cIl Giardino degli Aranci\u201d.<\/i><\/p>\n<p><b><i>Roberto Ippolito<\/i><\/b> &#8211; <i>Scrittore, giornalista e organizzatore culturale. Autore di libri d\u2019inchiesta sulla legalit\u00e0 e la cultura, prima di \u201cDelitto Neruda\u201d ha pubblicato \u201cIgnoranti\u201d e \u201cAbusivi\u201d (Chiarelettere), \u201cEvasori\u201d e \u201cIl Bel Paese maltratto\u201d (Bompiani). Conoscitore del mondo letterario, \u00e8 organizzatore di eventi che portano la cultura tra la gente nei luoghi pi\u00f9 vari come centri commerciali, mondiali di nuoto, navi, aeroporti, pullman, scuole, musei, siti Unesco, parchi. Ha curato l\u2019economia per \u201cLa Stampa\u201d, \u00e8 stato direttore comunicazione Confindustria e relazioni esterne Luiss dove ha insegnato alla Scuola superiore di giornalismo ed editor del Festival dell\u2019economia di Trento. \u00c8 Ambasciatore del tartufo di San Miniato nel mondo.<\/i><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_36271\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Invernale-locandina-A3-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Invernale-locandina-A3-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Invernale - locandina A3<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 la letteratura a dare il via. Dario Voltolini, secondo classificato del Premio Strega 2024, apre un fine settimana speciale per San Miniato. Conversa sul suo libro \u201cInvernale\u201d, pubblicato dalla [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":36270,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-36223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il 29 novembre Dario Voltolini a San Miniato per presentare &quot;Invernale&quot; - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il 29 novembre Dario Voltolini a San Miniato per presentare &quot;Invernale&quot; - San Miniato\" \/>\n<meta property=\"og:description\" content=\"\u00c8 la letteratura a dare il via. Dario Voltolini, secondo classificato del Premio Strega 2024, apre un fine settimana speciale per San Miniato. Conversa sul suo libro \u201cInvernale\u201d, pubblicato dalla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T08:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T08:02:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Voltolini-invernale-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Il 29 novembre Dario Voltolini a San Miniato per presentare &#8220;Invernale&#8221;\",\"datePublished\":\"2024-11-27T08:00:41+00:00\",\"dateModified\":\"2024-11-27T08:02:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/\"},\"wordCount\":564,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/Voltolini-invernale.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/\",\"name\":\"Il 29 novembre Dario Voltolini a San Miniato per presentare \\\"Invernale\\\" - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/Voltolini-invernale.jpg\",\"datePublished\":\"2024-11-27T08:00:41+00:00\",\"dateModified\":\"2024-11-27T08:02:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/Voltolini-invernale.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/Voltolini-invernale.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/18\\\/dario-voltolini-a-san-miniato-per-presentare-invernale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il 29 novembre Dario Voltolini a San Miniato per presentare &#8220;Invernale&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il 29 novembre Dario Voltolini a San Miniato per presentare \"Invernale\" - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/","og_locale":"it_IT","og_type":"article","og_title":"Il 29 novembre Dario Voltolini a San Miniato per presentare \"Invernale\" - San Miniato","og_description":"\u00c8 la letteratura a dare il via. Dario Voltolini, secondo classificato del Premio Strega 2024, apre un fine settimana speciale per San Miniato. Conversa sul suo libro \u201cInvernale\u201d, pubblicato dalla [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-11-27T08:00:41+00:00","article_modified_time":"2024-11-27T08:02:28+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Voltolini-invernale-1.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Il 29 novembre Dario Voltolini a San Miniato per presentare &#8220;Invernale&#8221;","datePublished":"2024-11-27T08:00:41+00:00","dateModified":"2024-11-27T08:02:28+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/"},"wordCount":564,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Voltolini-invernale.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/","name":"Il 29 novembre Dario Voltolini a San Miniato per presentare \"Invernale\" - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Voltolini-invernale.jpg","datePublished":"2024-11-27T08:00:41+00:00","dateModified":"2024-11-27T08:02:28+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Voltolini-invernale.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/Voltolini-invernale.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/18\/dario-voltolini-a-san-miniato-per-presentare-invernale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Il 29 novembre Dario Voltolini a San Miniato per presentare &#8220;Invernale&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"35351"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=36223"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36223\/revisions"}],"predecessor-version":[{"id":36269,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36223\/revisions\/36269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/36270"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=36223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=36223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=36223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}