{"id":36276,"date":"2024-11-28T12:18:02","date_gmt":"2024-11-28T11:18:02","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/"},"modified":"2024-11-28T12:18:02","modified_gmt":"2024-11-28T11:18:02","slug":"acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/","title":{"rendered":"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio"},"content":{"rendered":"<div>Continuare l\u2019opera di graduale ammodernamento della rete idrica, per ottenere miglioramenti sensibili nel servizio e ridurre l\u2019incidenza delle perdite su tubazioni attualmente datate. \u00c8 questo, da anni, uno dei principali obiettivi di Acque nel Basso Valdarno e, in particolare, nel comune di San Miniato, dove grazie alla stretta sinergia con l\u2019amministrazione comunale va avanti il programma per la sostituzione di importanti tratti di condotte idriche deteriorate.<\/div>\n<div><\/div>\n<div>In questi giorni sono pronti a partire due nuovi, significativi interventi sull\u2019acquedotto: il primo riguarda la posa in opera e l\u2019attivazione di 1.400 metri di tubazioni in ghisa sferoidale &#8211; materiale pi\u00f9 resistente rispetto alle condotte di \u201cvecchia generazione\u201d &#8211; in\u00a0<b>via Asmara<\/b>, tra le localit\u00e0 di Ontraino e Case Nuove di Roffia. Un lavoro da 760mila euro, che comprende anche il rifacimento degli allacci d\u2019utenza e con diversi ostacoli da superare, come gli attraversamenti dei rii Pinocchio e Santa Maria, per i quali si attendono le autorizzazioni degli enti coinvolti. L\u2019intervento, suddiviso in due lotti, terminer\u00e0 entro la prossima primavera.<\/div>\n<div><\/div>\n<div>Con un investimento di 400mila euro, un secondo intervento comincer\u00e0 a breve lungo\u00a0<b>via XXIV Maggio<\/b>, tra La Serra e Bucciano: progettato anch\u2019esso da Ingegnerie Toscane, avr\u00e0 il medesimo obiettivo di eliminare l\u2019incidenza dei guasti su una tubazione in cattivo stato. A essere ammodernato sar\u00e0 un tratto di 600 metri da \u201cmandare in pensione\u201d e sostituire con tubazioni pi\u00f9 performanti. Qui, come nel caso di via Asmara, a conclusione dei lavori si otterr\u00e0 anche un potenziamento del servizio, poich\u00e9 le condotte avranno un diametro maggiore di quelle attualmente in funzione.<\/div>\n<div><\/div>\n<div>Intanto procedono secondo copione le attivit\u00e0 a Canneto per il risanamento dell\u2019acquedotto in\u00a0<b>via Castelfiorentino<\/b>\u00a0(420mila euro d\u2019investimento). Iniziati a ottobre, i lavori riguardano la realizzazione di 1.100 metri di nuove tubazioni. Per tutti gli interventi, una volta trascorso il tempo necessario per l\u2019assestamento delle infrastrutture nel terreno, e con le condizioni meteo favorevoli, saranno garantite le riasfaltature dei tratti di strada interessati dai cantieri.<\/div>\n<div><\/div>\n<div><i>\u201cGli interventi in corso nel comune di San Miniato\u00a0<\/i>&#8211; ricorda il presidente di Acque, Simone Millozzi &#8211;<i>\u00a0rientrano tutti in Digital4zero, il nostro progetto co-finanziato dal PNRR che punta a implementare la digitalizzazione degli acquedotti e ad efficientare il servizio, aumentando le distrettualizzazioni delle reti, diminuendo le perdite e, di conseguenza, \u201cridimensionandone\u201d l\u2019impatto in termini ambientali ed energetici. Tutto questo, nel complesso, consentir\u00e0 anche di ridurre i prelievi di acqua dall\u2019ambiente, contribuendo a sviluppare un servizio sempre pi\u00f9 resiliente e sostenibile\u201d.<\/i><\/div>\n<div><i>\u00a0<\/i><\/div>\n<div><i>\u201cQuesti lavori &#8211;\u00a0<\/i>dichiara il sindaco di San Miniato, Simone Giglioli<i>\u00a0&#8211; vanno a migliorare le condotte vetuste su alcune zone del nostro territorio, andando cos\u00ec ad eliminare le perdite. Grazie ad Acque per questi importanti investimenti. L\u2019impegno del Comune \u00e8 quello di affiancare l\u2019azienda affinch\u00e9 lavori come questo possano essere estesi anche ad altre zone in cui siamo in difficolt\u00e0, a causa di perdite frequenti dovute a condotte oramai obsolete\u201d.<\/i><\/div>\n<div><\/div>\n<div>Fonte Ufficio Stampa Acque spa<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Continuare l\u2019opera di graduale ammodernamento della rete idrica, per ottenere miglioramenti sensibili nel servizio e ridurre l\u2019incidenza delle perdite su tubazioni attualmente datate. \u00c8 questo, da anni, uno dei principali [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":36277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-36276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Continuare l\u2019opera di graduale ammodernamento della rete idrica, per ottenere miglioramenti sensibili nel servizio e ridurre l\u2019incidenza delle perdite su tubazioni attualmente datate. \u00c8 questo, da anni, uno dei principali [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T11:18:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/San-Miniato-Castelfiorentino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio\",\"datePublished\":\"2024-11-28T11:18:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/\"},\"wordCount\":505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/San-Miniato-Castelfiorentino.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/\",\"name\":\"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/San-Miniato-Castelfiorentino.jpg\",\"datePublished\":\"2024-11-28T11:18:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/San-Miniato-Castelfiorentino.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/11\\\/San-Miniato-Castelfiorentino.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/11\\\/28\\\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/","og_locale":"it_IT","og_type":"article","og_title":"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio - San Miniato","og_description":"Continuare l\u2019opera di graduale ammodernamento della rete idrica, per ottenere miglioramenti sensibili nel servizio e ridurre l\u2019incidenza delle perdite su tubazioni attualmente datate. \u00c8 questo, da anni, uno dei principali [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-11-28T11:18:02+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/San-Miniato-Castelfiorentino.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio","datePublished":"2024-11-28T11:18:02+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/"},"wordCount":505,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/San-Miniato-Castelfiorentino.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/","name":"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/San-Miniato-Castelfiorentino.jpg","datePublished":"2024-11-28T11:18:02+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/San-Miniato-Castelfiorentino.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/11\/San-Miniato-Castelfiorentino.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/11\/28\/acque-oltre-2-km-di-nuove-condotte-tra-via-asmara-e-via-xxiv-maggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Acque, oltre 2 Km di nuove condotte tra via Asmara e via XXIV Maggio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"35400"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=36276"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/36277"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=36276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=36276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=36276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}