{"id":36476,"date":"2024-12-30T14:15:52","date_gmt":"2024-12-30T13:15:52","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/"},"modified":"2024-12-30T14:22:19","modified_gmt":"2024-12-30T13:22:19","slug":"ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/","title":{"rendered":"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti"},"content":{"rendered":"<div>\n<div>In vista dei festeggiamenti del Capodanno nelle piazze dei comuni del Comprensorio, i sindaci\u00a0<b>Simone Giglioli\u00a0<\/b>(San Miniato),\u00a0<b>Roberto Giannoni<\/b>\u00a0(Santa Croce sull&#8217;Arno),\u00a0<b>Linda Vanni\u00a0<\/b>(Montopoli in Val d&#8217;Arno) e\u00a0<b>Fabio Mini<\/b> (Castelfranco di Sotto) rivolgono un appello unanime ai cittadini e alle cittadine, affinch\u00e9 in questi giorni di festa non si usino i tradizionali ma pericolosi botti. <em>\u201cVi chiediamo di non utilizzare i botti, che sono pericolosi e possono arrecare danno alle persone e ai nostri amici animali. A differenza di altri Comuni, che impongono il divieto di utilizzo, noi sindaci del Comprensorio del Cuoio abbiamo ritenuto di fare appello al vostro senso di civilt\u00e0 che permetter\u00e0 di evitare situazioni gratuite di pericolo, per uomini e animali. Siamo sicuri che il divertimento e la voglia di far festa non mancheranno, quello che vi chiediamo \u00e8 che i festeggiamenti non degenerino in forme di condotta da punire: il rispetto per tutti deve prevalere. Vi auguriamo un buon Capodanno, sperando in un 2025 migliore dell\u2019anno che volge al termine\u201d.<\/em><\/div>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In vista dei festeggiamenti del Capodanno nelle piazze dei comuni del Comprensorio, i sindaci\u00a0Simone Giglioli\u00a0(San Miniato),\u00a0Roberto Giannoni\u00a0(Santa Croce sull&#8217;Arno),\u00a0Linda Vanni\u00a0(Montopoli in Val d&#8217;Arno) e\u00a0Fabio Mini (Castelfranco di Sotto) rivolgono un [&hellip;]<\/p>\n","protected":false},"author":372,"featured_media":36485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-36476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pubblica-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti - San Miniato\" \/>\n<meta property=\"og:description\" content=\"In vista dei festeggiamenti del Capodanno nelle piazze dei comuni del Comprensorio, i sindaci\u00a0Simone Giglioli\u00a0(San Miniato),\u00a0Roberto Giannoni\u00a0(Santa Croce sull&#8217;Arno),\u00a0Linda Vanni\u00a0(Montopoli in Val d&#8217;Arno) e\u00a0Fabio Mini (Castelfranco di Sotto) rivolgono un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-30T13:15:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T13:22:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/12\/botti-fine-anno-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandrospagli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandrospagli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/\"},\"author\":{\"name\":\"sandrospagli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\"},\"headline\":\"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti\",\"datePublished\":\"2024-12-30T13:15:52+00:00\",\"dateModified\":\"2024-12-30T13:22:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/\"},\"wordCount\":179,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/12\\\/botti-fine-anno-6.jpg\",\"articleSection\":[\"Pubblica Sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/\",\"name\":\"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/12\\\/botti-fine-anno-6.jpg\",\"datePublished\":\"2024-12-30T13:15:52+00:00\",\"dateModified\":\"2024-12-30T13:22:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/12\\\/botti-fine-anno-6.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2024\\\/12\\\/botti-fine-anno-6.jpg\",\"width\":660,\"height\":368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2024\\\/12\\\/30\\\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/ab1924e0e58e427309744c54a458d4cb\",\"name\":\"sandrospagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g\",\"caption\":\"sandrospagli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/sandrspagli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/","og_locale":"it_IT","og_type":"article","og_title":"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti - San Miniato","og_description":"In vista dei festeggiamenti del Capodanno nelle piazze dei comuni del Comprensorio, i sindaci\u00a0Simone Giglioli\u00a0(San Miniato),\u00a0Roberto Giannoni\u00a0(Santa Croce sull&#8217;Arno),\u00a0Linda Vanni\u00a0(Montopoli in Val d&#8217;Arno) e\u00a0Fabio Mini (Castelfranco di Sotto) rivolgono un [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-12-30T13:15:52+00:00","article_modified_time":"2024-12-30T13:22:19+00:00","og_image":[{"width":660,"height":368,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/12\/botti-fine-anno-6.jpg","type":"image\/jpeg"}],"author":"sandrospagli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sandrospagli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/"},"author":{"name":"sandrospagli","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb"},"headline":"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti","datePublished":"2024-12-30T13:15:52+00:00","dateModified":"2024-12-30T13:22:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/"},"wordCount":179,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/12\/botti-fine-anno-6.jpg","articleSection":["Pubblica Sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/","url":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/","name":"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/12\/botti-fine-anno-6.jpg","datePublished":"2024-12-30T13:15:52+00:00","dateModified":"2024-12-30T13:22:19+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/12\/botti-fine-anno-6.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2024\/12\/botti-fine-anno-6.jpg","width":660,"height":368},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2024\/12\/30\/ultimo-dellanno-appello-dei-sindaci-del-comprensorio-a-non-usare-botti-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Ultimo dell\u2019anno, appello dei sindaci del Comprensorio a non usare botti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/ab1924e0e58e427309744c54a458d4cb","name":"sandrospagli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad037c79e056c01b119cef66bb3ef3c00f4918966e06bb639431488810b2644d?s=96&d=mm&r=g","caption":"sandrospagli"},"url":"https:\/\/comunicacity.net\/sanminiato\/author\/sandrspagli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"35534"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/372"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=36476"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36476\/revisions"}],"predecessor-version":[{"id":36484,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/36476\/revisions\/36484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/36485"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=36476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=36476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=36476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}