{"id":37099,"date":"2025-05-20T10:50:10","date_gmt":"2025-05-20T08:50:10","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/"},"modified":"2025-05-20T10:50:10","modified_gmt":"2025-05-20T08:50:10","slug":"il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/","title":{"rendered":"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori"},"content":{"rendered":"<p style='margin-bottom: 11px;padding-bottom: 0px'><b style='font-size: 16px;color: #333'>Dal 24 Maggio 2025<\/b> <b style='font-size: 16px;color: #333'>al 24 Maggio 2025<\/b><\/p>\n<p><em>Sabato 24 maggio, alle 17.00, a Cigoli si svolger\u00e0 la cerimonia inaugurale delle iniziative in ricordo di Giuseppe Gori.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Sabato 24 maggio, alle 17.00, a Cigoli si svolger\u00e0 la cerimonia inaugurale delle iniziative in ricordo di Giuseppe Gori.<br \/>\nDopo i saluti istituzionali e delle autorit\u00e0, inaugurazione della mostra <strong><em>&#8220;Resistenza&#8221;<\/em><\/strong> dove un gruppo di artisti ha rappresentato e interpretato, oltre la figura di Gori, una serie di personaggi noti e rappresentativi della Resistenza.<\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>A chi \u00e8 rivolto:<\/b><\/p>\n<p><span style='font-size: 16px;color: #555'>Tutti e tutte.<\/span><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Costi:<\/b> <span style='font-size: 16px;color: #555'>Nessun costo.<\/span><\/p>\n<p><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Contatti:<\/b><\/p>\n<ul style='list-style-type: disc;padding-left: 20px;margin-top: 0px!important'>\n<li style='margin-bottom: 5px'><span>Matteo Squicciarini<\/span><\/li>\n<p><span style='font-size: 15px'><b>Telefono<\/b>: 0571 406227<\/span><br \/><span style='font-size: 15px'><b>Telefono<\/b>: 333 6142167<\/span><br \/><span style='font-size: 15px'><b>PEC<\/b>: comune.sanminiato.pi@postacert.toscana.it<\/span><br \/><span style='font-size: 15px'><b>Email<\/b>: msquicciarini@comune.san-miniato.pi.it<\/span><br \/><span style='font-size: 15px'><b>Indirizzo<\/b>: Via Ser Ridolfo, 3 &#8211; San Miniato<\/span><\/p>\n<li style='margin-bottom: 5px'><span>Simone Giglioli<\/span><\/li>\n<p><span style='font-size: 15px'><b>Telefono<\/b>: 0571 406220<\/span><br \/><span style='font-size: 15px'><b>PEC<\/b>: comune.sanminiato.pi@postacert.toscana.it<\/span><br \/><span style='font-size: 15px'><b>Email<\/b>: sindaco@comune.san-miniato.pi.it<\/span><br \/><span style='font-size: 15px'><b>Indirizzo<\/b>: Palazzo Comunale, 1\u00b0 piano Via Vittime del Duomo, 8 &#8211; San Miniato<\/span><\/ul>\n\t\t\t<h4>Inizio<\/h4>\n<p>24\/05\/2025 17:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>24\/05\/2025 18:30<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_37101\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/giuseppe-gori-scheda.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/giuseppe-gori-scheda.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>giuseppe gori scheda<\/a><\/li>\n<li><a id=\"wpba_attachment_list_37102\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/giuseppe-gori-programma-inaugurazione.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/giuseppe-gori-programma-inaugurazione.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>giuseppe gori programma inaugurazione<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dal 24 Maggio 2025 al 24 Maggio 2025 Sabato 24 maggio, alle 17.00, a Cigoli si svolger\u00e0 la cerimonia inaugurale delle iniziative in ricordo di Giuseppe Gori.&nbsp; Descrizione&nbsp; Sabato 24 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-37099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Dal 24 Maggio 2025 al 24 Maggio 2025 Sabato 24 maggio, alle 17.00, a Cigoli si svolger\u00e0 la cerimonia inaugurale delle iniziative in ricordo di Giuseppe Gori.&nbsp; Descrizione&nbsp; Sabato 24 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-20T08:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/Giuseppe-Gori.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1209\" \/>\n\t<meta property=\"og:image:height\" content=\"785\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori\",\"datePublished\":\"2025-05-20T08:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/\"},\"wordCount\":151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/05\\\/Giuseppe-Gori.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/\",\"name\":\"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/05\\\/Giuseppe-Gori.jpg\",\"datePublished\":\"2025-05-20T08:50:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/05\\\/Giuseppe-Gori.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/05\\\/Giuseppe-Gori.jpg\",\"width\":1209,\"height\":785},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/05\\\/20\\\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/","og_locale":"it_IT","og_type":"article","og_title":"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori - San Miniato","og_description":"Dal 24 Maggio 2025 al 24 Maggio 2025 Sabato 24 maggio, alle 17.00, a Cigoli si svolger\u00e0 la cerimonia inaugurale delle iniziative in ricordo di Giuseppe Gori.&nbsp; Descrizione&nbsp; Sabato 24 [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-05-20T08:50:10+00:00","og_image":[{"width":1209,"height":785,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/Giuseppe-Gori.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori","datePublished":"2025-05-20T08:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/"},"wordCount":151,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/Giuseppe-Gori.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/","name":"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/Giuseppe-Gori.jpg","datePublished":"2025-05-20T08:50:10+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/Giuseppe-Gori.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/05\/Giuseppe-Gori.jpg","width":1209,"height":785},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/05\/20\/il-24-maggio-al-via-una-serie-di-iniziative-per-celebrare-la-figura-di-giuseppe-gori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Il 24 maggio al via una serie di iniziative per celebrare la figura di Giuseppe Gori"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"24\/05\/2025 17:00","cc4_eve_data_fine":"24\/05\/2025 18:30","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000021701"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=37099"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/37100"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=37099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=37099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=37099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}