{"id":37483,"date":"2025-07-14T13:30:24","date_gmt":"2025-07-14T11:30:24","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/"},"modified":"2025-07-14T13:30:24","modified_gmt":"2025-07-14T11:30:24","slug":"22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/","title":{"rendered":"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi"},"content":{"rendered":"<p style='margin-bottom: 11px;padding-bottom: 0px'><b style='font-size: 16px;color: #333'>Dal 22 Luglio 2025<\/b> <b style='font-size: 16px;color: #333'>al 22 Luglio 2025<\/b><\/p>\n<p><em>Marted\u00ec 22 luglio ricorre l&#8217;81esimo anniversario della strage del Duomo di San Miniato, avvenuta il 22 luglio 1944, in cui persero la vita 55 persone. <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<article class=\"it-page-section anchor-offset\" data-audio=\"\">\n<div class=\"richtext-wrapper titillium\">\n<div>Marted\u00ec <b>22 luglio<\/b> ricorre l&#8217;81esimo anniversario della <b>strage del Duomo\u00a0<\/b>di San Miniato, avvenuta il 22 luglio 1944, in cui persero la vita\u00a0<b>55<\/b>\u00a0persone. La mattinata, organizzata dal\u00a0<b>Comune<\/b>\u00a0e dalla\u00a0<b>Diocesi di San Miniato<\/b>, si apre con la cerimonia civile, dalle 9.30, ai Loggiati di San Domenico alla presenza del sindaco <b>Simone Giglioli<\/b>, dell&#8217;assessora regionale alla memoria <strong>Alessandra Nardini<\/strong>, dell&#8217;assessore alla memoria <strong>Matteo Squicciarini<\/strong>, del presidente del consiglio comunale <b>Matteo Betti<\/b>, del vescovo\u00a0<b>Giovanni Paccosi<\/b>, delle altre autorit\u00e0 cittadine e degli amministratori del Valdarno. Alle 10.00, nell&#8217;ora dello scoppio dell&#8217;ordigno bellico, le campane suoneranno 55 rintocchi, in memoria delle vittime. A seguire sar\u00e0 deposta una corona di alloro alle lapidi dedicate alle strage ai Loggiati di San Domenico e una al monumento dedicato alle vittime. A conclusione della cerimonia, alle 11.30, ci sar\u00e0 una messa in Cattedrale officiata dal vescovo, monsignor <b>Giovanni Paccosi<\/b>.<\/div>\n<div>Per tutta la giornata il Museo della Memoria ai Loggiati di San Domenico rester\u00e0 aperto al pubblico e sar\u00e0 visitabile (<a href=\"mailto:sistemamuseale@comune.san-miniato.pi.it\">sistemamuseale@comune.san-miniato.pi.it<\/a>\u00a0&#8211; 345.3038991).<\/div>\n<\/div>\n<\/article>\n<p><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>A chi \u00e8 rivolto:<\/b><\/p>\n<p><span style='font-size: 16px;color: #555'>Tutti e tutte.<\/span><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Costi:<\/b> <span style='font-size: 16px;color: #555'>Nessun costo.<\/span><\/p>\n<p><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Contatti:<\/b><\/p>\n<ul style='list-style-type: disc;padding-left: 20px;margin-top: 0px!important'>\n<li style='margin-bottom: 5px'><span>Servizio Cultura, Turismo, Gemellaggi e Cooperazione internazionale<\/span><\/li>\n<p><span style='font-size: 15px'><b>Telefono<\/b>: 0571 406753 | 406650<\/span><br \/><span style='font-size: 15px'><b>Email<\/b>: cultura@comune.san-miniato.pi.it<\/span><br \/><span style='font-size: 15px'><b>Email<\/b>: turismo@comune.san-miniato.pi.it<\/span><br \/><span style='font-size: 15px'><b>PEC<\/b>: comune.sanminiato.pi@postacert.toscana.it<\/span><\/ul>\n\t\t\t<h4>Inizio<\/h4>\n<p>22\/07\/2025 09:30<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>22\/07\/2025 13:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_37488\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/22-luglio-2025_def-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/22-luglio-2025_def-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>22 luglio 2025_def.<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dal 22 Luglio 2025 al 22 Luglio 2025 Marted\u00ec 22 luglio ricorre l&#8217;81esimo anniversario della strage del Duomo di San Miniato, avvenuta il 22 luglio 1944, in cui persero la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-37483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Dal 22 Luglio 2025 al 22 Luglio 2025 Marted\u00ec 22 luglio ricorre l&#8217;81esimo anniversario della strage del Duomo di San Miniato, avvenuta il 22 luglio 1944, in cui persero la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-14T11:30:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/22-luglio-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi\",\"datePublished\":\"2025-07-14T11:30:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/\"},\"wordCount\":242,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/07\\\/22-luglio-1.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/\",\"name\":\"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/07\\\/22-luglio-1.jpeg\",\"datePublished\":\"2025-07-14T11:30:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/07\\\/22-luglio-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/07\\\/22-luglio-1.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/14\\\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/","og_locale":"it_IT","og_type":"article","og_title":"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi - San Miniato","og_description":"Dal 22 Luglio 2025 al 22 Luglio 2025 Marted\u00ec 22 luglio ricorre l&#8217;81esimo anniversario della strage del Duomo di San Miniato, avvenuta il 22 luglio 1944, in cui persero la [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-14T11:30:24+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/22-luglio-1.jpeg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi","datePublished":"2025-07-14T11:30:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/"},"wordCount":242,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/22-luglio-1.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/","name":"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/22-luglio-1.jpeg","datePublished":"2025-07-14T11:30:24+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/22-luglio-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/22-luglio-1.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/14\/22-luglio-81-anni-dalla-strage-del-duomo-le-celebrazioni-di-comune-e-diocesi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"22 luglio, 81 anni dalla strage del Duomo. Le celebrazioni di Comune e Diocesi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"22\/07\/2025 09:30","cc4_eve_data_fine":"22\/07\/2025 13:00","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000021967"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=37483"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37483\/revisions"}],"predecessor-version":[{"id":37486,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37483\/revisions\/37486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/37487"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=37483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=37483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=37483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}